{"id":63108,"date":"2016-10-06T12:59:55","date_gmt":"2016-10-06T10:59:55","guid":{"rendered":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?p=63108"},"modified":"2020-11-09T09:33:08","modified_gmt":"2020-11-09T08:33:08","slug":"una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/","title":{"rendered":"Una sesi\u00f3n sobre pacientes anticoagulados inaugura Los Mi\u00e9rcoles Hablamos de Salud del curso 2016-2017"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-63110 size-full\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg\" alt=\"dra-lopez-miercoles-salud\" width=\"5184\" height=\"3456\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg 5184w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-300x200.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-768x512.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-696x464.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-1068x712.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-630x420.jpg 630w\" sizes=\"auto, (max-width: 5184px) 100vw, 5184px\" \/>\u00a0<\/strong><\/p>\n<ul>\n<li><strong>La jefa del Servicio de Hematolog\u00eda del Hospital Arnau de Vilanova ha se\u00f1alado que <\/strong><strong>anualmente el incremento en el n\u00famero de pacientes anticoagulados es del 20%<\/strong><\/li>\n<\/ul>\n<p>La Facultad de Ciencias de la Salud de la Universidad CEU Cardenal Herrera inaugur\u00f3 el Ciclo <strong><em>\u201cLos Mi\u00e9rcoles hablamos de Salud en la CEU-UCH\u201d<\/em><\/strong> del curso 2016-2017, con la sesi\u00f3n <strong>Anticoagulados y portadores de v\u00e1lvulas card\u00edacas.<\/strong><!--more--><\/p>\n<p>La vicedecana del <a href=\"https:\/\/www.uchceu.es\/estudios\/area-ciencias-salud\">Grado en Farmacia<\/a> del CEU<strong>, <a href=\"https:\/\/www.uchceu.es\/directorio\/lmoreno\">Lucrecia Moreno<\/a>, <\/strong>present\u00f3 esta sesi\u00f3n que ha contado con la participaci\u00f3n de la <strong>Dra. Francisca L\u00f3pez Chuli\u00e1, <\/strong>jefa del Servicio de Hematolog\u00eda del Hospital Arnau de Vilanova<strong>; Camila Romero y Luciano Arochena, <\/strong>de la Asociaci\u00f3n de Pacientes\u00a0Anticoagulados y Portadores de V\u00e1lvulas Card\u00edacas, y <a href=\"https:\/\/www.uchceu.es\/directorio\/ma_dolores-guerrero\"><strong>M\u00aa Dolores Guerrero<\/strong><\/a>, profesora de Ciencias de la Salud.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-63111 size-full\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/presentacion-miercoles-salud.jpg\" alt=\"presentacion-miercoles-salud\" width=\"5184\" height=\"3456\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/presentacion-miercoles-salud.jpg 5184w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/presentacion-miercoles-salud-300x200.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/presentacion-miercoles-salud-768x512.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/presentacion-miercoles-salud-696x464.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/presentacion-miercoles-salud-1068x712.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/presentacion-miercoles-salud-630x420.jpg 630w\" sizes=\"auto, (max-width: 5184px) 100vw, 5184px\" \/><\/p>\n<p>La Dra. L\u00f3pez Chulia present\u00f3 las caracter\u00edsticas y la gesti\u00f3n del tratamiento anticoagulante, as\u00ed como la evoluci\u00f3n de las terapias y de la calidad asistencial. La experta se\u00f1al\u00f3 que anualmente el incremento en el n\u00famero de pacientes anticoagulados es del 20%, y se estima que, para el a\u00f1o 2050, habr\u00e1 16 millones de pacientes anticoagulados en el mundo.<\/p>\n<p>Para la responsable del Servicio de Hematolog\u00eda del Hospital Arnau de Vilanova es fundamental <strong>la informaci\u00f3n, formaci\u00f3n y comunicaci\u00f3n con el paciente<\/strong>, para garantizar la adherencia a los tratamientos y la m\u00e1xima calidad asistencial. La Dra. Francisca L\u00f3pez tambi\u00e9n destac\u00f3 la necesidad del trabajo en equipos multidisciplinares (m\u00e9dicos, enfermeros y especialistas) para ofrecer la mejor asistencia a los pacientes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-63112 size-full\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/pacientes-miercoles-salud.jpg\" alt=\"pacientes-miercoles-salud\" width=\"3678\" height=\"2491\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/pacientes-miercoles-salud.jpg 3678w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/pacientes-miercoles-salud-300x203.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/pacientes-miercoles-salud-768x520.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/pacientes-miercoles-salud-696x471.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/pacientes-miercoles-salud-1068x723.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/pacientes-miercoles-salud-620x420.jpg 620w\" sizes=\"auto, (max-width: 3678px) 100vw, 3678px\" \/><\/p>\n<p>Los pacientes <strong>Camila Romero <\/strong>y<strong> Luciano Arochena, <\/strong>de la Asociaci\u00f3n de Pacientes\u00a0Anticoagulados y Portadores de V\u00e1lvulas Card\u00edacas, compartieron su experiencia con los numerosos estudiantes de la Facultad de Ciencias de la Salud que asistieron a la sesi\u00f3n.<\/p>\n<p>Camila Romero y Luciano Arochena hablaron de c\u00f3mo ha cambiado su vida, y pusieron en valor la labor de las asociaciones de pacientes, en la atenci\u00f3n, la informaci\u00f3n y la formaci\u00f3n de las personas afectadas y sus familias.<\/p>\n<blockquote><p><em>\u201cNo puedo hacerlo todo pero<\/em><em>, en lo que hago, pongo todo de mi parte\u201d<\/em><\/p><\/blockquote>\n<p>Camila Romero solicit\u00f3 una mayor colaboraci\u00f3n del sistema sanitario con las asociaciones, que <em>\u201ccontribuyen a educar a los pacientes y a las familias en su necesaria participaci\u00f3n activa en los tratamientos\u201d.<\/em><\/p>\n<p>La sesi\u00f3n se cerr\u00f3 con un debate entre expertos, pacientes y estudiantes de Ciencias de la Salud.<\/p>\n<p>El Ciclo Los Mi\u00e9rcoles Hablamos de Salud en el CEU comenz\u00f3 su andadura en el Curso 2012-2013. Se trata de una actividad extra acad\u00e9mica con car\u00e1cter transversal, cuyo principal objetivo ha sido el de aportar al alumnado de la Facultad de Ciencias de la Salud un valor a\u00f1adido a la formaci\u00f3n reglada que recibe, acercando diferentes realidades cl\u00ednicas desde un abordaje multidisciplinar. En el pasado Curso, 800 alumnos de Ciencias de la Salud participaron en las iniciativas y conferencias incluidas en el Ciclo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 La jefa del Servicio de Hematolog\u00eda del Hospital Arnau de Vilanova ha se\u00f1alado que anualmente el incremento en el n\u00famero de pacientes anticoagulados es del 20% La Facultad de Ciencias de la Salud de la Universidad CEU Cardenal Herrera inaugur\u00f3 el Ciclo \u201cLos Mi\u00e9rcoles hablamos de Salud en la CEU-UCH\u201d del curso 2016-2017, con [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":63110,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[1410,31,35,36,38,17,28],"tags":[154,210,218,274],"class_list":["post-63108","post","type-post","status-publish","format-standard","has-post-thumbnail","category-es-noticia","category-nota-de-prensa-valencia","category-x-slider-campus-valencia","category-x-slider-formacion","category-x-slider-home","category-xmaquetacion","category-xnota-de-prensa","tag-dpto-farmacia","tag-grado-farmacia","tag-grado-medicina","tag-los-miercoles-hablamos-de-salud"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una sesi\u00f3n sobre pacientes anticoagulados inaugura Los Mi\u00e9rcoles Hablamos de Salud del curso 2016-2017<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una sesi\u00f3n sobre pacientes anticoagulados inaugura Los Mi\u00e9rcoles Hablamos de Salud del curso 2016-2017\" \/>\n<meta property=\"og:description\" content=\"\u00a0 La jefa del Servicio de Hematolog\u00eda del Hospital Arnau de Vilanova ha se\u00f1alado que anualmente el incremento en el n\u00famero de pacientes anticoagulados es del 20% La Facultad de Ciencias de la Salud de la Universidad CEU Cardenal Herrera inaugur\u00f3 el Ciclo \u201cLos Mi\u00e9rcoles hablamos de Salud en la CEU-UCH\u201d del curso 2016-2017, con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-06T10:59:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-09T08:33:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5184\" \/>\n\t<meta property=\"og:image:height\" content=\"3456\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana Salvador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Salvador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\\\/\"},\"author\":{\"name\":\"Ana Salvador\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/e9663a691e5285e1e04660b1315d65f0\"},\"headline\":\"Una sesi\u00f3n sobre pacientes anticoagulados inaugura Los Mi\u00e9rcoles Hablamos de Salud del curso 2016-2017\",\"datePublished\":\"2016-10-06T10:59:55+00:00\",\"dateModified\":\"2020-11-09T08:33:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\\\/\"},\"wordCount\":518,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/10\\\/dra-lopez-miercoles-salud.jpg\",\"keywords\":[\"Dpto. Farmacia\",\"Grado Farmacia\",\"Grado Medicina\",\"Los mi\u00e9rcoles hablamos de Salud\"],\"articleSection\":[\"Es noticia\",\"nota de prensa valencia\",\"x slider campus valencia\",\"x slider formacion\",\"x slider home\",\"xMaquetaci\u00f3n\",\"xNota de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\\\/\",\"name\":\"Una sesi\u00f3n sobre pacientes anticoagulados inaugura Los Mi\u00e9rcoles Hablamos de Salud del curso 2016-2017\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/10\\\/dra-lopez-miercoles-salud.jpg\",\"datePublished\":\"2016-10-06T10:59:55+00:00\",\"dateModified\":\"2020-11-09T08:33:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/10\\\/dra-lopez-miercoles-salud.jpg\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/10\\\/dra-lopez-miercoles-salud.jpg\",\"width\":5184,\"height\":3456},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una sesi\u00f3n sobre pacientes anticoagulados inaugura Los Mi\u00e9rcoles Hablamos de Salud del curso 2016-2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/e9663a691e5285e1e04660b1315d65f0\",\"name\":\"Ana Salvador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45c82f695cdd48afd056a2252ef18618d04ea35e940568d0484a72d8404ea9a2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45c82f695cdd48afd056a2252ef18618d04ea35e940568d0484a72d8404ea9a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45c82f695cdd48afd056a2252ef18618d04ea35e940568d0484a72d8404ea9a2?s=96&d=mm&r=g\",\"caption\":\"Ana Salvador\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/asalvador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una sesi\u00f3n sobre pacientes anticoagulados inaugura Los Mi\u00e9rcoles Hablamos de Salud del curso 2016-2017","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/","og_locale":"es_ES","og_type":"article","og_title":"Una sesi\u00f3n sobre pacientes anticoagulados inaugura Los Mi\u00e9rcoles Hablamos de Salud del curso 2016-2017","og_description":"\u00a0 La jefa del Servicio de Hematolog\u00eda del Hospital Arnau de Vilanova ha se\u00f1alado que anualmente el incremento en el n\u00famero de pacientes anticoagulados es del 20% La Facultad de Ciencias de la Salud de la Universidad CEU Cardenal Herrera inaugur\u00f3 el Ciclo \u201cLos Mi\u00e9rcoles hablamos de Salud en la CEU-UCH\u201d del curso 2016-2017, con [&hellip;]","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2016-10-06T10:59:55+00:00","article_modified_time":"2020-11-09T08:33:08+00:00","og_image":[{"width":5184,"height":3456,"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg","type":"image\/jpeg"}],"author":"Ana Salvador","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Ana Salvador","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/"},"author":{"name":"Ana Salvador","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/e9663a691e5285e1e04660b1315d65f0"},"headline":"Una sesi\u00f3n sobre pacientes anticoagulados inaugura Los Mi\u00e9rcoles Hablamos de Salud del curso 2016-2017","datePublished":"2016-10-06T10:59:55+00:00","dateModified":"2020-11-09T08:33:08+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/"},"wordCount":518,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg","keywords":["Dpto. Farmacia","Grado Farmacia","Grado Medicina","Los mi\u00e9rcoles hablamos de Salud"],"articleSection":["Es noticia","nota de prensa valencia","x slider campus valencia","x slider formacion","x slider home","xMaquetaci\u00f3n","xNota de Prensa"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/","name":"Una sesi\u00f3n sobre pacientes anticoagulados inaugura Los Mi\u00e9rcoles Hablamos de Salud del curso 2016-2017","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/#primaryimage"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg","datePublished":"2016-10-06T10:59:55+00:00","dateModified":"2020-11-09T08:33:08+00:00","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/#primaryimage","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg","width":5184,"height":3456},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/una-sesion-sobre-pacientes-anticoagulados-inaugura-los-miercoles-hablamos-de-salud-del-curso-2016-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"Una sesi\u00f3n sobre pacientes anticoagulados inaugura Los Mi\u00e9rcoles Hablamos de Salud del curso 2016-2017"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/e9663a691e5285e1e04660b1315d65f0","name":"Ana Salvador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/45c82f695cdd48afd056a2252ef18618d04ea35e940568d0484a72d8404ea9a2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45c82f695cdd48afd056a2252ef18618d04ea35e940568d0484a72d8404ea9a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45c82f695cdd48afd056a2252ef18618d04ea35e940568d0484a72d8404ea9a2?s=96&d=mm&r=g","caption":"Ana Salvador"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/asalvador\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg",5184,3456,false],"thumbnail":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-150x150.jpg",150,150,true],"medium":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-300x200.jpg",300,200,true],"medium_large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-768x512.jpg",696,464,true],"large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-696x464.jpg",696,464,true],"listado":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-310x174.jpg",310,174,true],"nuevaweb":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-280x280.jpg",280,280,true],"destacadablogs":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-580x280.jpg",580,280,true],"1536x1536":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg",1536,1024,false],"2048x2048":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg",2048,1365,false],"td_150x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg",150,100,false],"td_218x150":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-218x150.jpg",218,150,true],"td_300x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg",300,200,false],"td_324x400":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-324x400.jpg",324,400,true],"td_485x360":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg",485,323,false],"td_696x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-696x464.jpg",696,464,true],"td_1068x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-1068x712.jpg",1068,712,true],"td_1920x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud.jpg",1920,1280,false],"td_0x420":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-630x420.jpg",630,420,true],"td_80x60":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-80x60.jpg",80,60,true],"td_100x70":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-100x70.jpg",100,70,true],"td_265x198":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-265x198.jpg",265,198,true],"td_324x160":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-324x160.jpg",324,160,true],"td_324x235":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-324x235.jpg",324,235,true],"td_356x220":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-356x220.jpg",356,220,true],"td_356x364":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-356x364.jpg",356,364,true],"td_533x261":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-533x261.jpg",533,261,true],"td_534x462":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-534x462.jpg",534,462,true],"td_696x385":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-696x385.jpg",696,385,true],"td_741x486":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-741x486.jpg",741,486,true],"td_1068x580":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2016\/10\/dra-lopez-miercoles-salud-1068x580.jpg",1068,580,true]},"uagb_author_info":{"display_name":"Ana Salvador","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/asalvador\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00a0 La jefa del Servicio de Hematolog\u00eda del Hospital Arnau de Vilanova ha se\u00f1alado que anualmente el incremento en el n\u00famero de pacientes anticoagulados es del 20% La Facultad de Ciencias de la Salud de la Universidad CEU Cardenal Herrera inaugur\u00f3 el Ciclo \u201cLos Mi\u00e9rcoles hablamos de Salud en la CEU-UCH\u201d del curso 2016-2017, con&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/63108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=63108"}],"version-history":[{"count":1,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/63108\/revisions"}],"predecessor-version":[{"id":93881,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/63108\/revisions\/93881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media\/63110"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=63108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=63108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=63108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}