{"id":57162,"date":"2015-06-16T18:19:01","date_gmt":"2015-06-16T16:19:01","guid":{"rendered":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?p=57162"},"modified":"2023-02-13T13:18:30","modified_gmt":"2023-02-13T12:18:30","slug":"la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/","title":{"rendered":"La profesora Susana Sanz participa en la jornada cient\u00edfica sobre la defensa del inter\u00e9s superior del ni\u00f1o, en la Universidad Caddi Ayyad de Marrakech"},"content":{"rendered":"<p><strong>La CEU-UCH lidera un proyecto de I+D en esta materia, en el que participa tanto esta universidad marroqu\u00ed, como otras de Italia, M\u00e9xico, Per\u00fa y Chile<\/strong><\/p>\n<figure id=\"attachment_57163\" aria-describedby=\"caption-attachment-57163\" style=\"width: 2202px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-57163\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg\" alt=\"A la derecha, la profesora de la CEU-UCH, Susana Sanz, junto a profesoras de las universidades marroqu\u00edes de Caddi Ayyad  (Marrakech) y Ibn Zohr (Agadir).\" width=\"2202\" height=\"1528\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg 2202w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-300x208.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-1024x711.jpg 1024w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-100x70.jpg 100w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-218x150.jpg 218w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-696x483.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-1068x741.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-605x420.jpg 605w\" sizes=\"auto, (max-width: 2202px) 100vw, 2202px\" \/><\/a><figcaption id=\"caption-attachment-57163\" class=\"wp-caption-text\">A la derecha, la profesora de la CEU-UCH, Susana Sanz, junto a profesoras de las universidades marroqu\u00edes de Caddi Ayyad (Marrakech) y Ibn Zohr (Agadir).<\/figcaption><\/figure>\n<p>La <strong>catedr\u00e1tica de Derecho Internacional P\u00fablico en la Universidad CEU Cardenal Herrera Susana Sanz Caballero<\/strong> ha sido invitada por la <strong>Universidad Caddi Ayyad, de Marrakech<\/strong>, para participar en una jornada cient\u00edfica sobre la <strong>defensa del inter\u00e9s superior del ni\u00f1o en la jurisprudencia internacional<\/strong>. Este es el tema del proyecto de I+D que lidera la <strong>profesora Sanz<\/strong> y en el que participan, tanto profesores de la CEU-UCH, como de esta Universidad marroqu\u00ed y tambi\u00e9n de diversas universidades de Italia, M\u00e9xico, Per\u00fa y Chile.<\/p>\n<p><!--more--><\/p>\n<p>La jornada cient\u00edfica celebrada en Marrakech bajo la organizaci\u00f3n de la profesora Fatiha Sahli, se enmarca en el citado proyecto de investigaci\u00f3n liderado por la CEU-UCH, que lleva por t\u00edtulo \u00ab<strong>El inter\u00e9s superior del ni\u00f1o como derecho, principio y regla de procedimiento. La adaptaci\u00f3n del Derecho espa\u00f1ol y europeo: an\u00e1lisis de la jurisprudencia\u00bb <\/strong>(Proyecto I+D del MINECO, DER2013-47866-C3-2-P).<\/p>\n<p>Seg\u00fan explica la <strong>profesora de la CEU-UCH Susana Sanz<\/strong>, \u201cel objetivo de este proyecto es analizar c\u00f3mo los tribunales de diversos pa\u00edses, as\u00ed como los \u00f3rganos de Naciones Unidas y de otras organizaciones europeas y americanas \u2013como el Consejo de Europa, la Uni\u00f3n Europea, la Organizaci\u00f3n de Estados Americanos y la Uni\u00f3n Africana- entienden y aplican el <strong>principio del inter\u00e9s superior del ni\u00f1o en los casos judiciales<\/strong> y las reclamaciones que les llegan\u201d. Este proyecto de I+D se integra en el <strong><a href=\"https:\/\/www.uchceu.es\/grupos-lineas-investigacion\/cedri-proteccion-internacional-de-los-derechos-humanos\" target=\"_blank\" rel=\"noopener noreferrer\">Grupo de Investigaci\u00f3n de la CEU-UCH sobre Protecci\u00f3n internacional de los derechos humanos-CEDRI<\/a><\/strong>, cuya investigadora principal es la <strong>profesora Sanz<\/strong>.<\/p>\n<p><strong>Tribunal de posgrado<\/strong><\/p>\n<p>Entre las actividades de la jornada en la <strong>Universidad Caddi Ayyad de Marrakech<\/strong>, celebrada el 12 de junio, la profesora Sanz Caballero form\u00f3 tambi\u00e9n parte del tribunal del trabajo fin de m\u00e1ster de la estudiante de posgrado Asma Ezzahzi sobre \u201c<strong>L\u2019int\u00e9r\u00eat supr\u00eame de l\u2019enfant au Maroc, entre le Droit et la pratique<\/strong>\u00bb. Formaron tambi\u00e9n parte del tribunal las profesoras Fatiha Sahli y Habiba Belghiti, de esta Universidad de Marrakech; y Meryem Mehrez, de la <strong><a href=\"https:\/\/www.uiz.ac.ma\/\" target=\"_blank\" rel=\"noopener noreferrer\">Universidad Ibn Zohr, de Agadir<\/a><\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La CEU-UCH lidera un proyecto de I+D en esta materia, en el que participa tanto esta universidad marroqu\u00ed, como otras de Italia, M\u00e9xico, Per\u00fa y Chile La catedr\u00e1tica de Derecho Internacional P\u00fablico en la Universidad CEU Cardenal Herrera Susana Sanz Caballero ha sido invitada por la Universidad Caddi Ayyad, de Marrakech, para participar en una [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":57163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[3,7],"tags":[150,179,202,228],"class_list":["post-57162","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-cientifica","category-derecho-y-politicas-actualidad-cientifica","tag-dpto-derecho-publico","tag-facultad-derecho-empresa-y-ciencias-politicas","tag-grado-derecho","tag-grupo-cedri"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La profesora Susana Sanz participa en la jornada cient\u00edfica sobre la defensa del inter\u00e9s superior del ni\u00f1o, en la Universidad Caddi Ayyad de Marrakech<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La profesora Susana Sanz participa en la jornada cient\u00edfica sobre la defensa del inter\u00e9s superior del ni\u00f1o, en la Universidad Caddi Ayyad de Marrakech\" \/>\n<meta property=\"og:description\" content=\"La CEU-UCH lidera un proyecto de I+D en esta materia, en el que participa tanto esta universidad marroqu\u00ed, como otras de Italia, M\u00e9xico, Per\u00fa y Chile La catedr\u00e1tica de Derecho Internacional P\u00fablico en la Universidad CEU Cardenal Herrera Susana Sanz Caballero ha sido invitada por la Universidad Caddi Ayyad, de Marrakech, para participar en una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-16T16:19:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-13T12:18:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2202\" \/>\n\t<meta property=\"og:image:height\" content=\"1528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elisa Marco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa Marco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\\\/\"},\"author\":{\"name\":\"Elisa Marco\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\"},\"headline\":\"La profesora Susana Sanz participa en la jornada cient\u00edfica sobre la defensa del inter\u00e9s superior del ni\u00f1o, en la Universidad Caddi Ayyad de Marrakech\",\"datePublished\":\"2015-06-16T16:19:01+00:00\",\"dateModified\":\"2023-02-13T12:18:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\\\/\"},\"wordCount\":452,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/06\\\/susana-sanz-ceu-uch-marruecos.jpg\",\"keywords\":[\"Dpto. Derecho P\u00fablico\",\"Facultad Derecho, Empresa y Ciencias Pol\u00edticas\",\"Grado Derecho\",\"Grupo CEDRI\"],\"articleSection\":[\"Actualidad Cient\u00edfica\",\"Derecho y Pol\u00edticas\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\\\/\",\"name\":\"La profesora Susana Sanz participa en la jornada cient\u00edfica sobre la defensa del inter\u00e9s superior del ni\u00f1o, en la Universidad Caddi Ayyad de Marrakech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/06\\\/susana-sanz-ceu-uch-marruecos.jpg\",\"datePublished\":\"2015-06-16T16:19:01+00:00\",\"dateModified\":\"2023-02-13T12:18:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\\\/#primaryimage\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/06\\\/susana-sanz-ceu-uch-marruecos.jpg\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/06\\\/susana-sanz-ceu-uch-marruecos.jpg\",\"width\":2202,\"height\":1528,\"caption\":\"A la derecha, la profesora de la CEU-UCH, Susana Sanz, junto a profesoras de las universidades marroqu\u00edes de Caddi Ayyad (Marrakech) y Ibn Zohr (Agadir).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La profesora Susana Sanz participa en la jornada cient\u00edfica sobre la defensa del inter\u00e9s superior del ni\u00f1o, en la Universidad Caddi Ayyad de Marrakech\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\",\"name\":\"Elisa Marco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"caption\":\"Elisa Marco\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La profesora Susana Sanz participa en la jornada cient\u00edfica sobre la defensa del inter\u00e9s superior del ni\u00f1o, en la Universidad Caddi Ayyad de Marrakech","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/","og_locale":"es_ES","og_type":"article","og_title":"La profesora Susana Sanz participa en la jornada cient\u00edfica sobre la defensa del inter\u00e9s superior del ni\u00f1o, en la Universidad Caddi Ayyad de Marrakech","og_description":"La CEU-UCH lidera un proyecto de I+D en esta materia, en el que participa tanto esta universidad marroqu\u00ed, como otras de Italia, M\u00e9xico, Per\u00fa y Chile La catedr\u00e1tica de Derecho Internacional P\u00fablico en la Universidad CEU Cardenal Herrera Susana Sanz Caballero ha sido invitada por la Universidad Caddi Ayyad, de Marrakech, para participar en una [&hellip;]","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2015-06-16T16:19:01+00:00","article_modified_time":"2023-02-13T12:18:30+00:00","og_image":[{"width":2202,"height":1528,"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg","type":"image\/jpeg"}],"author":"Elisa Marco","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Elisa Marco","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/"},"author":{"name":"Elisa Marco","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334"},"headline":"La profesora Susana Sanz participa en la jornada cient\u00edfica sobre la defensa del inter\u00e9s superior del ni\u00f1o, en la Universidad Caddi Ayyad de Marrakech","datePublished":"2015-06-16T16:19:01+00:00","dateModified":"2023-02-13T12:18:30+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/"},"wordCount":452,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg","keywords":["Dpto. Derecho P\u00fablico","Facultad Derecho, Empresa y Ciencias Pol\u00edticas","Grado Derecho","Grupo CEDRI"],"articleSection":["Actualidad Cient\u00edfica","Derecho y Pol\u00edticas"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/","name":"La profesora Susana Sanz participa en la jornada cient\u00edfica sobre la defensa del inter\u00e9s superior del ni\u00f1o, en la Universidad Caddi Ayyad de Marrakech","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/#primaryimage"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg","datePublished":"2015-06-16T16:19:01+00:00","dateModified":"2023-02-13T12:18:30+00:00","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/#primaryimage","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg","width":2202,"height":1528,"caption":"A la derecha, la profesora de la CEU-UCH, Susana Sanz, junto a profesoras de las universidades marroqu\u00edes de Caddi Ayyad (Marrakech) y Ibn Zohr (Agadir)."},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-profesora-susana-sanz-participa-en-la-jornada-cientifica-sobre-la-defensa-del-interes-superior-del-nino-en-la-universidad-caddi-ayyad-de-marrakech\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"La profesora Susana Sanz participa en la jornada cient\u00edfica sobre la defensa del inter\u00e9s superior del ni\u00f1o, en la Universidad Caddi Ayyad de Marrakech"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334","name":"Elisa Marco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","caption":"Elisa Marco"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg",2202,1528,false],"thumbnail":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-150x150.jpg",150,150,true],"medium":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-300x208.jpg",300,208,true],"medium_large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg",696,483,false],"large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-1024x711.jpg",696,483,true],"listado":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-310x174.jpg",310,174,true],"nuevaweb":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg",280,194,false],"destacadablogs":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg",404,280,false],"1536x1536":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg",1536,1066,false],"2048x2048":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg",2048,1421,false],"td_150x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg",150,104,false],"td_218x150":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-218x150.jpg",218,150,true],"td_300x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg",300,208,false],"td_324x400":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-324x400.jpg",324,400,true],"td_485x360":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg",485,337,false],"td_696x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-696x483.jpg",696,483,true],"td_1068x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-1068x741.jpg",1068,741,true],"td_1920x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos.jpg",1920,1332,false],"td_0x420":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-605x420.jpg",605,420,true],"td_80x60":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-80x60.jpg",80,60,true],"td_100x70":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-100x70.jpg",100,70,true],"td_265x198":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-265x198.jpg",265,198,true],"td_324x160":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-324x160.jpg",324,160,true],"td_324x235":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-324x235.jpg",324,235,true],"td_356x220":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-356x220.jpg",356,220,true],"td_356x364":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-356x364.jpg",356,364,true],"td_533x261":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-533x261.jpg",533,261,true],"td_534x462":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-534x462.jpg",534,462,true],"td_696x385":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-696x385.jpg",696,385,true],"td_741x486":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-741x486.jpg",741,486,true],"td_1068x580":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2015\/06\/susana-sanz-ceu-uch-marruecos-1068x580.jpg",1068,580,true]},"uagb_author_info":{"display_name":"Elisa Marco","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"},"uagb_comment_info":0,"uagb_excerpt":"La CEU-UCH lidera un proyecto de I+D en esta materia, en el que participa tanto esta universidad marroqu\u00ed, como otras de Italia, M\u00e9xico, Per\u00fa y Chile La catedr\u00e1tica de Derecho Internacional P\u00fablico en la Universidad CEU Cardenal Herrera Susana Sanz Caballero ha sido invitada por la Universidad Caddi Ayyad, de Marrakech, para participar en una&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/57162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=57162"}],"version-history":[{"count":2,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/57162\/revisions"}],"predecessor-version":[{"id":153962,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/57162\/revisions\/153962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media\/57163"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=57162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=57162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=57162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}