{"id":5308,"date":"2009-07-15T00:00:00","date_gmt":"2009-07-14T22:00:00","guid":{"rendered":"https:\/\/blog.uchceu.es\/docu\/?p=5308"},"modified":"2020-11-05T11:52:12","modified_gmt":"2020-11-05T10:52:12","slug":"colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/","title":{"rendered":"Colaboraci\u00f3n entre la Facultad de Veterinaria de la CEU-UCH y la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas para el impulso de la acuicultura valenciana"},"content":{"rendered":"<p>Pondr\u00e1n en marcha actividades de investigaci\u00f3n, formaci\u00f3n y divulgaci\u00f3n para la especializaci\u00f3n en acuicultura y la formaci\u00f3n en pr\u00e1cticas de los futuros licenciados en Veterinaria<\/p>\n<p><img alt='El rector del CEU-UCH y el presidente de RIIA, durante la firma del convenio.' src='\/actualidad-ceu\/wp-content\/uploads\/docu\/ConvCEU-RIIA_23_07_2009.jpg' \/><\/p>\n<\/p>\n<p>El rector de la Universidad CEU Cardenal Herrera, Jos\u00e9 Alberto Parejo G\u00e1mir, y el presidente de la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas (RIIA) de la Comunidad Valenciana, Rodolfo Barrera, han suscrito un convenio marco de colaboraci\u00f3n. El objeto del acuerdo es fomentar la formaci\u00f3n especializada de los futuros veterinarios valencianos en el \u00e1rea de la acuicultura, mediante la impartici\u00f3n de cursos, as\u00ed como la realizaci\u00f3n de pr\u00e1cticas en empresas del sector.<br \/>La colaboraci\u00f3n con la Facultad de Veterinaria de la Universidad CEU Cardenal Herrera de Valencia podr\u00e1 abarcar en el futuro todas las l\u00edneas de actuaci\u00f3n del RIIA, en materia de transferencia tecnol\u00f3gica, promoci\u00f3n del sector acu\u00edcola, investigaci\u00f3n, formaci\u00f3n y sanidad humana y animal. Adem\u00e1s, el acuerdo permitir\u00e1 la realizaci\u00f3n de pr\u00e1cticas formativas por parte de los estudiantes en las empresas asociadas a RIIA, dedicadas a la producci\u00f3n de moluscos y peces marinos.<\/p>\n<p><b>Acuicultura valenciana<\/b><br \/>La Red de Innovaci\u00f3n en Industrias Acu\u00edcolas (RIIA) de la Comunidad Valenciana, dirigida por el doctor Francisco Espin\u00f3s, es un observatorio que estudia las posibilidades y tendencias del sector de la acuicultura de la Comunidad Valenciana y facilita la incorporaci\u00f3n de tecnolog\u00eda, las alianzas, la disponibilidad de recursos, etc. La red surge a partir del Plan de Impulso al Sector de la Acuicultura de la Comunidad Valenciana que elabor\u00f3 la Conseller\u00eda de Empresa, Universidad y Ciencia de la Generalitat Valenciana en 2005, tras ser catalogada como sector emergente.<br \/>La Comunidad Valenciana se ha situado en los \u00faltimos a\u00f1os a la cabeza de la producci\u00f3n acu\u00edcola nacional en lo que se refiere a la acuicultura marina de peces, seguida de Canarias y Andaluc\u00eda. En concreto, la Comunidad Valenciana lidera la producci\u00f3n de dorada, corvina y anguila, y es la tercera productora de lubina. Entre las empresas valencianas, se encuentra la segunda instalaci\u00f3n m\u00e1s grande de de Europa dedicada al engorde de anguila en circuito cerrado, con el 100% de la producci\u00f3n nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pondr\u00e1n en marcha actividades de investigaci\u00f3n, formaci\u00f3n y divulgaci\u00f3n para la especializaci\u00f3n en acuicultura y la formaci\u00f3n en pr\u00e1cticas de los futuros licenciados en Veterinaria El rector de la Universidad CEU Cardenal Herrera, Jos\u00e9 Alberto Parejo G\u00e1mir, y el presidente de la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas (RIIA) de la Comunidad Valenciana, Rodolfo Barrera, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[1410],"tags":[127],"class_list":["post-5308","post","type-post","status-publish","format-standard","category-es-noticia","tag-convenios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colaboraci\u00f3n entre la Facultad de Veterinaria de la CEU-UCH y la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas para el impulso de la acuicultura valenciana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colaboraci\u00f3n entre la Facultad de Veterinaria de la CEU-UCH y la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas para el impulso de la acuicultura valenciana\" \/>\n<meta property=\"og:description\" content=\"Pondr\u00e1n en marcha actividades de investigaci\u00f3n, formaci\u00f3n y divulgaci\u00f3n para la especializaci\u00f3n en acuicultura y la formaci\u00f3n en pr\u00e1cticas de los futuros licenciados en Veterinaria El rector de la Universidad CEU Cardenal Herrera, Jos\u00e9 Alberto Parejo G\u00e1mir, y el presidente de la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas (RIIA) de la Comunidad Valenciana, Rodolfo Barrera, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-14T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-05T10:52:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/docu\/ConvCEU-RIIA_23_07_2009.jpg\" \/>\n<meta name=\"author\" content=\"Elisa Marco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa Marco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\\\/\"},\"author\":{\"name\":\"Elisa Marco\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\"},\"headline\":\"Colaboraci\u00f3n entre la Facultad de Veterinaria de la CEU-UCH y la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas para el impulso de la acuicultura valenciana\",\"datePublished\":\"2009-07-14T22:00:00+00:00\",\"dateModified\":\"2020-11-05T10:52:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\\\/\"},\"wordCount\":408,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"keywords\":[\"Convenios\"],\"articleSection\":[\"Es noticia\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\\\/\",\"name\":\"Colaboraci\u00f3n entre la Facultad de Veterinaria de la CEU-UCH y la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas para el impulso de la acuicultura valenciana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"datePublished\":\"2009-07-14T22:00:00+00:00\",\"dateModified\":\"2020-11-05T10:52:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colaboraci\u00f3n entre la Facultad de Veterinaria de la CEU-UCH y la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas para el impulso de la acuicultura valenciana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\",\"name\":\"Elisa Marco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"caption\":\"Elisa Marco\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colaboraci\u00f3n entre la Facultad de Veterinaria de la CEU-UCH y la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas para el impulso de la acuicultura valenciana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/","og_locale":"es_ES","og_type":"article","og_title":"Colaboraci\u00f3n entre la Facultad de Veterinaria de la CEU-UCH y la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas para el impulso de la acuicultura valenciana","og_description":"Pondr\u00e1n en marcha actividades de investigaci\u00f3n, formaci\u00f3n y divulgaci\u00f3n para la especializaci\u00f3n en acuicultura y la formaci\u00f3n en pr\u00e1cticas de los futuros licenciados en Veterinaria El rector de la Universidad CEU Cardenal Herrera, Jos\u00e9 Alberto Parejo G\u00e1mir, y el presidente de la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas (RIIA) de la Comunidad Valenciana, Rodolfo Barrera, [&hellip;]","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2009-07-14T22:00:00+00:00","article_modified_time":"2020-11-05T10:52:12+00:00","og_image":[{"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/docu\/ConvCEU-RIIA_23_07_2009.jpg","type":"","width":"","height":""}],"author":"Elisa Marco","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Elisa Marco","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/"},"author":{"name":"Elisa Marco","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334"},"headline":"Colaboraci\u00f3n entre la Facultad de Veterinaria de la CEU-UCH y la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas para el impulso de la acuicultura valenciana","datePublished":"2009-07-14T22:00:00+00:00","dateModified":"2020-11-05T10:52:12+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/"},"wordCount":408,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"keywords":["Convenios"],"articleSection":["Es noticia"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/","name":"Colaboraci\u00f3n entre la Facultad de Veterinaria de la CEU-UCH y la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas para el impulso de la acuicultura valenciana","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"datePublished":"2009-07-14T22:00:00+00:00","dateModified":"2020-11-05T10:52:12+00:00","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/colaboracion-entre-la-facultad-de-veterinaria-de-la-ceu-uch-y-la-red-de-innovacion-en-industrias-acuicolas-para-el-impulso-de-la-acuicultura-valenciana-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"Colaboraci\u00f3n entre la Facultad de Veterinaria de la CEU-UCH y la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas para el impulso de la acuicultura valenciana"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334","name":"Elisa Marco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","caption":"Elisa Marco"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"listado":false,"nuevaweb":false,"destacadablogs":false,"1536x1536":false,"2048x2048":false,"td_150x0":false,"td_218x150":false,"td_300x0":false,"td_324x400":false,"td_485x360":false,"td_696x0":false,"td_1068x0":false,"td_1920x0":false,"td_0x420":false,"td_80x60":false,"td_100x70":false,"td_265x198":false,"td_324x160":false,"td_324x235":false,"td_356x220":false,"td_356x364":false,"td_533x261":false,"td_534x462":false,"td_696x385":false,"td_741x486":false,"td_1068x580":false},"uagb_author_info":{"display_name":"Elisa Marco","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"},"uagb_comment_info":0,"uagb_excerpt":"Pondr\u00e1n en marcha actividades de investigaci\u00f3n, formaci\u00f3n y divulgaci\u00f3n para la especializaci\u00f3n en acuicultura y la formaci\u00f3n en pr\u00e1cticas de los futuros licenciados en Veterinaria El rector de la Universidad CEU Cardenal Herrera, Jos\u00e9 Alberto Parejo G\u00e1mir, y el presidente de la Red de Innovaci\u00f3n en Industrias Acu\u00edcolas (RIIA) de la Comunidad Valenciana, Rodolfo Barrera,&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=5308"}],"version-history":[{"count":1,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5308\/revisions"}],"predecessor-version":[{"id":93173,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5308\/revisions\/93173"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=5308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=5308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=5308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}