{"id":5307,"date":"2009-07-16T00:00:00","date_gmt":"2009-07-15T22:00:00","guid":{"rendered":"https:\/\/blog.uchceu.es\/docu\/?p=5307"},"modified":"2020-11-05T11:52:05","modified_gmt":"2020-11-05T10:52:05","slug":"la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/","title":{"rendered":"La Universidad CEU Cardenal Herrera concede 90 Becas a la Excelencia a los alumnos de nuevo ingreso con mejor expediente acad\u00e9mico"},"content":{"rendered":"<p>Estas becas suponen la exenci\u00f3n total de los honorarios de primer curso y se renovar\u00e1n anualmente con una nota media de notable o superior<\/p>\n<p><img alt='Se suman a las 10 modalidades de becas concedidas por la Fundaci\u00f3n Universitaria San Pablo CEU y a las becas y premios de entidades privadas para alumnos de la CEU-UCH' src='\/actualidad-ceu\/wp-content\/uploads\/docu\/CEU-2006415_1_16_07_2009.jpg' \/><\/p>\n<\/p>\n<p>Los alumnos de nuevo ingreso en la Universidad CEU Cardenal Herrera con una nota media de 8 en el Bachillerato y la Selectividad recibir\u00e1n una de las 90 Becas a la Excelencia para J\u00f3venes con Talento, implantadas este curso por la CEU-UCH. La ayuda se conceder\u00e1 a los alumnos que se matriculen en cualquiera de las titulaciones de la Universidad y suponen la gratuidad de la ense\u00f1anza del primer curso. Los beneficiarios podr\u00e1n seguir disfrutando de la beca hasta el t\u00e9rmino de su carrera, siempre que en cada curso acad\u00e9mico obtengan una calificaci\u00f3n media de notable como m\u00ednimo. <br \/>Por Facultades, la distribuci\u00f3n de las becas es la siguiente: 10 becas en la Facultad de Veterinaria, 18 becas en la Facultad de Ciencias de la Salud, 15 becas en la Facultad de Humanidades y Ciencias de la Comunicaci\u00f3n, 15 becas en la Facultad de Derecho, Empresa y Ciencias Pol\u00edticas y 12 becas en la Escuela Superior de Ense\u00f1anzas T\u00e9cnicas. Tambi\u00e9n se conceder\u00e1n 15 becas en el centro de Elche y 5 en el de Castell\u00f3n, donde la Universidad CEU Cardenal Herrera imparte la diplomatura en Enfermer\u00eda.<\/p>\n<p><b>Becas de la Fundaci\u00f3n Universitaria San Pablo CEU<\/b> <br \/>Estas nuevas becas a la Excelencia para J\u00f3venes con Talento se suman a las 10 modalidades de becas y ayudas al estudio concedidas por la Fundaci\u00f3n Universitaria San Pablo CEU a los alumnos de sus distintos centros (becas a la excelencia, bonificaciones por familia numerosa, becas de colaboraci\u00f3n, becas conveniadas con Ayuntamientos, etc.); a las becas y premios concedidos por empresas y entidades privadas a los estudiantes de la Cardenal Herrera (Bancaja, Banco de Santander, Ocaso, etc.) y a las becas oficiales concedidas por las administraciones p\u00fablicas, a las que tambi\u00e9n pueden optar los estudiantes de la Universidad CEU Cardenal Herrera.<br \/>El plazo de solicitud de las nuevas 90 Becas a la Excelencia para J\u00f3venes con Talento finaliza el 1 de septiembre. La solicitud de los estudiantes de nuevo ingreso debe presentarse en la Unidad de Becas de la Secretar\u00eda General de la Universidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estas becas suponen la exenci\u00f3n total de los honorarios de primer curso y se renovar\u00e1n anualmente con una nota media de notable o superior Los alumnos de nuevo ingreso en la Universidad CEU Cardenal Herrera con una nota media de 8 en el Bachillerato y la Selectividad recibir\u00e1n una de las 90 Becas a la [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[1410],"tags":[],"class_list":["post-5307","post","type-post","status-publish","format-standard","category-es-noticia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Universidad CEU Cardenal Herrera concede 90 Becas a la Excelencia a los alumnos de nuevo ingreso con mejor expediente acad\u00e9mico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Universidad CEU Cardenal Herrera concede 90 Becas a la Excelencia a los alumnos de nuevo ingreso con mejor expediente acad\u00e9mico\" \/>\n<meta property=\"og:description\" content=\"Estas becas suponen la exenci\u00f3n total de los honorarios de primer curso y se renovar\u00e1n anualmente con una nota media de notable o superior Los alumnos de nuevo ingreso en la Universidad CEU Cardenal Herrera con una nota media de 8 en el Bachillerato y la Selectividad recibir\u00e1n una de las 90 Becas a la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-15T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-05T10:52:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/docu\/CEU-2006415_1_16_07_2009.jpg\" \/>\n<meta name=\"author\" content=\"Elisa Marco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa Marco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\\\/\"},\"author\":{\"name\":\"Elisa Marco\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\"},\"headline\":\"La Universidad CEU Cardenal Herrera concede 90 Becas a la Excelencia a los alumnos de nuevo ingreso con mejor expediente acad\u00e9mico\",\"datePublished\":\"2009-07-15T22:00:00+00:00\",\"dateModified\":\"2020-11-05T10:52:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\\\/\"},\"wordCount\":397,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"articleSection\":[\"Es noticia\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\\\/\",\"name\":\"La Universidad CEU Cardenal Herrera concede 90 Becas a la Excelencia a los alumnos de nuevo ingreso con mejor expediente acad\u00e9mico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"datePublished\":\"2009-07-15T22:00:00+00:00\",\"dateModified\":\"2020-11-05T10:52:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Universidad CEU Cardenal Herrera concede 90 Becas a la Excelencia a los alumnos de nuevo ingreso con mejor expediente acad\u00e9mico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\",\"name\":\"Elisa Marco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"caption\":\"Elisa Marco\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Universidad CEU Cardenal Herrera concede 90 Becas a la Excelencia a los alumnos de nuevo ingreso con mejor expediente acad\u00e9mico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/","og_locale":"es_ES","og_type":"article","og_title":"La Universidad CEU Cardenal Herrera concede 90 Becas a la Excelencia a los alumnos de nuevo ingreso con mejor expediente acad\u00e9mico","og_description":"Estas becas suponen la exenci\u00f3n total de los honorarios de primer curso y se renovar\u00e1n anualmente con una nota media de notable o superior Los alumnos de nuevo ingreso en la Universidad CEU Cardenal Herrera con una nota media de 8 en el Bachillerato y la Selectividad recibir\u00e1n una de las 90 Becas a la [&hellip;]","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2009-07-15T22:00:00+00:00","article_modified_time":"2020-11-05T10:52:05+00:00","og_image":[{"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/docu\/CEU-2006415_1_16_07_2009.jpg","type":"","width":"","height":""}],"author":"Elisa Marco","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Elisa Marco","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/"},"author":{"name":"Elisa Marco","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334"},"headline":"La Universidad CEU Cardenal Herrera concede 90 Becas a la Excelencia a los alumnos de nuevo ingreso con mejor expediente acad\u00e9mico","datePublished":"2009-07-15T22:00:00+00:00","dateModified":"2020-11-05T10:52:05+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/"},"wordCount":397,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"articleSection":["Es noticia"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/","name":"La Universidad CEU Cardenal Herrera concede 90 Becas a la Excelencia a los alumnos de nuevo ingreso con mejor expediente acad\u00e9mico","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"datePublished":"2009-07-15T22:00:00+00:00","dateModified":"2020-11-05T10:52:05+00:00","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-universidad-ceu-cardenal-herrera-concede-90-becas-a-la-excelencia-a-los-alumnos-de-nuevo-ingreso-con-mejor-expediente-academico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"La Universidad CEU Cardenal Herrera concede 90 Becas a la Excelencia a los alumnos de nuevo ingreso con mejor expediente acad\u00e9mico"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334","name":"Elisa Marco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","caption":"Elisa Marco"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"listado":false,"nuevaweb":false,"destacadablogs":false,"1536x1536":false,"2048x2048":false,"td_150x0":false,"td_218x150":false,"td_300x0":false,"td_324x400":false,"td_485x360":false,"td_696x0":false,"td_1068x0":false,"td_1920x0":false,"td_0x420":false,"td_80x60":false,"td_100x70":false,"td_265x198":false,"td_324x160":false,"td_324x235":false,"td_356x220":false,"td_356x364":false,"td_533x261":false,"td_534x462":false,"td_696x385":false,"td_741x486":false,"td_1068x580":false},"uagb_author_info":{"display_name":"Elisa Marco","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"},"uagb_comment_info":0,"uagb_excerpt":"Estas becas suponen la exenci\u00f3n total de los honorarios de primer curso y se renovar\u00e1n anualmente con una nota media de notable o superior Los alumnos de nuevo ingreso en la Universidad CEU Cardenal Herrera con una nota media de 8 en el Bachillerato y la Selectividad recibir\u00e1n una de las 90 Becas a la&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=5307"}],"version-history":[{"count":1,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5307\/revisions"}],"predecessor-version":[{"id":93172,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5307\/revisions\/93172"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=5307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=5307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=5307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}