{"id":5300,"date":"2009-07-21T00:00:00","date_gmt":"2009-07-20T22:00:00","guid":{"rendered":"https:\/\/blog.uchceu.es\/docu\/?p=5300"},"modified":"2020-11-05T11:51:43","modified_gmt":"2020-11-05T10:51:43","slug":"curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/","title":{"rendered":"Curso de expresi\u00f3n oral, imagen y oratoria en la Universidad de Verano de la CEU-UCH"},"content":{"rendered":"<p>Impartido por el escritor y pedagogo Roberto Garc\u00eda Carbonell, experto en temas de comunicaci\u00f3n humana<\/p>\n<p><img alt='Roberto Garc\u00eda Carbonell y Antonio L\u00f3pez, en la inauguraci\u00f3n del curso de verano.' src='\/actualidad-ceu\/wp-content\/uploads\/docu\/CursoOratoria_30_07_2009.jpg' \/><\/p>\n<\/p>\n<p>Este mes de julio, los estudiantes de la Universidad CEU Cardenal Herrera han tenido la oportunidad de mejorar sus dotes de oratoria gracias al Curso de Verano dirigido por el vicedecano de la Facultad de Ciencias Sociales en Elche, Antonio L\u00f3pez. Con la participaci\u00f3n de Roberto Garc\u00eda Carbonell, autor de numerosos libros sobre la materia, los estudiantes han podido aprender t\u00e9cnicas para perfeccionar el empleo de la expresi\u00f3n oral, corporal, y emocional, para el desarrollo de las competencias y aptitudes que los alumnos necesitan en el mundo profesional.<\/p>\n<p><b>Conquistar al auditorio<\/b><br \/>En las sesiones del curso de verano los alumnos han practicado la mec\u00e1nica del habla y la soltura en los ademanes, han profundizado en la cultura de la mirada en p\u00fablico y persona-persona y han aprendido los recursos corporales afectivos m\u00e1s adecuados en la comunicaci\u00f3n. La colocaci\u00f3n, volumen, ritmos y pausas de la voz y la organizaci\u00f3n de las ideas, el mensaje y el gui\u00f3n de la exposici\u00f3n han centrado tambi\u00e9n las sesiones del curso. Con todo ello, los alumnos han profundizado, a trav\u00e9s de ejercicios y pr\u00e1cticas en el habla y la expresi\u00f3n, los recursos y t\u00e9cnicas de persuasi\u00f3n, la organizaci\u00f3n y disposici\u00f3n de las ideas y la conquista del auditorio. <br \/>Roberto Garc\u00eda Carbonell, profesor invitado al curso, es autor de diversos libros, entre los que destacan \u201ctodos pueden hablar bien. En p\u00fablico, en los negocios, en la conversaci\u00f3n privada\u201d; \u201cLectura rapida para todos\u00bb; \u00abEl poder de la expresi\u00f3n oral\u201d; y \u201cNuevas t\u00e9cnicas de comunicaci\u00f3n escrita\u201d, entre otros libros sobre la materia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impartido por el escritor y pedagogo Roberto Garc\u00eda Carbonell, experto en temas de comunicaci\u00f3n humana Este mes de julio, los estudiantes de la Universidad CEU Cardenal Herrera han tenido la oportunidad de mejorar sus dotes de oratoria gracias al Curso de Verano dirigido por el vicedecano de la Facultad de Ciencias Sociales en Elche, Antonio [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[1410],"tags":[],"class_list":["post-5300","post","type-post","status-publish","format-standard","category-es-noticia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Curso de expresi\u00f3n oral, imagen y oratoria en la Universidad de Verano de la CEU-UCH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso de expresi\u00f3n oral, imagen y oratoria en la Universidad de Verano de la CEU-UCH\" \/>\n<meta property=\"og:description\" content=\"Impartido por el escritor y pedagogo Roberto Garc\u00eda Carbonell, experto en temas de comunicaci\u00f3n humana Este mes de julio, los estudiantes de la Universidad CEU Cardenal Herrera han tenido la oportunidad de mejorar sus dotes de oratoria gracias al Curso de Verano dirigido por el vicedecano de la Facultad de Ciencias Sociales en Elche, Antonio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-20T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-05T10:51:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/docu\/CursoOratoria_30_07_2009.jpg\" \/>\n<meta name=\"author\" content=\"Elisa Marco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa Marco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\\\/\"},\"author\":{\"name\":\"Elisa Marco\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\"},\"headline\":\"Curso de expresi\u00f3n oral, imagen y oratoria en la Universidad de Verano de la CEU-UCH\",\"datePublished\":\"2009-07-20T22:00:00+00:00\",\"dateModified\":\"2020-11-05T10:51:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\\\/\"},\"wordCount\":314,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"articleSection\":[\"Es noticia\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\\\/\",\"name\":\"Curso de expresi\u00f3n oral, imagen y oratoria en la Universidad de Verano de la CEU-UCH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"datePublished\":\"2009-07-20T22:00:00+00:00\",\"dateModified\":\"2020-11-05T10:51:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso de expresi\u00f3n oral, imagen y oratoria en la Universidad de Verano de la CEU-UCH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\",\"name\":\"Elisa Marco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"caption\":\"Elisa Marco\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curso de expresi\u00f3n oral, imagen y oratoria en la Universidad de Verano de la CEU-UCH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/","og_locale":"es_ES","og_type":"article","og_title":"Curso de expresi\u00f3n oral, imagen y oratoria en la Universidad de Verano de la CEU-UCH","og_description":"Impartido por el escritor y pedagogo Roberto Garc\u00eda Carbonell, experto en temas de comunicaci\u00f3n humana Este mes de julio, los estudiantes de la Universidad CEU Cardenal Herrera han tenido la oportunidad de mejorar sus dotes de oratoria gracias al Curso de Verano dirigido por el vicedecano de la Facultad de Ciencias Sociales en Elche, Antonio [&hellip;]","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2009-07-20T22:00:00+00:00","article_modified_time":"2020-11-05T10:51:43+00:00","og_image":[{"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/docu\/CursoOratoria_30_07_2009.jpg","type":"","width":"","height":""}],"author":"Elisa Marco","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Elisa Marco","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/"},"author":{"name":"Elisa Marco","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334"},"headline":"Curso de expresi\u00f3n oral, imagen y oratoria en la Universidad de Verano de la CEU-UCH","datePublished":"2009-07-20T22:00:00+00:00","dateModified":"2020-11-05T10:51:43+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/"},"wordCount":314,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"articleSection":["Es noticia"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/","name":"Curso de expresi\u00f3n oral, imagen y oratoria en la Universidad de Verano de la CEU-UCH","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"datePublished":"2009-07-20T22:00:00+00:00","dateModified":"2020-11-05T10:51:43+00:00","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/curso-de-expresion-oral-imagen-y-oratoria-en-la-universidad-de-verano-de-la-ceu-uch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"Curso de expresi\u00f3n oral, imagen y oratoria en la Universidad de Verano de la CEU-UCH"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334","name":"Elisa Marco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","caption":"Elisa Marco"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"listado":false,"nuevaweb":false,"destacadablogs":false,"1536x1536":false,"2048x2048":false,"td_150x0":false,"td_218x150":false,"td_300x0":false,"td_324x400":false,"td_485x360":false,"td_696x0":false,"td_1068x0":false,"td_1920x0":false,"td_0x420":false,"td_80x60":false,"td_100x70":false,"td_265x198":false,"td_324x160":false,"td_324x235":false,"td_356x220":false,"td_356x364":false,"td_533x261":false,"td_534x462":false,"td_696x385":false,"td_741x486":false,"td_1068x580":false},"uagb_author_info":{"display_name":"Elisa Marco","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"},"uagb_comment_info":0,"uagb_excerpt":"Impartido por el escritor y pedagogo Roberto Garc\u00eda Carbonell, experto en temas de comunicaci\u00f3n humana Este mes de julio, los estudiantes de la Universidad CEU Cardenal Herrera han tenido la oportunidad de mejorar sus dotes de oratoria gracias al Curso de Verano dirigido por el vicedecano de la Facultad de Ciencias Sociales en Elche, Antonio&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=5300"}],"version-history":[{"count":1,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5300\/revisions"}],"predecessor-version":[{"id":93169,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5300\/revisions\/93169"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=5300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=5300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=5300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}