{"id":5265,"date":"2009-10-03T00:00:00","date_gmt":"2009-10-02T22:00:00","guid":{"rendered":"https:\/\/blog.uchceu.es\/docu\/?p=5265"},"modified":"2009-10-03T00:00:00","modified_gmt":"2009-10-02T22:00:00","slug":"investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/","title":{"rendered":"Investigadores del CIMA se ubicar\u00e1n en la Universidad CEU Cardenal Herrera"},"content":{"rendered":"<p>El grupo de cient\u00edficos de la Universidad de Navarra analizar\u00e1 los genes y las funciones de una prote\u00edna relevante en el desarrollo de un tipo de linfomas<\/p>\n<p><img alt='Se prev\u00e9 que la colaboraci\u00f3n dure, al menos, cuatro a\u00f1os.' src='\/actualidad-ceu\/wp-content\/uploads\/docu\/CIMA_14_10_2009.jpg' \/><\/p>\n<\/p>\n<p>Gracias al convenio de colaboraci\u00f3n que la Universidad CEU Cardenal Herrera y el Centro Investigaci\u00f3n M\u00e9dica Aplicada (CIMA) de la Universidad de Navarra han firmado recientemente, parte del laboratorio de Oncolog\u00eda Molecular del CIMA se trasladar\u00e1 a las instalaciones del CEU de Valencia. Esta colaboraci\u00f3n, pionera en Espa\u00f1a y que durar\u00e1 al menos cuatro a\u00f1os, supone que \u201csurjan nuevos cauces de comunicaci\u00f3n entre el grupo del CIMA, dirigido por el doctor Jos\u00e9 \u00c1ngel Mart\u00ednez Climent y otros grupos de investigaci\u00f3n del CEU\u201d, tal y como afirma el actual decano de la Facultad de Ciencias de la Salud, Francisco Javier Romero.<br \/>Esta colaboraci\u00f3n ya se ha iniciado con la publicaci\u00f3n que el grupo de investigadores de la CEU-UCH, que analiza sobre la leucemia y que est\u00e1 coordinado por el profesor Ignacio P\u00e9rez, y el grupo del CIMA han realizado en la revista Cancer Research. Y es que ambos grupos coinciden en el estudio de tumores relacionados con las c\u00e9lulas de la sangre. <br \/>En cuanto a la l\u00ednea de investigaci\u00f3n que desarrollar\u00e1n los cient\u00edficos del CIMA que se trasladen a las instalaciones de la Universidad CEU Cardenal Herrera se centrar\u00e1 en el estudio de los genes y las funciones de una prote\u00edna relevante en el desarrollo de un tipo de linfomas. Este an\u00e1lisis comenzar\u00e1 a desarrollarse a partir de enero de 2010 con la llegada de cuatro investigadores del Centro Investigaci\u00f3n M\u00e9dica Aplicada de la Universidad de Navarra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El grupo de cient\u00edficos de la Universidad de Navarra analizar\u00e1 los genes y las funciones de una prote\u00edna relevante en el desarrollo de un tipo de linfomas Gracias al convenio de colaboraci\u00f3n que la Universidad CEU Cardenal Herrera y el Centro Investigaci\u00f3n M\u00e9dica Aplicada (CIMA) de la Universidad de Navarra han firmado recientemente, parte del [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[3,4],"tags":[],"class_list":["post-5265","post","type-post","status-publish","format-standard","category-actualidad-cientifica","category-ciencias-de-la-salud-actualidad-cientifica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investigadores del CIMA se ubicar\u00e1n en la Universidad CEU Cardenal Herrera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investigadores del CIMA se ubicar\u00e1n en la Universidad CEU Cardenal Herrera\" \/>\n<meta property=\"og:description\" content=\"El grupo de cient\u00edficos de la Universidad de Navarra analizar\u00e1 los genes y las funciones de una prote\u00edna relevante en el desarrollo de un tipo de linfomas Gracias al convenio de colaboraci\u00f3n que la Universidad CEU Cardenal Herrera y el Centro Investigaci\u00f3n M\u00e9dica Aplicada (CIMA) de la Universidad de Navarra han firmado recientemente, parte del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-02T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/docu\/CIMA_14_10_2009.jpg\" \/>\n<meta name=\"author\" content=\"Elisa Marco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa Marco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\\\/\"},\"author\":{\"name\":\"Elisa Marco\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\"},\"headline\":\"Investigadores del CIMA se ubicar\u00e1n en la Universidad CEU Cardenal Herrera\",\"datePublished\":\"2009-10-02T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\\\/\"},\"wordCount\":298,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"articleSection\":[\"Actualidad Cient\u00edfica\",\"Ciencias de la Salud\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\\\/\",\"name\":\"Investigadores del CIMA se ubicar\u00e1n en la Universidad CEU Cardenal Herrera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"datePublished\":\"2009-10-02T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investigadores del CIMA se ubicar\u00e1n en la Universidad CEU Cardenal Herrera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\",\"name\":\"Elisa Marco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"caption\":\"Elisa Marco\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investigadores del CIMA se ubicar\u00e1n en la Universidad CEU Cardenal Herrera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/","og_locale":"es_ES","og_type":"article","og_title":"Investigadores del CIMA se ubicar\u00e1n en la Universidad CEU Cardenal Herrera","og_description":"El grupo de cient\u00edficos de la Universidad de Navarra analizar\u00e1 los genes y las funciones de una prote\u00edna relevante en el desarrollo de un tipo de linfomas Gracias al convenio de colaboraci\u00f3n que la Universidad CEU Cardenal Herrera y el Centro Investigaci\u00f3n M\u00e9dica Aplicada (CIMA) de la Universidad de Navarra han firmado recientemente, parte del [&hellip;]","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2009-10-02T22:00:00+00:00","og_image":[{"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/docu\/CIMA_14_10_2009.jpg","type":"","width":"","height":""}],"author":"Elisa Marco","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Elisa Marco","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/"},"author":{"name":"Elisa Marco","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334"},"headline":"Investigadores del CIMA se ubicar\u00e1n en la Universidad CEU Cardenal Herrera","datePublished":"2009-10-02T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/"},"wordCount":298,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"articleSection":["Actualidad Cient\u00edfica","Ciencias de la Salud"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/","name":"Investigadores del CIMA se ubicar\u00e1n en la Universidad CEU Cardenal Herrera","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"datePublished":"2009-10-02T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-del-cima-se-ubicaran-en-la-universidad-ceu-cardenal-herrera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"Investigadores del CIMA se ubicar\u00e1n en la Universidad CEU Cardenal Herrera"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334","name":"Elisa Marco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","caption":"Elisa Marco"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"listado":false,"nuevaweb":false,"destacadablogs":false,"1536x1536":false,"2048x2048":false,"td_150x0":false,"td_218x150":false,"td_300x0":false,"td_324x400":false,"td_485x360":false,"td_696x0":false,"td_1068x0":false,"td_1920x0":false,"td_0x420":false,"td_80x60":false,"td_100x70":false,"td_265x198":false,"td_324x160":false,"td_324x235":false,"td_356x220":false,"td_356x364":false,"td_533x261":false,"td_534x462":false,"td_696x385":false,"td_741x486":false,"td_1068x580":false},"uagb_author_info":{"display_name":"Elisa Marco","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"},"uagb_comment_info":0,"uagb_excerpt":"El grupo de cient\u00edficos de la Universidad de Navarra analizar\u00e1 los genes y las funciones de una prote\u00edna relevante en el desarrollo de un tipo de linfomas Gracias al convenio de colaboraci\u00f3n que la Universidad CEU Cardenal Herrera y el Centro Investigaci\u00f3n M\u00e9dica Aplicada (CIMA) de la Universidad de Navarra han firmado recientemente, parte del&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=5265"}],"version-history":[{"count":0,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5265\/revisions"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=5265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=5265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=5265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}