{"id":5251,"date":"2009-10-22T00:00:00","date_gmt":"2009-10-21T22:00:00","guid":{"rendered":"https:\/\/blog.uchceu.es\/docu\/?p=5251"},"modified":"2009-10-22T00:00:00","modified_gmt":"2009-10-21T22:00:00","slug":"el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/","title":{"rendered":"El Instituto IDEA presenta su C\u00e1tedra de Agua y Energ\u00edas Renovables"},"content":{"rendered":"<p>El acto ha estado presidido por el vicepresidente tercero del Consell, Juan Cotino<\/p>\n<p><img alt='La presentaci\u00f3n se ha celebrado en el Palacio de Colomina, sede del IDEA.' src='\/actualidad-ceu\/wp-content\/uploads\/docu\/CatedraAgua_22_10_2009.jpg' \/><\/p>\n<\/p>\n<p>El vicepresidente tercero y conseller de Medio Ambiente, Agua, Urbanismo y Vivienda, Juan Cotino, ha asistido a la presentaci\u00f3n de la C\u00e1tedra del Agua y Energ\u00edas Renovables, creada por el Instituto CEU de Derecho y \u00c9tica Ambiental (IDEA) y el Foro Solidario por el Agua y el Medio Ambiente (FOSAMA). En su intervenci\u00f3n, el conseller ha destacado la importancia del trabajo conjunto de todos los agentes sociales para defender aquello que es bueno para la sociedad y conseguir una Comunidad productiva y verde. Y ha destacado que \u201cel universitario es important\u00edsimo para la investigaci\u00f3n, para profundizar, para profundizar, para ver que realidad es la de nuestra Comunitat y ver como podemos avanzar para solucionar esta situaci\u00f3n\u201d.<br \/>Por su parte el rector de la Universidad CEU Cardenal Herrera ha destacado que esta C\u00e1tedra, fruto del convenio de colaboraci\u00f3n firmado entre la CEU-UCH y FOSAMA pretende ser \u201cun referente de la un referente en materia de investigaci\u00f3n, as\u00ed como en un importante foro de discusi\u00f3n, que nos permitir\u00e1 avanzar en la b\u00fasqueda de soluciones tanto para los problemas derivados de la escasez del agua como en la potenciaci\u00f3n de las energ\u00edas renovables\u201d, seg\u00fan el rector de la CEU-UCH. Y ha recordado, como prueba de ese dinamismo por el que trabaja el IDEA, la organizaci\u00f3n de las \u201cJornadas sobre el agua en Espa\u00f1a, cuestiones jur\u00eddicas y econ\u00f3micas\u201d, y las jornadas que pr\u00f3ximamente se celebrar\u00e1n sobre \u201cAgua y cambio clim\u00e1tico\u201d y sobre \u201cEnerg\u00edas Renovables y eficiencia energ\u00e9tica\u201d, organizadas junto al Ayuntamiento de Valencia.<br \/>Al acto tambi\u00e9n han asistido la concejal de Calidad Mediambiental, Energ\u00edas Renovables y Cambio Clim\u00e1tico, M\u00aa \u00c0ngels Ram\u00f3n-Llin; el presidente de la Federaci\u00f3n Valenciana. Forum Solidari per l\u2019 Aigua i el Medi Ambient, Federico Llorca; el director de la Fundaci\u00f3n Instituto Euromediterr\u00e1neo del Agua en Murcia, Francisco Cabezas; y el director del Instituto IDEA, I\u00f1aki Bilbao.<br \/><b><br \/>Estudio del Agua y las Energ\u00edas Renovables<\/b><br \/>La C\u00e1tedra de Agua y Energ\u00edas Renovables quiere fomentar el conocimientos de estas dos disciplinas entre la comunidad universitaria y ciudadan\u00eda e interactuar con entidades p\u00fablicas y privadas para colaborar en la investigaci\u00f3n. Adem\u00e1s pretende difundir la visi\u00f3n multidisciplinar en el \u00e1mbito del agua y las energ\u00edas renovables. Para conseguirlo trabajar\u00e1 seg\u00fan las l\u00edneas de actuaci\u00f3n que anualmente marcar\u00e1n el IDEA y FOSAMA, sus dos promotores, y se enmarcar\u00e1n en el \u00e1mbito de la formaci\u00f3n, de la investigaci\u00f3n y la transferencia y la divulgaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El acto ha estado presidido por el vicepresidente tercero del Consell, Juan Cotino El vicepresidente tercero y conseller de Medio Ambiente, Agua, Urbanismo y Vivienda, Juan Cotino, ha asistido a la presentaci\u00f3n de la C\u00e1tedra del Agua y Energ\u00edas Renovables, creada por el Instituto CEU de Derecho y \u00c9tica Ambiental (IDEA) y el Foro Solidario [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[3,18],"tags":[256],"class_list":["post-5251","post","type-post","status-publish","format-standard","category-actualidad-cientifica","category-medio-ambiente-actualidad-cientifica","tag-ideas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Instituto IDEA presenta su C\u00e1tedra de Agua y Energ\u00edas Renovables<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Instituto IDEA presenta su C\u00e1tedra de Agua y Energ\u00edas Renovables\" \/>\n<meta property=\"og:description\" content=\"El acto ha estado presidido por el vicepresidente tercero del Consell, Juan Cotino El vicepresidente tercero y conseller de Medio Ambiente, Agua, Urbanismo y Vivienda, Juan Cotino, ha asistido a la presentaci\u00f3n de la C\u00e1tedra del Agua y Energ\u00edas Renovables, creada por el Instituto CEU de Derecho y \u00c9tica Ambiental (IDEA) y el Foro Solidario [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2009-10-21T22:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/docu\/CatedraAgua_22_10_2009.jpg\" \/>\n<meta name=\"author\" content=\"Elisa Marco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa Marco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\\\/\"},\"author\":{\"name\":\"Elisa Marco\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\"},\"headline\":\"El Instituto IDEA presenta su C\u00e1tedra de Agua y Energ\u00edas Renovables\",\"datePublished\":\"2009-10-21T22:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\\\/\"},\"wordCount\":471,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"keywords\":[\"IDEAS\"],\"articleSection\":[\"Actualidad Cient\u00edfica\",\"Medio Ambiente\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\\\/\",\"name\":\"El Instituto IDEA presenta su C\u00e1tedra de Agua y Energ\u00edas Renovables\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"datePublished\":\"2009-10-21T22:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Instituto IDEA presenta su C\u00e1tedra de Agua y Energ\u00edas Renovables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\",\"name\":\"Elisa Marco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"caption\":\"Elisa Marco\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Instituto IDEA presenta su C\u00e1tedra de Agua y Energ\u00edas Renovables","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/","og_locale":"es_ES","og_type":"article","og_title":"El Instituto IDEA presenta su C\u00e1tedra de Agua y Energ\u00edas Renovables","og_description":"El acto ha estado presidido por el vicepresidente tercero del Consell, Juan Cotino El vicepresidente tercero y conseller de Medio Ambiente, Agua, Urbanismo y Vivienda, Juan Cotino, ha asistido a la presentaci\u00f3n de la C\u00e1tedra del Agua y Energ\u00edas Renovables, creada por el Instituto CEU de Derecho y \u00c9tica Ambiental (IDEA) y el Foro Solidario [&hellip;]","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2009-10-21T22:00:00+00:00","og_image":[{"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/docu\/CatedraAgua_22_10_2009.jpg","type":"","width":"","height":""}],"author":"Elisa Marco","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Elisa Marco","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/"},"author":{"name":"Elisa Marco","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334"},"headline":"El Instituto IDEA presenta su C\u00e1tedra de Agua y Energ\u00edas Renovables","datePublished":"2009-10-21T22:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/"},"wordCount":471,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"keywords":["IDEAS"],"articleSection":["Actualidad Cient\u00edfica","Medio Ambiente"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/","name":"El Instituto IDEA presenta su C\u00e1tedra de Agua y Energ\u00edas Renovables","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"datePublished":"2009-10-21T22:00:00+00:00","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-instituto-idea-presenta-su-catedra-de-agua-y-energias-renovables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"El Instituto IDEA presenta su C\u00e1tedra de Agua y Energ\u00edas Renovables"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334","name":"Elisa Marco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","caption":"Elisa Marco"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"listado":false,"nuevaweb":false,"destacadablogs":false,"1536x1536":false,"2048x2048":false,"td_150x0":false,"td_218x150":false,"td_300x0":false,"td_324x400":false,"td_485x360":false,"td_696x0":false,"td_1068x0":false,"td_1920x0":false,"td_0x420":false,"td_80x60":false,"td_100x70":false,"td_265x198":false,"td_324x160":false,"td_324x235":false,"td_356x220":false,"td_356x364":false,"td_533x261":false,"td_534x462":false,"td_696x385":false,"td_741x486":false,"td_1068x580":false},"uagb_author_info":{"display_name":"Elisa Marco","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"},"uagb_comment_info":0,"uagb_excerpt":"El acto ha estado presidido por el vicepresidente tercero del Consell, Juan Cotino El vicepresidente tercero y conseller de Medio Ambiente, Agua, Urbanismo y Vivienda, Juan Cotino, ha asistido a la presentaci\u00f3n de la C\u00e1tedra del Agua y Energ\u00edas Renovables, creada por el Instituto CEU de Derecho y \u00c9tica Ambiental (IDEA) y el Foro Solidario&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=5251"}],"version-history":[{"count":0,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5251\/revisions"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=5251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=5251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=5251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}