{"id":5235,"date":"2009-11-05T00:00:00","date_gmt":"2009-11-04T23:00:00","guid":{"rendered":"https:\/\/blog.uchceu.es\/docu\/?p=5235"},"modified":"2009-11-05T00:00:00","modified_gmt":"2009-11-04T23:00:00","slug":"manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/","title":{"rendered":"Manuel\u00a0 Toharia, en las Jornadas de Medio Ambiente y Derechos Humanos"},"content":{"rendered":"<p>El director del Museo de las Ciencias Pr\u00edncipe Felipe ha resaltado el mal uso del agua que se hace en los pa\u00edses desarrollados<\/p>\n<p><img alt='La profesora Ruth Abril, coordinadora de las sesiones, y el divulgador cient\u00edfico Manuel Toharia, en las Jornadas celebradas en el Palacio de Colomina..' src='\/actualidad-ceu\/wp-content\/uploads\/docu\/Toharia_05_11_2009.jpg' \/><\/p>\n<\/p>\n<p>El director del Museo de las Ciencias Pr\u00edncipe Felipe, Manuel Toharia, ha participado en las Jornadas \u201cMedio Ambiente y Derechos Humanos\u201d de la Universidad CEU Cardenal Herrera. En su intervenci\u00f3n, Toharia ha recordado que el problema del agua se concentra m\u00e1s en pa\u00edses en v\u00edas de desarrollo, donde no se cumple el derecho al agua potable \u201cporque mueren personas que no tienen acceso a los d<br \/>litros de agua necesarios para vivir\u201d. Y ha matizado que la causa es que el ser humano es \u201csofisticado biol\u00f3gicamente porque si pudi\u00e9ramos beber agua salada no tendr\u00edamos problemas con este recurso\u201d. Manuel Toharia tambi\u00e9n ha recordado la importancia de la concienciaci\u00f3n social adem\u00e1s de la educaci\u00f3n medioambiental.<br \/><b><br \/>Fuerzas Armadas y cambio clim\u00e1tico<\/b><br \/>En las sesiones de hoy de las Jornadas sobre \u201cMedio Ambiente y Derechos Humanos\u201d en la Universidad CEU Cardenal Herrera ha participado tambi\u00e9n el comandante Jes\u00fas Serrano, jefe de operaciones del Batall\u00f3n de Intervenci\u00f3n en B\u00e9tera de la Unidad Militar de Emergencias. Serrano ha afirmado que \u201clas Fuerzas Armadas espa\u00f1olas son las que tienen un mayor n\u00famero de instalaciones con certificaci\u00f3n medioambiental de toda la Uni\u00f3n Europea\u201d y que sus m\u00e9todos de tratamiento de residuos, ahorro energ\u00e9tico y conservaci\u00f3n del suelo \u201cse aplican en las bases militares instaladas en las misiones en el extranjero\u201d. Para el comandante Serrano, \u201cEspa\u00f1a y sus Fuerzas Armadas est\u00e1n a la cabeza en medidas de protecci\u00f3n medioambiental\u201d.<br \/>En este sentido, la creaci\u00f3n de la Unidad Militar de Emergencias es, para Serrano, \u201cun paso m\u00e1s\u201d. En sus dos a\u00f1os de plena operatividad, sus cinco batallones, integrados por m\u00e1s de 3.500 hombres, han desarrollado m\u00e1s de 40 intervenciones en incendios forestales, inundaciones o tormentas invernales. \u201cSomos la punta de lanza, los primeros en desplegarnos en cat\u00e1strofes que tienen su origen en el cambio clim\u00e1tico\u201d.<\/p>\n<p><b>\u00c1frica y la Cumbre de Barcelona<\/b><br \/>En las sesiones tambi\u00e9n se ha abordado el papel de Naciones Unidas por el cambio clim\u00e1tico, con la intervenci\u00f3n del ex oficial de Coordinaci\u00f3n del Sistema de Naciones Unidas en Belice, Antonio Moreno. Para Moreno, con experiencia tambi\u00e9n en las misiones de Cruz Roja desplegadas en N\u00edger, \u201cel cambio clim\u00e1tico es terriblemente injusto, porque los pa\u00edses menos desarrollados, que son los menos han contribuido a crear el problema, son, sin embargo, los que m\u00e1s est\u00e1n sufriendo las consecuencias\u201d. Esta es la raz\u00f3n que explica, seg\u00fan Moreno, la actitud de los pa\u00edses africanos, que hoy mismo han amenazado con marcharse de la Cumbre del Clima de Barcelona si los pa\u00edses ricos no aportan cifras concretas sobre reducci\u00f3n de emisiones de di\u00f3xido de carbono al que se comprometen para 2020.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director del Museo de las Ciencias Pr\u00edncipe Felipe ha resaltado el mal uso del agua que se hace en los pa\u00edses desarrollados El director del Museo de las Ciencias Pr\u00edncipe Felipe, Manuel Toharia, ha participado en las Jornadas \u201cMedio Ambiente y Derechos Humanos\u201d de la Universidad CEU Cardenal Herrera. En su intervenci\u00f3n, Toharia ha [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[3,18],"tags":[256],"class_list":["post-5235","post","type-post","status-publish","format-standard","category-actualidad-cientifica","category-medio-ambiente-actualidad-cientifica","tag-ideas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manuel\u00a0 Toharia, en las Jornadas de Medio Ambiente y Derechos Humanos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manuel\u00a0 Toharia, en las Jornadas de Medio Ambiente y Derechos Humanos\" \/>\n<meta property=\"og:description\" content=\"El director del Museo de las Ciencias Pr\u00edncipe Felipe ha resaltado el mal uso del agua que se hace en los pa\u00edses desarrollados El director del Museo de las Ciencias Pr\u00edncipe Felipe, Manuel Toharia, ha participado en las Jornadas \u201cMedio Ambiente y Derechos Humanos\u201d de la Universidad CEU Cardenal Herrera. En su intervenci\u00f3n, Toharia ha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2009-11-04T23:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/docu\/Toharia_05_11_2009.jpg\" \/>\n<meta name=\"author\" content=\"Elisa Marco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa Marco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\\\/\"},\"author\":{\"name\":\"Elisa Marco\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\"},\"headline\":\"Manuel\u00a0 Toharia, en las Jornadas de Medio Ambiente y Derechos Humanos\",\"datePublished\":\"2009-11-04T23:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\\\/\"},\"wordCount\":513,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"keywords\":[\"IDEAS\"],\"articleSection\":[\"Actualidad Cient\u00edfica\",\"Medio Ambiente\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\\\/\",\"name\":\"Manuel\u00a0 Toharia, en las Jornadas de Medio Ambiente y Derechos Humanos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"datePublished\":\"2009-11-04T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manuel\u00a0 Toharia, en las Jornadas de Medio Ambiente y Derechos Humanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\",\"name\":\"Elisa Marco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"caption\":\"Elisa Marco\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manuel\u00a0 Toharia, en las Jornadas de Medio Ambiente y Derechos Humanos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/","og_locale":"es_ES","og_type":"article","og_title":"Manuel\u00a0 Toharia, en las Jornadas de Medio Ambiente y Derechos Humanos","og_description":"El director del Museo de las Ciencias Pr\u00edncipe Felipe ha resaltado el mal uso del agua que se hace en los pa\u00edses desarrollados El director del Museo de las Ciencias Pr\u00edncipe Felipe, Manuel Toharia, ha participado en las Jornadas \u201cMedio Ambiente y Derechos Humanos\u201d de la Universidad CEU Cardenal Herrera. En su intervenci\u00f3n, Toharia ha [&hellip;]","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2009-11-04T23:00:00+00:00","og_image":[{"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/docu\/Toharia_05_11_2009.jpg","type":"","width":"","height":""}],"author":"Elisa Marco","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Elisa Marco","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/"},"author":{"name":"Elisa Marco","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334"},"headline":"Manuel\u00a0 Toharia, en las Jornadas de Medio Ambiente y Derechos Humanos","datePublished":"2009-11-04T23:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/"},"wordCount":513,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"keywords":["IDEAS"],"articleSection":["Actualidad Cient\u00edfica","Medio Ambiente"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/","name":"Manuel\u00a0 Toharia, en las Jornadas de Medio Ambiente y Derechos Humanos","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"datePublished":"2009-11-04T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/manuel-toharia-en-las-jornadas-de-medio-ambiente-y-derechos-humanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"Manuel\u00a0 Toharia, en las Jornadas de Medio Ambiente y Derechos Humanos"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334","name":"Elisa Marco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","caption":"Elisa Marco"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"listado":false,"nuevaweb":false,"destacadablogs":false,"1536x1536":false,"2048x2048":false,"td_150x0":false,"td_218x150":false,"td_300x0":false,"td_324x400":false,"td_485x360":false,"td_696x0":false,"td_1068x0":false,"td_1920x0":false,"td_0x420":false,"td_80x60":false,"td_100x70":false,"td_265x198":false,"td_324x160":false,"td_324x235":false,"td_356x220":false,"td_356x364":false,"td_533x261":false,"td_534x462":false,"td_696x385":false,"td_741x486":false,"td_1068x580":false},"uagb_author_info":{"display_name":"Elisa Marco","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"},"uagb_comment_info":0,"uagb_excerpt":"El director del Museo de las Ciencias Pr\u00edncipe Felipe ha resaltado el mal uso del agua que se hace en los pa\u00edses desarrollados El director del Museo de las Ciencias Pr\u00edncipe Felipe, Manuel Toharia, ha participado en las Jornadas \u201cMedio Ambiente y Derechos Humanos\u201d de la Universidad CEU Cardenal Herrera. En su intervenci\u00f3n, Toharia ha&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=5235"}],"version-history":[{"count":0,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/5235\/revisions"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=5235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=5235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=5235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}