{"id":40366,"date":"2014-02-13T17:02:58","date_gmt":"2014-02-13T16:02:58","guid":{"rendered":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?p=40366"},"modified":"2020-11-09T10:39:43","modified_gmt":"2020-11-09T09:39:43","slug":"el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/","title":{"rendered":"El tabaquismo y la salud mental, a debate en el ciclo \u201cEducar para la Salud\u201d de la Universidad CEU Cardenal Herrera de Castell\u00f3n"},"content":{"rendered":"<ul>\n<li>Los ponentes han sido el presidente y la secretaria general de la Real Academia de Medicina de la Comunidad Valenciana<b><br \/>\n<\/b><\/li>\n<\/ul>\n<p><a href=\"\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-debate.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40369\" src=\"\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-debate-1024x768.jpg\" alt=\"ciclo educar salud debate\" width=\"700\" height=\"525\" \/><\/a><\/p>\n<p>La patolog\u00eda del tabaquismo y su prevenci\u00f3n as\u00ed como los factores de riesgo y protecci\u00f3n en la salud mental han sido los dos asuntos abordados hoy en \u201cEducar para la Salud\u201d, un ciclo de conferencias de la Universidad CEU Cardenal Herrera de Castell\u00f3n que pretende promover h\u00e1bitos saludables entre la comunidad universitaria y la ciudadan\u00eda.<\/p>\n<p>Los ponentes han sido el doctor Antonio Llombart, catedr\u00e1tico de Histolog\u00eda y Anatom\u00eda Patol\u00f3gica y presidente de la Real Academia de Medicina de la Comunidad Valenciana, y la doctora Carmen Leal, secretaria general de esta instituci\u00f3n, catedr\u00e1tica de Psiquiatr\u00eda y miembro del Servicio de Psiquiatr\u00eda del Hospital Cl\u00ednico Universitario de Valencia.<\/p>\n<p>En su intervenci\u00f3n, el doctor Llombart ha recordado a los numerosos estudiantes que han acudido a las charlas que el tabaquismo \u201ces la mayor causa evitable de muerte en el mundo\u201d y que tiene, adem\u00e1s, un grave impacto sobre la salud p\u00fablica. \u201cSi la tendencia contin\u00faa, ha avisado el catedr\u00e1tico, morir\u00e1n 500 millones de personas en el siglo XXI\u201d.<\/p>\n<p>Ante lo impactante de las cifras, el m\u00e9dico ha optado por darles la vuelta con el objetivo de concienciar a los j\u00f3venes para que no caigan en este h\u00e1bito: \u201cSi no se fumara, se evitar\u00eda el 90% del c\u00e1ncer de pulm\u00f3n, el 20% de las muertes por enfermedades coronarias y el 80% por enfermedad pulmonar cr\u00f3nica\u201d. Por el contrario, \u201cel que empiece a fumar ahora, ha advertido, lo va a pagar seguro: en calidad de vida y en supervivencia\u201d.<\/p>\n<p>El presidente de la Real Academia ha animado a los ya fumadores a acogerse a programas de deshabituaci\u00f3n como los ofrecidos por entidades como la Asociaci\u00f3n Espa\u00f1ola Contra el C\u00e1ncer.<\/p>\n<p><a href=\"\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-40370\" src=\"\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes-1024x768.jpg\" alt=\"ciclo educar salud ponentes\" width=\"700\" height=\"525\" \/><\/a><b>Proteger la salud mental<\/b><\/p>\n<p>Por su parte, la doctora Leal ha abordado la importancia de la prevenci\u00f3n en la salud mental a trav\u00e9s de la implementaci\u00f3n de los factores de protecci\u00f3n que dependen de cada persona.<\/p>\n<p>Entre muchos otros, ha destacado la necesidad de procurarse una buena salud f\u00edsica evitando las drogas (incluido el tabaco), incrementar la autoestima, practicar estrategias para afrontar el estr\u00e9s, desarrollar buenas relaciones interpersonales y procurar una crianza adecuada. En este aspecto, la experta ha recomendado que el v\u00ednculo de padres e hijos \u201csea estable e incluya control, afecto e imposici\u00f3n de un modo equilibrado\u201d.<\/p>\n<p>La psiquiatra ha se\u00f1alado como grupos alto riesgo a las mujeres, los inmigrantes, los enfermos cr\u00f3nicos, los ni\u00f1os \u2013sean v\u00edctimas de abusos o bien hijos de personas con trastornos mentales-, los adolescentes y los parados. Respecto estos \u00faltimos, Leal ha destacado la creciente demanda que est\u00e1n experimentando las consultas para atender a personas que han perdido el empleo y padecen irritabilidad, angustia e insomnio entre otros s\u00edntomas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ponentes han sido el presidente y la secretaria general de la Real Academia de Medicina de la Comunidad Valenciana La patolog\u00eda del tabaquismo y su prevenci\u00f3n as\u00ed como los factores de riesgo y protecci\u00f3n en la salud mental han sido los dos asuntos abordados hoy en \u201cEducar para la Salud\u201d, un ciclo de conferencias [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":40370,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[1410,29,36,28],"tags":[83,218,327],"class_list":["post-40366","post","type-post","status-publish","format-standard","has-post-thumbnail","category-es-noticia","category-nota-de-prensa-castellon","category-x-slider-formacion","category-xnota-de-prensa","tag-campus-castellon","tag-grado-medicina","tag-medicina-castellon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El tabaquismo y la salud mental, a debate en el ciclo \u201cEducar para la Salud\u201d de la Universidad CEU Cardenal Herrera de Castell\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El tabaquismo y la salud mental, a debate en el ciclo \u201cEducar para la Salud\u201d de la Universidad CEU Cardenal Herrera de Castell\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Los ponentes han sido el presidente y la secretaria general de la Real Academia de Medicina de la Comunidad Valenciana La patolog\u00eda del tabaquismo y su prevenci\u00f3n as\u00ed como los factores de riesgo y protecci\u00f3n en la salud mental han sido los dos asuntos abordados hoy en \u201cEducar para la Salud\u201d, un ciclo de conferencias [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-13T16:02:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-09T09:39:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3264\" \/>\n\t<meta property=\"og:image:height\" content=\"2448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marisa Sanjuanbenito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marisa Sanjuanbenito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\\\/\"},\"author\":{\"name\":\"Marisa Sanjuanbenito\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/db9a2d353525ad9242d604bdcbb0b1fc\"},\"headline\":\"El tabaquismo y la salud mental, a debate en el ciclo \u201cEducar para la Salud\u201d de la Universidad CEU Cardenal Herrera de Castell\u00f3n\",\"datePublished\":\"2014-02-13T16:02:58+00:00\",\"dateModified\":\"2020-11-09T09:39:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\\\/\"},\"wordCount\":526,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/02\\\/ciclo-educar-salud-ponentes.jpg\",\"keywords\":[\"Campus Castell\u00f3n\",\"Grado Medicina\",\"Medicina castell\u00f3n\"],\"articleSection\":[\"Es noticia\",\"nota de prensa castellon\",\"x slider formacion\",\"xNota de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\\\/\",\"name\":\"El tabaquismo y la salud mental, a debate en el ciclo \u201cEducar para la Salud\u201d de la Universidad CEU Cardenal Herrera de Castell\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/02\\\/ciclo-educar-salud-ponentes.jpg\",\"datePublished\":\"2014-02-13T16:02:58+00:00\",\"dateModified\":\"2020-11-09T09:39:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/02\\\/ciclo-educar-salud-ponentes.jpg\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/02\\\/ciclo-educar-salud-ponentes.jpg\",\"width\":3264,\"height\":2448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El tabaquismo y la salud mental, a debate en el ciclo \u201cEducar para la Salud\u201d de la Universidad CEU Cardenal Herrera de Castell\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/db9a2d353525ad9242d604bdcbb0b1fc\",\"name\":\"Marisa Sanjuanbenito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eef2bed1784dc9d596a2c97a302447ccdbd00f04427f41618b70d1cb442d4eac?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eef2bed1784dc9d596a2c97a302447ccdbd00f04427f41618b70d1cb442d4eac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eef2bed1784dc9d596a2c97a302447ccdbd00f04427f41618b70d1cb442d4eac?s=96&d=mm&r=g\",\"caption\":\"Marisa Sanjuanbenito\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/marisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El tabaquismo y la salud mental, a debate en el ciclo \u201cEducar para la Salud\u201d de la Universidad CEU Cardenal Herrera de Castell\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/","og_locale":"es_ES","og_type":"article","og_title":"El tabaquismo y la salud mental, a debate en el ciclo \u201cEducar para la Salud\u201d de la Universidad CEU Cardenal Herrera de Castell\u00f3n","og_description":"Los ponentes han sido el presidente y la secretaria general de la Real Academia de Medicina de la Comunidad Valenciana La patolog\u00eda del tabaquismo y su prevenci\u00f3n as\u00ed como los factores de riesgo y protecci\u00f3n en la salud mental han sido los dos asuntos abordados hoy en \u201cEducar para la Salud\u201d, un ciclo de conferencias [&hellip;]","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2014-02-13T16:02:58+00:00","article_modified_time":"2020-11-09T09:39:43+00:00","og_image":[{"width":3264,"height":2448,"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg","type":"image\/jpeg"}],"author":"Marisa Sanjuanbenito","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Marisa Sanjuanbenito","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/"},"author":{"name":"Marisa Sanjuanbenito","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/db9a2d353525ad9242d604bdcbb0b1fc"},"headline":"El tabaquismo y la salud mental, a debate en el ciclo \u201cEducar para la Salud\u201d de la Universidad CEU Cardenal Herrera de Castell\u00f3n","datePublished":"2014-02-13T16:02:58+00:00","dateModified":"2020-11-09T09:39:43+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/"},"wordCount":526,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg","keywords":["Campus Castell\u00f3n","Grado Medicina","Medicina castell\u00f3n"],"articleSection":["Es noticia","nota de prensa castellon","x slider formacion","xNota de Prensa"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/","name":"El tabaquismo y la salud mental, a debate en el ciclo \u201cEducar para la Salud\u201d de la Universidad CEU Cardenal Herrera de Castell\u00f3n","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/#primaryimage"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg","datePublished":"2014-02-13T16:02:58+00:00","dateModified":"2020-11-09T09:39:43+00:00","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/#primaryimage","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg","width":3264,"height":2448},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-tabaquismo-y-la-salud-mental-a-debate-en-el-ciclo-educar-para-la-salud-de-la-universidad-ceu-cardenal-herrera-de-castellon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"El tabaquismo y la salud mental, a debate en el ciclo \u201cEducar para la Salud\u201d de la Universidad CEU Cardenal Herrera de Castell\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/db9a2d353525ad9242d604bdcbb0b1fc","name":"Marisa Sanjuanbenito","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eef2bed1784dc9d596a2c97a302447ccdbd00f04427f41618b70d1cb442d4eac?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eef2bed1784dc9d596a2c97a302447ccdbd00f04427f41618b70d1cb442d4eac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eef2bed1784dc9d596a2c97a302447ccdbd00f04427f41618b70d1cb442d4eac?s=96&d=mm&r=g","caption":"Marisa Sanjuanbenito"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/marisa\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",3264,2448,false],"thumbnail":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",150,113,false],"medium":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",300,225,false],"medium_large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",696,522,false],"large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",696,522,false],"listado":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",232,174,false],"nuevaweb":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",280,210,false],"destacadablogs":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",373,280,false],"1536x1536":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",1536,1152,false],"2048x2048":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",2048,1536,false],"td_150x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",150,113,false],"td_218x150":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",200,150,false],"td_300x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",300,225,false],"td_324x400":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",324,243,false],"td_485x360":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",480,360,false],"td_696x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",696,522,false],"td_1068x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",1068,801,false],"td_1920x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",1920,1440,false],"td_0x420":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",560,420,false],"td_80x60":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",80,60,false],"td_100x70":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",93,70,false],"td_265x198":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",265,198,false],"td_324x160":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",213,160,false],"td_324x235":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",313,235,false],"td_356x220":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",293,220,false],"td_356x364":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",356,267,false],"td_533x261":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",348,261,false],"td_534x462":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",534,401,false],"td_696x385":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",513,385,false],"td_741x486":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",648,486,false],"td_1068x580":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2014\/02\/ciclo-educar-salud-ponentes.jpg",773,580,false]},"uagb_author_info":{"display_name":"Marisa Sanjuanbenito","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/marisa\/"},"uagb_comment_info":0,"uagb_excerpt":"Los ponentes han sido el presidente y la secretaria general de la Real Academia de Medicina de la Comunidad Valenciana La patolog\u00eda del tabaquismo y su prevenci\u00f3n as\u00ed como los factores de riesgo y protecci\u00f3n en la salud mental han sido los dos asuntos abordados hoy en \u201cEducar para la Salud\u201d, un ciclo de conferencias&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/40366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=40366"}],"version-history":[{"count":1,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/40366\/revisions"}],"predecessor-version":[{"id":94137,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/40366\/revisions\/94137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media\/40370"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=40366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=40366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=40366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}