{"id":200088,"date":"2026-07-15T11:58:14","date_gmt":"2026-07-15T09:58:14","guid":{"rendered":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?p=200088"},"modified":"2026-07-15T12:13:38","modified_gmt":"2026-07-15T10:13:38","slug":"el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/","title":{"rendered":"El HCV CEU acoge la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera veterinario"},"content":{"rendered":"<ul>\n<li><strong>Organizado junto a BlueSAO Spain, re\u00fane a formadores de referencia internacional en la cirug\u00eda ortop\u00e9dica veterinaria<\/strong><\/li>\n<li><strong>El vicerrector <a href=\"https:\/\/www.uchceu.es\/directorio\/jmcorpa\">Juan Manuel Corpa<\/a> y el decano <a href=\"https:\/\/www.uchceu.es\/directorio\/jsopena\">Joaqu\u00edn Sopena<\/a>, han inaugurado el curso junto a Mar\u00eda Marcet, en representaci\u00f3n de la empresa colaboradora<\/strong><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-200089 size-full\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-3.jpg\" alt=\"\" width=\"2048\" height=\"1365\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-3.jpg 2048w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-3-300x200.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-3-1060x706.jpg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-3-768x512.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-3-1536x1024.jpg 1536w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-3-150x100.jpg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-3-696x464.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-3-1068x712.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-3-1920x1280.jpg 1920w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-3-630x420.jpg 630w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<p>El <a href=\"https:\/\/hospitalveterinario.uchceu.es\/\">Hospital Cl\u00ednico Veterinario de la Universidad CEU Cardenal Herrera<\/a> (HCV CEU) acoge esta semana la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera (Total Hip Replacement, THR), una formaci\u00f3n pionera que sit\u00faa a la Universidad como referente en la ense\u00f1anza de una de las t\u00e9cnicas m\u00e1s avanzadas de la cirug\u00eda ortop\u00e9dica veterinaria.<\/p>\n<p>Organizado junto a BlueSAO Spain, el curso re\u00fane a veterinarios procedentes de distintos pa\u00edses, tanto interesados en obtener la certificaci\u00f3n en esta t\u00e9cnica como en actualizar sus conocimientos sobre enfoques quir\u00fargicos de la mano de especialistas de reconocido prestigio internacional.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-200090 size-full\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-70.jpg\" alt=\"\" width=\"2048\" height=\"1365\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-70.jpg 2048w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-70-300x200.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-70-1060x706.jpg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-70-768x512.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-70-1536x1024.jpg 1536w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-70-150x100.jpg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-70-696x464.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-70-1068x712.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-70-1920x1280.jpg 1920w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-70-630x420.jpg 630w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<p>Entre los ponentes, destaca el Dr. Brian Beale (Estados Unidos), considerado como una de las m\u00e1ximas referencias mundiales en cirug\u00eda ortop\u00e9dica veterinaria. Junto a \u00e9l participa el Dr. Tom\u00e1s Guerrero, uno de los cirujanos con mayor experiencia en reemplazo total de cadera en Europa y referente internacional en la aplicaci\u00f3n cl\u00ednica de esta t\u00e9cnica. El equipo docente se completa con especialistas como el Dr. Zhou Luoping y el Dr. Chen Weili, reconocidos por su amplia trayectoria cl\u00ednica y acad\u00e9mica en cirug\u00eda prot\u00e9sica de cadera.<\/p>\n<p>El reemplazo total de cadera constituye una de las intervenciones m\u00e1s complejas y avanzadas dentro de la traumatolog\u00eda veterinaria. A pesar de sus excelentes resultados cl\u00ednicos, son pocas las compa\u00f1\u00edas que invierten en el desarrollo, formaci\u00f3n y difusi\u00f3n de esta tecnolog\u00eda, lo que convierte esta iniciativa en un paso importante para acercar esta cirug\u00eda a un mayor n\u00famero de profesionales.<\/p>\n<div id='gallery-1' class='gallery galleryid-200088 gallery-columns-2 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/ceu-bionic-thr-practicas\/'><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"464\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas-1060x706.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas-1060x706.jpg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas-300x200.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas-768x512.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas-1536x1024.jpg 1536w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas-150x100.jpg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas-696x464.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas-1068x712.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas-1920x1280.jpg 1920w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas-630x420.jpg 630w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas.jpg 2048w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/ceu-bionic-thr-practicas2\/'><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"464\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas2-1060x707.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas2-1060x707.jpg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas2-300x200.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas2-768x512.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas2-1536x1024.jpg 1536w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas2-2048x1365.jpg 2048w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas2-150x100.jpg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas2-696x464.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas2-1068x712.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas2-1920x1280.jpg 1920w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-bionic-thr-practicas2-630x420.jpg 630w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p><strong>Centro de referencia para la formaci\u00f3n veterinaria especializada<\/strong><\/p>\n<p>La inauguraci\u00f3n de este primer curso internacional se desarroll\u00f3 en el Paraninfo del campus de la CEU UCH en Valencia, con la participaci\u00f3n del vicerrector de Ordenaci\u00f3n Acad\u00e9mica, Digitalizaci\u00f3n y Calidad, Juan Manuel Corpa; el decano de la Facultad de Veterinaria, Joaqu\u00edn Sopena; y Mar\u00eda Marcet, en representaci\u00f3n de BlueSAO Spain.<\/p>\n<div id='gallery-2' class='gallery galleryid-200088 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/ceu-cursothr-hcv-9\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-9-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-9-300x200.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-9-1060x706.jpg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-9-768x512.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-9-1536x1024.jpg 1536w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-9-150x100.jpg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-9-696x464.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-9-1068x712.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-9-1920x1280.jpg 1920w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-9-630x420.jpg 630w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-9.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/ceu-cursothr-hcv-6\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-6-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-6-300x200.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-6-1060x706.jpg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-6-768x512.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-6-1536x1024.jpg 1536w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-6-150x100.jpg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-6-696x464.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-6-1068x712.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-6-1920x1280.jpg 1920w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-6-630x420.jpg 630w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-6.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/ceu-cursothr-hcv-30\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-30-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-30-300x200.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-30-1060x706.jpg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-30-768x512.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-30-1536x1024.jpg 1536w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-30-150x100.jpg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-30-696x464.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-30-1068x712.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-30-1920x1280.jpg 1920w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-30-630x420.jpg 630w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-30.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Con la organizaci\u00f3n de este curso, el Hospital Cl\u00ednico Veterinario de la Universidad CEU Cardenal Herrera refuerza su posici\u00f3n como centro de referencia para la formaci\u00f3n veterinaria especializada, la innovaci\u00f3n cl\u00ednica y la transferencia de tecnolog\u00eda aplicada a la pr\u00e1ctica profesional, consolidando adem\u00e1s su proyecci\u00f3n internacional en el \u00e1mbito de la medicina y cirug\u00eda veterinarias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organizado junto a BlueSAO Spain, re\u00fane a formadores de referencia internacional en la cirug\u00eda ortop\u00e9dica veterinaria El vicerrector Juan Manuel Corpa y el decano Joaqu\u00edn Sopena, han inaugurado el curso junto a Mar\u00eda Marcet, en representaci\u00f3n de la empresa colaboradora El Hospital Cl\u00ednico Veterinario de la Universidad CEU Cardenal Herrera (HCV CEU) acoge esta semana [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":200096,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[1410,1411,1750,1776,26],"tags":[1105,85,2090,1685],"class_list":["post-200088","post","type-post","status-publish","format-standard","has-post-thumbnail","category-es-noticia","category-expertos","category-nota-de-prensa-valencia-en","category-x-cuadritos-home-fr","category-x-cuadritos-home","tag-campus-internacional","tag-campus-valencia","tag-facultad-de-veterinaria","tag-hcv-ceu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El HCV CEU acoge la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera veterinario<\/title>\n<meta name=\"description\" content=\"El Hospital Cl\u00ednico Veterinario de la Universidad CEU Cardenal Herrera (HCV CEU) acoge esta semana la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera (Total Hip Replacement, THR), una formaci\u00f3n pionera que sit\u00faa a la Universidad como referente en la ense\u00f1anza de una de las t\u00e9cnicas m\u00e1s avanzadas de la cirug\u00eda ortop\u00e9dica veterinaria. Organizado junto a BlueSAO Spain, el curso re\u00fane a veterinarios procedentes de distintos pa\u00edses, tanto interesados en obtener la certificaci\u00f3n en esta t\u00e9cnica como en actualizar sus conocimientos sobre enfoques quir\u00fargicos de la mano de especialistas de reconocido prestigio internacional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El HCV CEU acoge la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera veterinario\" \/>\n<meta property=\"og:description\" content=\"El Hospital Cl\u00ednico Veterinario de la Universidad CEU Cardenal Herrera (HCV CEU) acoge esta semana la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera (Total Hip Replacement, THR), una formaci\u00f3n pionera que sit\u00faa a la Universidad como referente en la ense\u00f1anza de una de las t\u00e9cnicas m\u00e1s avanzadas de la cirug\u00eda ortop\u00e9dica veterinaria. Organizado junto a BlueSAO Spain, el curso re\u00fane a veterinarios procedentes de distintos pa\u00edses, tanto interesados en obtener la certificaci\u00f3n en esta t\u00e9cnica como en actualizar sus conocimientos sobre enfoques quir\u00fargicos de la mano de especialistas de reconocido prestigio internacional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T09:58:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T10:13:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana Salvador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Salvador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\\\/\"},\"author\":{\"name\":\"Ana Salvador\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/e9663a691e5285e1e04660b1315d65f0\"},\"headline\":\"El HCV CEU acoge la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera veterinario\",\"datePublished\":\"2026-07-15T09:58:14+00:00\",\"dateModified\":\"2026-07-15T10:13:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\\\/\"},\"wordCount\":491,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/07\\\/ceu-cursothr-hcv-14.jpg\",\"keywords\":[\"campus internacional\",\"Campus Valencia\",\"Facultad de Veterinaria\",\"HCV CEU\"],\"articleSection\":[\"Es noticia\",\"Expertos\",\"nota de prensa valencia\",\"x cuadritos home\",\"x cuadritos home\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\\\/\",\"name\":\"El HCV CEU acoge la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera veterinario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/07\\\/ceu-cursothr-hcv-14.jpg\",\"datePublished\":\"2026-07-15T09:58:14+00:00\",\"dateModified\":\"2026-07-15T10:13:38+00:00\",\"description\":\"El Hospital Cl\u00ednico Veterinario de la Universidad CEU Cardenal Herrera (HCV CEU) acoge esta semana la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera (Total Hip Replacement, THR), una formaci\u00f3n pionera que sit\u00faa a la Universidad como referente en la ense\u00f1anza de una de las t\u00e9cnicas m\u00e1s avanzadas de la cirug\u00eda ortop\u00e9dica veterinaria. Organizado junto a BlueSAO Spain, el curso re\u00fane a veterinarios procedentes de distintos pa\u00edses, tanto interesados en obtener la certificaci\u00f3n en esta t\u00e9cnica como en actualizar sus conocimientos sobre enfoques quir\u00fargicos de la mano de especialistas de reconocido prestigio internacional.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/07\\\/ceu-cursothr-hcv-14.jpg\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/07\\\/ceu-cursothr-hcv-14.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El HCV CEU acoge la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera veterinario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/e9663a691e5285e1e04660b1315d65f0\",\"name\":\"Ana Salvador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45c82f695cdd48afd056a2252ef18618d04ea35e940568d0484a72d8404ea9a2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45c82f695cdd48afd056a2252ef18618d04ea35e940568d0484a72d8404ea9a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45c82f695cdd48afd056a2252ef18618d04ea35e940568d0484a72d8404ea9a2?s=96&d=mm&r=g\",\"caption\":\"Ana Salvador\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/asalvador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El HCV CEU acoge la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera veterinario","description":"El Hospital Cl\u00ednico Veterinario de la Universidad CEU Cardenal Herrera (HCV CEU) acoge esta semana la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera (Total Hip Replacement, THR), una formaci\u00f3n pionera que sit\u00faa a la Universidad como referente en la ense\u00f1anza de una de las t\u00e9cnicas m\u00e1s avanzadas de la cirug\u00eda ortop\u00e9dica veterinaria. Organizado junto a BlueSAO Spain, el curso re\u00fane a veterinarios procedentes de distintos pa\u00edses, tanto interesados en obtener la certificaci\u00f3n en esta t\u00e9cnica como en actualizar sus conocimientos sobre enfoques quir\u00fargicos de la mano de especialistas de reconocido prestigio internacional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/","og_locale":"es_ES","og_type":"article","og_title":"El HCV CEU acoge la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera veterinario","og_description":"El Hospital Cl\u00ednico Veterinario de la Universidad CEU Cardenal Herrera (HCV CEU) acoge esta semana la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera (Total Hip Replacement, THR), una formaci\u00f3n pionera que sit\u00faa a la Universidad como referente en la ense\u00f1anza de una de las t\u00e9cnicas m\u00e1s avanzadas de la cirug\u00eda ortop\u00e9dica veterinaria. Organizado junto a BlueSAO Spain, el curso re\u00fane a veterinarios procedentes de distintos pa\u00edses, tanto interesados en obtener la certificaci\u00f3n en esta t\u00e9cnica como en actualizar sus conocimientos sobre enfoques quir\u00fargicos de la mano de especialistas de reconocido prestigio internacional.","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2026-07-15T09:58:14+00:00","article_modified_time":"2026-07-15T10:13:38+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14.jpg","type":"image\/jpeg"}],"author":"Ana Salvador","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Ana Salvador","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/"},"author":{"name":"Ana Salvador","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/e9663a691e5285e1e04660b1315d65f0"},"headline":"El HCV CEU acoge la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera veterinario","datePublished":"2026-07-15T09:58:14+00:00","dateModified":"2026-07-15T10:13:38+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/"},"wordCount":491,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14.jpg","keywords":["campus internacional","Campus Valencia","Facultad de Veterinaria","HCV CEU"],"articleSection":["Es noticia","Expertos","nota de prensa valencia","x cuadritos home","x cuadritos home"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/","name":"El HCV CEU acoge la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera veterinario","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/#primaryimage"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14.jpg","datePublished":"2026-07-15T09:58:14+00:00","dateModified":"2026-07-15T10:13:38+00:00","description":"El Hospital Cl\u00ednico Veterinario de la Universidad CEU Cardenal Herrera (HCV CEU) acoge esta semana la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera (Total Hip Replacement, THR), una formaci\u00f3n pionera que sit\u00faa a la Universidad como referente en la ense\u00f1anza de una de las t\u00e9cnicas m\u00e1s avanzadas de la cirug\u00eda ortop\u00e9dica veterinaria. Organizado junto a BlueSAO Spain, el curso re\u00fane a veterinarios procedentes de distintos pa\u00edses, tanto interesados en obtener la certificaci\u00f3n en esta t\u00e9cnica como en actualizar sus conocimientos sobre enfoques quir\u00fargicos de la mano de especialistas de reconocido prestigio internacional.","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/#primaryimage","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14.jpg","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-hcv-ceu-acoge-la-primera-edicion-en-espana-del-curso-internacional-de-certificacion-en-reemplazo-total-de-cadera-veterinario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"El HCV CEU acoge la primera edici\u00f3n en Espa\u00f1a del curso internacional de certificaci\u00f3n en reemplazo total de cadera veterinario"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/e9663a691e5285e1e04660b1315d65f0","name":"Ana Salvador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/45c82f695cdd48afd056a2252ef18618d04ea35e940568d0484a72d8404ea9a2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45c82f695cdd48afd056a2252ef18618d04ea35e940568d0484a72d8404ea9a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45c82f695cdd48afd056a2252ef18618d04ea35e940568d0484a72d8404ea9a2?s=96&d=mm&r=g","caption":"Ana Salvador"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/asalvador\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14.jpg",2048,1365,false],"thumbnail":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-150x150.jpg",150,150,true],"medium":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-300x200.jpg",300,200,true],"medium_large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-768x512.jpg",696,464,true],"large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-1060x706.jpg",696,464,true],"listado":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-310x174.jpg",310,174,true],"nuevaweb":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-280x280.jpg",280,280,true],"destacadablogs":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-580x280.jpg",580,280,true],"1536x1536":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14.jpg",2048,1365,false],"td_150x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-150x100.jpg",150,100,true],"td_218x150":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-218x150.jpg",218,150,true],"td_300x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-300x200.jpg",300,200,true],"td_324x400":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-324x400.jpg",324,400,true],"td_485x360":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-485x360.jpg",485,360,true],"td_696x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-696x464.jpg",696,464,true],"td_1068x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-1068x712.jpg",1068,712,true],"td_1920x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-1920x1280.jpg",1920,1280,true],"td_0x420":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-630x420.jpg",630,420,true],"td_80x60":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-80x60.jpg",80,60,true],"td_100x70":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-100x70.jpg",100,70,true],"td_265x198":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-265x198.jpg",265,198,true],"td_324x160":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-324x160.jpg",324,160,true],"td_324x235":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-324x235.jpg",324,235,true],"td_356x220":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-356x220.jpg",356,220,true],"td_356x364":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-356x364.jpg",356,364,true],"td_533x261":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-533x261.jpg",533,261,true],"td_534x462":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-534x462.jpg",534,462,true],"td_696x385":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-696x385.jpg",696,385,true],"td_741x486":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-741x486.jpg",741,486,true],"td_1068x580":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/07\/ceu-cursothr-hcv-14-1068x580.jpg",1068,580,true]},"uagb_author_info":{"display_name":"Ana Salvador","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/asalvador\/"},"uagb_comment_info":0,"uagb_excerpt":"Organizado junto a BlueSAO Spain, re\u00fane a formadores de referencia internacional en la cirug\u00eda ortop\u00e9dica veterinaria El vicerrector Juan Manuel Corpa y el decano Joaqu\u00edn Sopena, han inaugurado el curso junto a Mar\u00eda Marcet, en representaci\u00f3n de la empresa colaboradora El Hospital Cl\u00ednico Veterinario de la Universidad CEU Cardenal Herrera (HCV CEU) acoge esta semana&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/200088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=200088"}],"version-history":[{"count":5,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/200088\/revisions"}],"predecessor-version":[{"id":200127,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/200088\/revisions\/200127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media\/200096"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=200088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=200088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=200088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}