{"id":199523,"date":"2026-06-25T10:22:00","date_gmt":"2026-06-25T08:22:00","guid":{"rendered":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?p=199523"},"modified":"2026-06-25T18:02:11","modified_gmt":"2026-06-25T16:02:11","slug":"sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/","title":{"rendered":"Sara Landeras, Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Investigadora Ram\u00f3n y Cajal en la Universidad CEU Cardenal Herrera (CEU UCH), <a href=\"https:\/\/investigacionuch.ceu.es\/investigadores\/1874997\/detalle\" target=\"_blank\" rel=\"noreferrer noopener\">Sara Landeras<\/a> ha recibido el premio \u201cen reconocimiento a la calidad y proyecci\u00f3n de su trayectoria cient\u00edfica y a sus contribuciones en el campo de la virolog\u00eda\u201d<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1060\" height=\"707\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-1-1060x707.jpeg\" alt=\"\" class=\"wp-image-199524\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-1-1060x707.jpeg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-1-300x200.jpeg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-1-768x512.jpeg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-1-1536x1025.jpeg 1536w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-1-1200x800.jpeg 1200w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-1-150x100.jpeg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-1-696x464.jpeg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-1-1068x712.jpeg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-1-1920x1281.jpeg 1920w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-1-630x420.jpeg 630w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-1.jpeg 2048w\" sizes=\"auto, (max-width: 1060px) 100vw, 1060px\" \/><figcaption class=\"wp-element-caption\"><strong>El presidente de la Sociedad Espa\u00f1ola de Virolog\u00eda (SEV), Juan E. Echevarr\u00eda, entrega el Premio Vir\u00f3loga Junior a la profesora e investigadora de la CEU UCH Sara Landeras Bueno. <em>(FOTOS: Olivia Youssed, IPLA-CSIC, Asturias)<\/em><\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"margin-top:25px\">La <strong><a href=\"https:\/\/sevirologia.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sociedad Espa\u00f1ola de Virolog\u00eda (SEV)<\/a><\/strong> ha concedido a <strong><a href=\"https:\/\/investigacionuch.ceu.es\/investigadores\/1874997\/detalle\" target=\"_blank\" rel=\"noreferrer noopener\">Sara Landeras Bueno<\/a><\/strong>, investigadora y profesora de la Universidad CEU Cardenal Herrera (CEU UCH), el <strong>Premio Vir\u00f3loga Junior<\/strong>, entregado en el XVIII Congreso Nacional de Virolog\u00eda celebrado en C\u00e1ceres. Sara Landeras es investigadora del Programa Ram\u00f3n y Cajal en la Universidad CEU Cardenal Herrera (CEU UCH), donde lidera el <strong><a href=\"https:\/\/investigacionuch.ceu.es\/grupos\/175746\/detalle\" target=\"_blank\" rel=\"noreferrer noopener\">Laboratorio de Prevenci\u00f3n de Pandemias Virales (PrePan)<\/a><\/strong>. El Premio Vir\u00f3loga Junior de la SEV le ha sido concedido \u201cen reconocimiento a la calidad y proyecci\u00f3n de su trayectoria cient\u00edfica y a sus contribuciones en el campo de la virolog\u00eda\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/investigacionuch.ceu.es\/investigadores\/1874997\/detalle\" target=\"_blank\" rel=\"noreferrer noopener\">Sara Landeras Bueno<\/a><\/strong> ha centrado su trayectoria profesional en la biolog\u00eda molecular, la inmunolog\u00eda y la biolog\u00eda estructural de virus ARN responsables de emergencias sanitarias globales, incluyendo la gripe, el \u00c9bola y el SARS-CoV-2. Esta labor investigadora ha contribuido a mejorar el conocimiento de los mecanismos de infecci\u00f3n y de la respuesta inmunitaria frente a estos pat\u00f3genos, sentando las bases para el desarrollo de nuevas herramientas preventivas y terap\u00e9uticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El premio le ha sido entregado por el <strong>presidente de la Sociedad Espa\u00f1ola de Virolog\u00eda, Juan E. Echevarr\u00eda Mayo<\/strong>, durante el <strong><a href=\"https:\/\/www.congresovirologiacaceres2026.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">XVIII Congreso Nacional de Virolog\u00eda<\/a><\/strong>. En este encuentro cient\u00edfico, Sara Landeras ha impartido la <a href=\"https:\/\/www.congresovirologiacaceres2026.com\/programa\" target=\"_blank\" rel=\"noreferrer noopener\">conferencia<\/a> titulada \u201cPrototipos vacunales universales frente a virus respiratorios con potencial pand\u00e9mico integrando biolog\u00eda molecular, estructural e inmunolog\u00eda\u201d, en la que ha presentado los descubrimientos m\u00e1s destacados de su trayectoria, as\u00ed como las nuevas estrategias que desarrolla su equipo para anticiparse a futuras amenazas virales.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1060\" height=\"1282\" data-id=\"199536\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal1-1060x1282.jpeg\" alt=\"\" class=\"wp-image-199536\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal1-1060x1282.jpeg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal1-248x300.jpeg 248w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal1-768x929.jpeg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal1-1270x1536.jpeg 1270w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal1-992x1200.jpeg 992w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal1-150x181.jpeg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal1-300x363.jpeg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal1-696x842.jpeg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal1-1068x1292.jpeg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal1-347x420.jpeg 347w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal1.jpeg 1323w\" sizes=\"auto, (max-width: 1060px) 100vw, 1060px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1060\" height=\"1413\" data-id=\"199533\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal2-1060x1413.jpeg\" alt=\"\" class=\"wp-image-199533\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal2-1060x1413.jpeg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal2-225x300.jpeg 225w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal2-768x1024.jpeg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal2-1152x1536.jpeg 1152w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal2-900x1200.jpeg 900w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal2-150x200.jpeg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal2-300x400.jpeg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal2-696x928.jpeg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal2-1068x1424.jpeg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal2-315x420.jpeg 315w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal2.jpeg 1200w\" sizes=\"auto, (max-width: 1060px) 100vw, 1060px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"910\" height=\"1200\" data-id=\"199530\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal3.jpeg\" alt=\"\" class=\"wp-image-199530\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal3.jpeg 910w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal3-228x300.jpeg 228w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal3-768x1013.jpeg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal3-150x198.jpeg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal3-300x396.jpeg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal3-696x918.jpeg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-gal3-319x420.jpeg 319w\" sizes=\"auto, (max-width: 910px) 100vw, 910px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"margin-top:25px\"><strong>Trayectoria en Espa\u00f1a y Estados Unidos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/investigacionuch.ceu.es\/investigadores\/1874997\/detalle\" target=\"_blank\" rel=\"noreferrer noopener\">Sara Landeras Bueno<\/a><\/strong> inici\u00f3 su carrera en el Centro Nacional de Biotecnolog\u00eda (CNB-CSIC) en Madrid, estudiando la interacci\u00f3n molecular del virus de la gripe con la c\u00e9lula hospedadora. Posteriormente, en Estados Unidos investig\u00f3 el \u00e9bola y los coronavirus desde una perspectiva estructural e inmunol\u00f3gica, en dos centros de investigaci\u00f3n: The Scripps Research Institute y el Instituto de Inmunolog\u00eda La Jolla. Actualmente, es investigadora Ram\u00f3n y Cajal y profesora en la Universidad CEU Cardenal Herrera (CEU UCH).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Sara Landeras Bueno lidera en la CEU UCH el Laboratorio de Prevenci\u00f3n de Pandemias Virales, dedicado al dise\u00f1o de vacunas universales contra virus respiratorios como la gripe, el \u00c9bola y los coronavirus<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo del <strong><a href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/etiqueta\/grupo-prevencion-pandemias-prepan\/\" target=\"_blank\" rel=\"noreferrer noopener\">Grupo PrePan, que lidera en la CEU UCH<\/a><\/strong>, es contribuir a la prevenci\u00f3n de futuras pandemias causadas por un virus ARN respiratorios, desde un enfoque innovador. Mientras que las vacunas actuales se dirigen a los componentes de los virus situados en su superficie, que son los que m\u00e1s mutaciones acumulan, desde su laboratorio en la CEU UCH, Sara Landeras, trabaja en el desarrollo de <strong>terapias dirigidas a los componentes internos del virus<\/strong> que, al estar ocultos del sistema inmune, presentan una menor variabilidad, como la <a href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-publica-en-nature-communications-un-avance-clave-sobre-la-proteina-n-de-los-coronavirus\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>prote\u00edna N en el caso de los coronavirus<\/strong><\/a>. Las terapias efectivas contra estas prote\u00ednas internas no solo ayudar\u00edan a bloquear los virus conocidos, sino tambi\u00e9n aquellos que a\u00fan no han emergido, especialmente los que circulan en animales, y que podr\u00edan desencadenar futuras pandemias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sus estudios para este tipo de terapias antivirales innovadoras frente a virus con potencial pand\u00e9mico han sido <strong>publicados en destacadas revistas cient\u00edficas,<\/strong> como <em>Nature Communications, Cell Reports, Science Advances, Trends in Microbiology<\/em> o <em>Plos Pathogens.<\/em> Y cuentan con <strong>financiaci\u00f3n competitiva del Plan Estatal de Investigaci\u00f3n<\/strong> del Ministerio de Ciencia Innovaci\u00f3n y Universidades y de la Generalitat Valenciana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>M\u00e1s informaci\u00f3n sobre el Premio Vir\u00f3loga Junior SEV 2026 a Sara Landeras, <a href=\"https:\/\/sevirologia.es\/la-sev-reconoce-la-excelencia-cientifica-con-los-premios-virologo-senior-y-virologo-junior-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">en la web de la SEV<\/a>.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-rich is-provider-x wp-block-embed-x\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Terminamos cuatro intensos d\u00edas compartidos en el XVIII Congreso Nacional de Virolog\u00eda, en C\u00e1ceres, con la conferencia de Sara Landeras Bueno, ganadora del Premio Vir\u00f3loga Junior de la <a href=\"https:\/\/x.com\/hashtag\/SEV?src=hash&amp;ref_src=twsrc%5Etfw\">#SEV<\/a>.<br><br>Programa:<a href=\"https:\/\/t.co\/h6E3EHgG0m\">https:\/\/t.co\/h6E3EHgG0m<\/a> <a href=\"https:\/\/t.co\/5flgmHHeQx\">pic.twitter.com\/5flgmHHeQx<\/a><\/p>&mdash; SEV Virolog\u00eda (@sev_virologia) <a href=\"https:\/\/x.com\/sev_virologia\/status\/2068002970143240236?ref_src=twsrc%5Etfw\">June 19, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-rich is-provider-x wp-block-embed-x\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\ud83c\udfc6\ud83d\udd2cLa investigadora Ram\u00f3n y Cajal en <a href=\"https:\/\/x.com\/uchceu?ref_src=twsrc%5Etfw\">@uchceu<\/a> Sara Landeras, <a href=\"https:\/\/x.com\/hashtag\/Premio?src=hash&amp;ref_src=twsrc%5Etfw\">#Premio<\/a> Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de <a href=\"https:\/\/x.com\/hashtag\/Virolog%C3%ADa?src=hash&amp;ref_src=twsrc%5Etfw\">#Virolog\u00eda<\/a> (SEV)<br>&quot;En reconocimiento a la calidad y proyecci\u00f3n de su trayectoria cient\u00edfica y a sus contribuciones en el campo de la virolog\u00eda\u201d<a href=\"https:\/\/t.co\/BHSXx2wE9w\">https:\/\/t.co\/BHSXx2wE9w<\/a> <a href=\"https:\/\/t.co\/A02uCN76zS\">pic.twitter.com\/A02uCN76zS<\/a><\/p>&mdash; Ciencia CEU UCH (@CienciaUCHCEU) <a href=\"https:\/\/x.com\/CienciaUCHCEU\/status\/2070061477445197860?ref_src=twsrc%5Etfw\">June 25, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.x.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-sev-sociedad-espa-ola-de-virolog-a wp-block-embed-sev-sociedad-espa-ola-de-virolog-a\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"ueRrFoQHQn\"><a href=\"https:\/\/sevirologia.es\/la-sev-reconoce-la-excelencia-cientifica-con-los-premios-virologo-senior-y-virologo-junior-2026\/\">La SEV reconoce la excelencia cient\u00edfica con los Premios Vir\u00f3logo Senior y Vir\u00f3logo Junior 2026<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u00abLa SEV reconoce la excelencia cient\u00edfica con los Premios Vir\u00f3logo Senior y Vir\u00f3logo Junior 2026\u00bb \u2014 SEV |  Sociedad Espa\u00f1ola de Virolog\u00eda\" src=\"https:\/\/sevirologia.es\/la-sev-reconoce-la-excelencia-cientifica-con-los-premios-virologo-senior-y-virologo-junior-2026\/embed\/#?secret=TzZ4PTvRHE#?secret=ueRrFoQHQn\" data-secret=\"ueRrFoQHQn\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Investigadora Ram\u00f3n y Cajal en la Universidad CEU Cardenal Herrera (CEU UCH), Sara Landeras ha recibido el premio \u201cen reconocimiento a la calidad y proyecci\u00f3n de su trayectoria cient\u00edfica y a sus contribuciones en el campo de la virolog\u00eda\u201d La Sociedad Espa\u00f1ola de Virolog\u00eda (SEV) ha concedido a Sara Landeras Bueno, investigadora y profesora de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":199527,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[3,4,12,31,20,32,38,39,17,28,1089],"tags":[143,178,2177,268,2045,362],"class_list":["post-199523","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-cientifica","category-ciencias-de-la-salud-actualidad-cientifica","category-gente-ceu","category-nota-de-prensa-valencia","category-profesores-gente-ceu","category-x-profesores-home","category-x-slider-home","category-x-slider-investigacion","category-xmaquetacion","category-xnota-de-prensa","category-destacada_home1","tag-dpto-ciencias-biomedicas","tag-facultad-ciencias-de-la-salud","tag-grupo-prevencion-pandemias-prepan","tag-investigacion","tag-investigadores-ramon-y-cajal","tag-premios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sara Landeras, Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda<\/title>\n<meta name=\"description\" content=\"Sara Landeras Bueno, investigadora Ram\u00f3n y Cajal en la Universidad CEU Cardenal Herrera (CEU UCH), ha recibido el Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda (SEV) \u201cen reconocimiento a la calidad y proyecci\u00f3n de su trayectoria cient\u00edfica y a sus contribuciones en el campo de la virolog\u00eda\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sara Landeras, Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda\" \/>\n<meta property=\"og:description\" content=\"Sara Landeras Bueno, investigadora Ram\u00f3n y Cajal en la Universidad CEU Cardenal Herrera (CEU UCH), ha recibido el Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda (SEV) \u201cen reconocimiento a la calidad y proyecci\u00f3n de su trayectoria cient\u00edfica y a sus contribuciones en el campo de la virolog\u00eda\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T08:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T16:02:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1856\" \/>\n\t<meta property=\"og:image:height\" content=\"1207\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elisa Marco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa Marco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\\\/\"},\"author\":{\"name\":\"Elisa Marco\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\"},\"headline\":\"Sara Landeras, Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda\",\"datePublished\":\"2026-06-25T08:22:00+00:00\",\"dateModified\":\"2026-06-25T16:02:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\\\/\"},\"wordCount\":729,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/06\\\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg\",\"keywords\":[\"Dpto. Ciencias Biom\u00e9dicas\",\"Facultad Ciencias de la Salud\",\"Grupo Prevenci\u00f3n Pandemias PrePan\",\"Investigaci\u00f3n\",\"Investigadores Ram\u00f3n y Cajal\",\"Premios\"],\"articleSection\":[\"Actualidad Cient\u00edfica\",\"Ciencias de la Salud\",\"Gente CEU\",\"nota de prensa valencia\",\"Profesores\",\"x profesores home\",\"x slider home\",\"x slider investigacion\",\"xMaquetaci\u00f3n\",\"xNota de Prensa\",\"xPrimera noticia en home\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\\\/\",\"name\":\"Sara Landeras, Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/06\\\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg\",\"datePublished\":\"2026-06-25T08:22:00+00:00\",\"dateModified\":\"2026-06-25T16:02:11+00:00\",\"description\":\"Sara Landeras Bueno, investigadora Ram\u00f3n y Cajal en la Universidad CEU Cardenal Herrera (CEU UCH), ha recibido el Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda (SEV) \u201cen reconocimiento a la calidad y proyecci\u00f3n de su trayectoria cient\u00edfica y a sus contribuciones en el campo de la virolog\u00eda\u201d\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/06\\\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/06\\\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg\",\"width\":1856,\"height\":1207},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sara Landeras, Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\",\"name\":\"Elisa Marco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"caption\":\"Elisa Marco\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sara Landeras, Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda","description":"Sara Landeras Bueno, investigadora Ram\u00f3n y Cajal en la Universidad CEU Cardenal Herrera (CEU UCH), ha recibido el Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda (SEV) \u201cen reconocimiento a la calidad y proyecci\u00f3n de su trayectoria cient\u00edfica y a sus contribuciones en el campo de la virolog\u00eda\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/","og_locale":"es_ES","og_type":"article","og_title":"Sara Landeras, Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda","og_description":"Sara Landeras Bueno, investigadora Ram\u00f3n y Cajal en la Universidad CEU Cardenal Herrera (CEU UCH), ha recibido el Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda (SEV) \u201cen reconocimiento a la calidad y proyecci\u00f3n de su trayectoria cient\u00edfica y a sus contribuciones en el campo de la virolog\u00eda\u201d","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2026-06-25T08:22:00+00:00","article_modified_time":"2026-06-25T16:02:11+00:00","og_image":[{"width":1856,"height":1207,"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg","type":"image\/jpeg"}],"author":"Elisa Marco","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Elisa Marco","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/"},"author":{"name":"Elisa Marco","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334"},"headline":"Sara Landeras, Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda","datePublished":"2026-06-25T08:22:00+00:00","dateModified":"2026-06-25T16:02:11+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/"},"wordCount":729,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg","keywords":["Dpto. Ciencias Biom\u00e9dicas","Facultad Ciencias de la Salud","Grupo Prevenci\u00f3n Pandemias PrePan","Investigaci\u00f3n","Investigadores Ram\u00f3n y Cajal","Premios"],"articleSection":["Actualidad Cient\u00edfica","Ciencias de la Salud","Gente CEU","nota de prensa valencia","Profesores","x profesores home","x slider home","x slider investigacion","xMaquetaci\u00f3n","xNota de Prensa","xPrimera noticia en home"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/","name":"Sara Landeras, Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/#primaryimage"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg","datePublished":"2026-06-25T08:22:00+00:00","dateModified":"2026-06-25T16:02:11+00:00","description":"Sara Landeras Bueno, investigadora Ram\u00f3n y Cajal en la Universidad CEU Cardenal Herrera (CEU UCH), ha recibido el Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda (SEV) \u201cen reconocimiento a la calidad y proyecci\u00f3n de su trayectoria cient\u00edfica y a sus contribuciones en el campo de la virolog\u00eda\u201d","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/#primaryimage","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg","width":1856,"height":1207},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/sara-landeras-premio-virologa-junior-de-la-sociedad-espanola-de-virologia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"Sara Landeras, Premio Vir\u00f3loga Junior de la Sociedad Espa\u00f1ola de Virolog\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334","name":"Elisa Marco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","caption":"Elisa Marco"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg",1856,1207,false],"thumbnail":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-150x150.jpeg",150,150,true],"medium":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-300x195.jpeg",300,195,true],"medium_large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-768x499.jpeg",696,452,true],"large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-1060x689.jpeg",696,452,true],"listado":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-310x174.jpeg",310,174,true],"nuevaweb":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-280x280.jpeg",280,280,true],"destacadablogs":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-580x280.jpeg",580,280,true],"1536x1536":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-1536x999.jpeg",1536,999,true],"2048x2048":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg",1856,1207,false],"td_150x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-150x98.jpeg",150,98,true],"td_218x150":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-218x150.jpeg",218,150,true],"td_300x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-300x195.jpeg",300,195,true],"td_324x400":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-324x400.jpeg",324,400,true],"td_485x360":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-485x360.jpeg",485,360,true],"td_696x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-696x453.jpeg",696,453,true],"td_1068x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-1068x695.jpeg",1068,695,true],"td_1920x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2.jpeg",1856,1207,false],"td_0x420":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-646x420.jpeg",646,420,true],"td_80x60":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-80x60.jpeg",80,60,true],"td_100x70":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-100x70.jpeg",100,70,true],"td_265x198":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-265x198.jpeg",265,198,true],"td_324x160":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-324x160.jpeg",324,160,true],"td_324x235":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-324x235.jpeg",324,235,true],"td_356x220":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-356x220.jpeg",356,220,true],"td_356x364":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-356x364.jpeg",356,364,true],"td_533x261":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-533x261.jpeg",533,261,true],"td_534x462":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-534x462.jpeg",534,462,true],"td_696x385":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-696x385.jpeg",696,385,true],"td_741x486":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-741x486.jpeg",741,486,true],"td_1068x580":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2026\/06\/premio-virologa-junior-sev-sara-landeras-ceu-uch-2-1068x580.jpeg",1068,580,true]},"uagb_author_info":{"display_name":"Elisa Marco","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"},"uagb_comment_info":0,"uagb_excerpt":"Investigadora Ram\u00f3n y Cajal en la Universidad CEU Cardenal Herrera (CEU UCH), Sara Landeras ha recibido el premio \u201cen reconocimiento a la calidad y proyecci\u00f3n de su trayectoria cient\u00edfica y a sus contribuciones en el campo de la virolog\u00eda\u201d La Sociedad Espa\u00f1ola de Virolog\u00eda (SEV) ha concedido a Sara Landeras Bueno, investigadora y profesora de&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/199523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=199523"}],"version-history":[{"count":9,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/199523\/revisions"}],"predecessor-version":[{"id":199617,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/199523\/revisions\/199617"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media\/199527"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=199523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=199523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=199523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}