{"id":168826,"date":"2024-02-02T12:08:41","date_gmt":"2024-02-02T11:08:41","guid":{"rendered":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?p=168826"},"modified":"2025-02-28T12:02:56","modified_gmt":"2025-02-28T11:02:56","slug":"la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/","title":{"rendered":"La CEU UCH y Ford Valencia, Premio \u00c1ngel Herrera de Investigaci\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>El proyecto \u00abMiniterms 4.0\u00bb,<\/strong> <strong>que se inici\u00f3 con la primera tesis doctoral de personal de Ford dirigida por la CEU UCH y recibi\u00f3 el Henry Ford Technology Award, ya est\u00e1 implantado en las factor\u00edas de Almussafes, Cologne y Craiova, y ha sido seleccionado por los editores de la revista cient\u00edfica <em>Sensors<\/em> como una de las publicaciones de mayor impacto cient\u00edfico del a\u00f1o<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1060\" height=\"759\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-1-1-1060x759.jpg\" alt=\"Investigadores de CEU UCH y Ford, recogiendo el Premio \u00c1ngel Herrera de Investigaci\u00f3n en la CEU UCH.\n\" class=\"wp-image-168833\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-1-1-1060x759.jpg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-1-1-300x215.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-1-1-768x550.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-1-1-1536x1099.jpg 1536w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-1-1-1200x859.jpg 1200w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-1-1-150x107.jpg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-1-1-696x498.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-1-1-1068x764.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-1-1-587x420.jpg 587w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-1-1.jpg 1593w\" sizes=\"auto, (max-width: 1060px) 100vw, 1060px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"margin-top:25px\">El <strong>proyecto \u201cMiniterms 4.0\u201d<\/strong>, liderado por los doctores <strong><a href=\"https:\/\/www.uchceu.es\/directorio\/nicolas-montes\" target=\"_blank\" rel=\"noreferrer noopener\">Nicol\u00e1s Montes<\/a><\/strong>, de la Universidad CEU Cardenal Herrera (CEU UCH), y <strong>Eduardo Garc\u00eda Magraner<\/strong>, de Ford Valencia, ha obtenido el <strong>premio \u00c1ngel Herrera a la mejor labor de Investigaci\u00f3n en el \u00c1rea de Ingenier\u00eda y Arquitectura <\/strong>de las Universidades CEU en Espa\u00f1a. Esta herramienta I3oT (Industrializable Industrial Internet of Things), dise\u00f1ada por investigadores de ambas instituciones, permite monitorizar en tiempo real el deterioro de los componentes de las l\u00edneas de fabricaci\u00f3n y predecir posibles aver\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La herramienta <strong>\u201cMiniterms 4.0\u201d <\/strong>est\u00e1 monitorizando ya m\u00e1s de 36.000 equipos y m\u00e1quinas, no solo en la planta de Ford en Almussafes, sino tambi\u00e9n en las factor\u00edas de Cologne y Craiova. Seg\u00fan explica <strong>Eduardo Garc\u00eda Magraner, gerente del \u00e1rea de Ingenier\u00eda de Montaje y Bater\u00edas de Ford Valencia y doctor por la CEU UCH<\/strong>, \u201cel sistema Miniterms 4.0 puede monitorizar cualquier tipo de m\u00e1quina o componente, determinando un cambio de comportamiento en el tiempo de ciclo y enviando un aviso a los operarios de mantenimiento para que lo revisen. Con esta investigaci\u00f3n, hemos abierto un camino para seguir explorando los datos con los que las m\u00e1quinas \u201cnos hablan\u201d. El beneficio econ\u00f3mico del sistema Miniterms 4.0 se estima en un mill\u00f3n de euros por cada una de las plantas que Ford tiene en Valencia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Colaboraci\u00f3n Universidad-Empresa<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>profesor de la CEU UCH <a href=\"https:\/\/www.uchceu.es\/directorio\/nicolas-montes\" target=\"_blank\" rel=\"noreferrer noopener\">Nicol\u00e1s Montes<\/a>, investigador principal del <a href=\"https:\/\/www.uchceu.es\/grupos-lineas-investigacion\/automatizacion-industrial-y-robotica-air-industrial-automation-and-robotics-air\" target=\"_blank\" rel=\"noreferrer noopener\">Grupo en Automatizaci\u00f3n Industrial y Rob\u00f3tica (AIR)<\/a><\/strong>, destaca: \u201cEl proyecto Miniterms demuestra que la clave del \u00e9xito en los sistemas predictivos es la colaboraci\u00f3n con la industria y el uso de los sensores que ya est\u00e1n instalados en las factor\u00edas. Solo as\u00ed se pueden desarrollar herramientas verdaderamente aplicables a la industria 4.0, sin necesidad de instalar otros sensores propios y aumentar los costes. La colaboraci\u00f3n Universidad-Empresa, como la que desarrollamos entre la CEU UCH y Ford Valencia, es esencial en este sentido\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los \u00faltimos resultados del proyecto \u201cMiniterms\u201d, reconocidos con el <strong>Premio \u00c1ngel Herrera a la mejor labor de Investigaci\u00f3n en Arquitectura e Ingenier\u00eda de la Fundaci\u00f3n Universitaria San Pablo CEU<\/strong>, han sido publicados recientemente <strong><a href=\"https:\/\/www.mdpi.com\/1424-8220\/23\/14\/6569\" target=\"_blank\" rel=\"noreferrer noopener\">en la revista cient\u00edfica <em>Sensors<\/em><\/a><\/strong><em>.<\/em> La editorial internacional de esta revista, MDPI, ha seleccionado este art\u00edculo de los investigadores de Ford Valencia y la CEU UCH en su secci\u00f3n <strong>\u201cEditor&#8217;s Choice Articles\u201d<\/strong>. Esta elecci\u00f3n como publicaci\u00f3n destacada por su inter\u00e9s para el \u00e1rea de investigaci\u00f3n en el \u00faltimo a\u00f1o se basa en las recomendaciones de los <strong>editores cient\u00edficos de las revistas MDPI de todo el mundo<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1060\" height=\"706\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-1060x706.jpg\" alt=\"Equipo de investigaci\u00f3n de la CEU UCH y Ford que desarrolla el proyecto \u201cMiniterms 4.0\u201d.\n\" class=\"wp-image-168830\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-1060x706.jpg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-300x200.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-768x512.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-1536x1024.jpg 1536w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-1200x800.jpg 1200w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-150x100.jpg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-696x464.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-1068x712.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-1920x1280.jpg 1920w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-630x420.jpg 630w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg 2048w\" sizes=\"auto, (max-width: 1060px) 100vw, 1060px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"margin-top:25px\"><strong>Doctores Ford por la CEU UCH<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Junto a los <strong>doctores <a href=\"https:\/\/www.uchceu.es\/directorio\/nicolas-montes\" target=\"_blank\" rel=\"noreferrer noopener\">Nicol\u00e1s Montes S\u00e1nchez<\/a> y Eduardo Garc\u00eda Magraner<\/strong>, forman parte del equipo investigador de Ford Valencia y la CEU UCH tres doctorandos de la CEU Escuela Internacional de Doctorado (CEINDO), que preparan sus tesis doctorales en nuevas Herramientas I3oT para el proceso de estampaci\u00f3n, detecci\u00f3n de sub-cuellos de botella y rebalanceo de las l\u00edneas de fabricaci\u00f3n en tiempo real para ahorro energ\u00e9tico: <strong>Iv\u00e1n Peinado Asensi, Javier Llopis Ballester y Antonio Lacasa Corral<\/strong>. Junto a ellos, completan el equipo investigador <strong>Hilario Teruel Sempere y Manolo Segrelles<\/strong>, de Ford, y <strong>Juan Carlos Latorre Iranzo<\/strong>, como personal de apoyo a la investigaci\u00f3n de la CEU UCH destinado en Ford.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El origen del <strong>proyecto de investigaci\u00f3n \u201cMiniterms\u201d de la CEU UCH y Ford Valencia <\/strong>surgi\u00f3 de la investigaci\u00f3n para la tesis del doctor Eduardo Garc\u00eda Magraner, dirigida por el profesor Nicol\u00e1s Montes. Los desarrollos posteriores derivados de esta primera tesis, defendida en 2016, llevaron a la <strong>CEU UCH <\/strong>a convertirse en la<strong> primera Universidad espa\u00f1ola incluida en el University Research Program<\/strong> <strong>de la multinacional Ford<\/strong>, el programa de la compa\u00f1\u00eda para promover la investigaci\u00f3n con universidades de todo el mundo. Oleg Gusikhin, <em>Technical Leader<\/em> de la sede central de Ford en Dearborn, viaj\u00f3 a Valencia en 2019 para la entrega del diploma de colaboraci\u00f3n en investigaci\u00f3n con la CEU UCH, en un acto celebrado en el Palacio de Colomina-CEU.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Premiados por Ford Motor Company<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto <strong>Miniterms 4.0<\/strong> ha sido tambi\u00e9n galardonado en 2019 con el premio m\u00e1s importante que la compa\u00f1\u00eda Ford otorga a nivel mundial y que lleva el nombre de su fundador, el <strong><a href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/ford-valencia-y-la-ceu-uch-premio-henry-ford-technology-award\/\" target=\"_blank\" rel=\"noreferrer noopener\">Henry Ford Technology Award<\/a><\/strong>. Un reconocimiento a la relevancia del trabajo realizado por Ford Valencia y la UCHCEU, como la mejor propuesta presentada por sus 80 plantas y 3 centros de investigaci\u00f3n en todo el mundo, que el equipo investigador recibi\u00f3 en el Museo Henry Ford, en Dearborn (Michigan), de manos del presidente y CEO de Ford Motor Company, Jim Hackett. En 2023, el equipo de la CEU UCH y Ford Valencia recibi\u00f3 tambi\u00e9n el <strong><a href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/ceu-uch-y-ford-valencia-ganan-el-premio-technical-excellence-award-de-ford-motor-company\/\" target=\"_blank\" rel=\"noreferrer noopener\">Global Manufacturing Technical Excellence Award (GMTEA) 2023<\/a><\/strong>, que <strong>Ford Motor Company <\/strong>concede cada a\u00f1o al mejor proyecto de investigaci\u00f3n e innovaci\u00f3n de todas sus factor\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto \u00abMiniterms 4.0\u00bb, que se inici\u00f3 con la primera tesis doctoral de personal de Ford dirigida por la CEU UCH y recibi\u00f3 el Henry Ford Technology Award, ya est\u00e1 implantado en las factor\u00edas de Almussafes, Cologne y Craiova, y ha sido seleccionado por los editores de la revista cient\u00edfica Sensors como una de las [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":168830,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[3,14,31,39,17,28],"tags":[765,2115,145,173,797,258,362,488,397],"class_list":["post-168826","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-cientifica","category-ingenieria-y-arquitectura-actualidad-cientifica","category-nota-de-prensa-valencia","category-x-slider-investigacion","category-xmaquetacion","category-xnota-de-prensa","tag-ceindo","tag-ceu-uch-y-ford","tag-dpto-ciencias-fisicas-matematicas-y-de-la-computacion","tag-eset","tag-grupo-air-robotica","tag-idit","tag-premios","tag-premios-angel-herrera","tag-tesis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La CEU UCH y Ford Valencia, Premio \u00c1ngel Herrera de Investigaci\u00f3n<\/title>\n<meta name=\"description\" content=\"El proyecto &quot;Miniterms 4.0&quot;, que se inici\u00f3 con la primera tesis doctoral de personal de Ford dirigida por la CEU UCH y recibi\u00f3 el Henry Ford Technology Award, ya est\u00e1 implantado en las factor\u00edas de Almussafes, Cologne y Craiova, y ha sido seleccionado por los editores de la revista cient\u00edfica Sensors como una de las publicaciones de mayor impacto cient\u00edfico del a\u00f1o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La CEU UCH y Ford Valencia, Premio \u00c1ngel Herrera de Investigaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El proyecto &quot;Miniterms 4.0&quot;, que se inici\u00f3 con la primera tesis doctoral de personal de Ford dirigida por la CEU UCH y recibi\u00f3 el Henry Ford Technology Award, ya est\u00e1 implantado en las factor\u00edas de Almussafes, Cologne y Craiova, y ha sido seleccionado por los editores de la revista cient\u00edfica Sensors como una de las publicaciones de mayor impacto cient\u00edfico del a\u00f1o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-02T11:08:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-28T11:02:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elisa Marco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa Marco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\\\/\"},\"author\":{\"name\":\"Elisa Marco\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\"},\"headline\":\"La CEU UCH y Ford Valencia, Premio \u00c1ngel Herrera de Investigaci\u00f3n\",\"datePublished\":\"2024-02-02T11:08:41+00:00\",\"dateModified\":\"2025-02-28T11:02:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\\\/\"},\"wordCount\":917,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/02\\\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg\",\"keywords\":[\"CEINDO\",\"CEU UCH y Ford\",\"Dpto. Ciencias F\u00edsicas Matem\u00e1ticas y de la Computaci\u00f3n\",\"ESET\",\"Grupo AIR Rob\u00f3tica\",\"IDIT\",\"Premios\",\"Premios \u00c1ngel Herrera\",\"tesis\"],\"articleSection\":[\"Actualidad Cient\u00edfica\",\"Ingenier\u00eda y Arquitectura\",\"nota de prensa valencia\",\"x slider investigacion\",\"xMaquetaci\u00f3n\",\"xNota de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\\\/\",\"name\":\"La CEU UCH y Ford Valencia, Premio \u00c1ngel Herrera de Investigaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/02\\\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg\",\"datePublished\":\"2024-02-02T11:08:41+00:00\",\"dateModified\":\"2025-02-28T11:02:56+00:00\",\"description\":\"El proyecto \\\"Miniterms 4.0\\\", que se inici\u00f3 con la primera tesis doctoral de personal de Ford dirigida por la CEU UCH y recibi\u00f3 el Henry Ford Technology Award, ya est\u00e1 implantado en las factor\u00edas de Almussafes, Cologne y Craiova, y ha sido seleccionado por los editores de la revista cient\u00edfica Sensors como una de las publicaciones de mayor impacto cient\u00edfico del a\u00f1o\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/02\\\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/02\\\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La CEU UCH y Ford Valencia, Premio \u00c1ngel Herrera de Investigaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\",\"name\":\"Elisa Marco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"caption\":\"Elisa Marco\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La CEU UCH y Ford Valencia, Premio \u00c1ngel Herrera de Investigaci\u00f3n","description":"El proyecto \"Miniterms 4.0\", que se inici\u00f3 con la primera tesis doctoral de personal de Ford dirigida por la CEU UCH y recibi\u00f3 el Henry Ford Technology Award, ya est\u00e1 implantado en las factor\u00edas de Almussafes, Cologne y Craiova, y ha sido seleccionado por los editores de la revista cient\u00edfica Sensors como una de las publicaciones de mayor impacto cient\u00edfico del a\u00f1o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/","og_locale":"es_ES","og_type":"article","og_title":"La CEU UCH y Ford Valencia, Premio \u00c1ngel Herrera de Investigaci\u00f3n","og_description":"El proyecto \"Miniterms 4.0\", que se inici\u00f3 con la primera tesis doctoral de personal de Ford dirigida por la CEU UCH y recibi\u00f3 el Henry Ford Technology Award, ya est\u00e1 implantado en las factor\u00edas de Almussafes, Cologne y Craiova, y ha sido seleccionado por los editores de la revista cient\u00edfica Sensors como una de las publicaciones de mayor impacto cient\u00edfico del a\u00f1o","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2024-02-02T11:08:41+00:00","article_modified_time":"2025-02-28T11:02:56+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg","type":"image\/jpeg"}],"author":"Elisa Marco","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Elisa Marco","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/"},"author":{"name":"Elisa Marco","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334"},"headline":"La CEU UCH y Ford Valencia, Premio \u00c1ngel Herrera de Investigaci\u00f3n","datePublished":"2024-02-02T11:08:41+00:00","dateModified":"2025-02-28T11:02:56+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/"},"wordCount":917,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg","keywords":["CEINDO","CEU UCH y Ford","Dpto. Ciencias F\u00edsicas Matem\u00e1ticas y de la Computaci\u00f3n","ESET","Grupo AIR Rob\u00f3tica","IDIT","Premios","Premios \u00c1ngel Herrera","tesis"],"articleSection":["Actualidad Cient\u00edfica","Ingenier\u00eda y Arquitectura","nota de prensa valencia","x slider investigacion","xMaquetaci\u00f3n","xNota de Prensa"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/","name":"La CEU UCH y Ford Valencia, Premio \u00c1ngel Herrera de Investigaci\u00f3n","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/#primaryimage"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg","datePublished":"2024-02-02T11:08:41+00:00","dateModified":"2025-02-28T11:02:56+00:00","description":"El proyecto \"Miniterms 4.0\", que se inici\u00f3 con la primera tesis doctoral de personal de Ford dirigida por la CEU UCH y recibi\u00f3 el Henry Ford Technology Award, ya est\u00e1 implantado en las factor\u00edas de Almussafes, Cologne y Craiova, y ha sido seleccionado por los editores de la revista cient\u00edfica Sensors como una de las publicaciones de mayor impacto cient\u00edfico del a\u00f1o","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/#primaryimage","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-ford-valencia-premio-angel-herrera-de-investigacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"La CEU UCH y Ford Valencia, Premio \u00c1ngel Herrera de Investigaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334","name":"Elisa Marco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","caption":"Elisa Marco"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg",2048,1365,false],"thumbnail":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-150x150.jpg",150,150,true],"medium":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-300x200.jpg",300,200,true],"medium_large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-768x512.jpg",696,464,true],"large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-1060x706.jpg",696,464,true],"listado":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-310x174.jpg",310,174,true],"nuevaweb":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-280x280.jpg",280,280,true],"destacadablogs":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-580x280.jpg",580,280,true],"1536x1536":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2.jpg",2048,1365,false],"td_150x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-150x100.jpg",150,100,true],"td_218x150":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-218x150.jpg",218,150,true],"td_300x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-300x200.jpg",300,200,true],"td_324x400":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-324x400.jpg",324,400,true],"td_485x360":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-485x360.jpg",485,360,true],"td_696x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-696x464.jpg",696,464,true],"td_1068x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-1068x712.jpg",1068,712,true],"td_1920x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-1920x1280.jpg",1920,1280,true],"td_0x420":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-630x420.jpg",630,420,true],"td_80x60":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-80x60.jpg",80,60,true],"td_100x70":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-100x70.jpg",100,70,true],"td_265x198":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-265x198.jpg",265,198,true],"td_324x160":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-324x160.jpg",324,160,true],"td_324x235":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-324x235.jpg",324,235,true],"td_356x220":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-356x220.jpg",356,220,true],"td_356x364":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-356x364.jpg",356,364,true],"td_533x261":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-533x261.jpg",533,261,true],"td_534x462":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-534x462.jpg",534,462,true],"td_696x385":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-696x385.jpg",696,385,true],"td_741x486":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-741x486.jpg",741,486,true],"td_1068x580":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2024\/02\/premio-investigacion-angel-herrera-ford-ceu-uch-2-1068x580.jpg",1068,580,true]},"uagb_author_info":{"display_name":"Elisa Marco","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"},"uagb_comment_info":0,"uagb_excerpt":"El proyecto \u00abMiniterms 4.0\u00bb, que se inici\u00f3 con la primera tesis doctoral de personal de Ford dirigida por la CEU UCH y recibi\u00f3 el Henry Ford Technology Award, ya est\u00e1 implantado en las factor\u00edas de Almussafes, Cologne y Craiova, y ha sido seleccionado por los editores de la revista cient\u00edfica Sensors como una de las&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/168826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=168826"}],"version-history":[{"count":1,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/168826\/revisions"}],"predecessor-version":[{"id":168836,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/168826\/revisions\/168836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media\/168830"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=168826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=168826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=168826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}