{"id":166567,"date":"2023-11-14T10:28:25","date_gmt":"2023-11-14T09:28:25","guid":{"rendered":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?p=166567"},"modified":"2023-12-19T20:05:42","modified_gmt":"2023-12-19T19:05:42","slug":"el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/","title":{"rendered":"El investigador Jordi Renau y la diputada por Castell\u00f3n Candela Angl\u00e9s inician su colaboraci\u00f3n en el programa de \u00abCiencia en el Parlamento\u00bb en la CV"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>El \u201cScience Meets Regions Comunitat Valenciana 2023\u201d, liderado por la <a href=\"https:\/\/cienciaenelparlamento.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Asociaci\u00f3n Ciencia en el Parlamento (CeeP)<\/a>, se dedica a la transici\u00f3n verde y la sosteniblidad, con la colaboraci\u00f3n de <a href=\"https:\/\/urldefense.com\/v3\/__https:\/ruvid.org\/__;!!D9dNQwwGXtA!WB6b-6w8LxwOqry82MgCWzZQEmColSZvDoDKLsa45nHBam2hw4iY8k1m-Eu_txo69pBuIIBAlzZ4N61_6kpf3Q-6jg$\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>RUVID<\/strong><\/a> y la financiaci\u00f3n del <a href=\"https:\/\/commission.europa.eu\/about-european-commission\/departments-and-executive-agencies\/joint-research-centre_en\" target=\"_blank\" rel=\"noreferrer noopener\">Joint Research Center (JRC) <\/a>de la Comisi\u00f3n Europea<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa <strong>\u201cScience Meets Regions Comunitat Valenciana 2023\u201d (SMR-Valencia)<\/strong>, liderado por la <strong><a href=\"https:\/\/cienciaenelparlamento.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Asociaci\u00f3n Ciencia en el Parlamento (CeeP)<\/a><\/strong>, ha hecho p\u00fablicos hoy los emparejamientos entre los 12 cient\u00edficos y los 14 pol\u00edticos de la Comunidad Valenciana que participan en esta iniciativa, con el objetivo de dise\u00f1ar un futuro energ\u00e9tico m\u00e1s sostenible. Por parte de la Universidad CEU Cardenal Herrera (CEU UCH) participa en este programa el investigador <strong>experto en hidr\u00f3geno verde, <strong><a href=\"https:\/\/www.uchceu.es\/directorio\/jordi-renau\" target=\"_blank\" rel=\"noreferrer noopener\">Jordi Renau Mart\u00ednez<\/a><\/strong><\/strong>, que trabajar\u00e1 con <strong>Candela Angl\u00e9s, diputada por Castell\u00f3n en <a href=\"https:\/\/www.cortsvalencianes.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les Corts Valencianes<\/a> y concejal del <a href=\"https:\/\/www.calig.es\/es\" target=\"_blank\" rel=\"noreferrer noopener\">Ayuntamiento de C\u00e0lig<\/a><\/strong>. Este programa de colaboraci\u00f3n entre ciencia y pol\u00edtica se orienta a que los investigadores puedan conocer mejor el funcionamiento de la administraci\u00f3n local y regional y a que los pol\u00edticos identifiquen el potencial de la ciencia para su <strong>asesoramiento<\/strong>, en este caso, en materia de <strong>transici\u00f3n verde y sostenibilida<\/strong>d.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1060\" height=\"860\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2021\/01\/jordi-renau-ceu-uch-hidrogeno-1-1060x860.jpg\" alt=\"Jordi Renau, profesor de la ESET e investigador del Grupo TecEner de la CEU UCH.\" class=\"wp-image-113695\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2021\/01\/jordi-renau-ceu-uch-hidrogeno-1-1060x860.jpg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2021\/01\/jordi-renau-ceu-uch-hidrogeno-1-300x243.jpg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2021\/01\/jordi-renau-ceu-uch-hidrogeno-1-768x623.jpg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2021\/01\/jordi-renau-ceu-uch-hidrogeno-1-1536x1246.jpg 1536w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2021\/01\/jordi-renau-ceu-uch-hidrogeno-1-2048x1661.jpg 2048w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2021\/01\/jordi-renau-ceu-uch-hidrogeno-1-1200x974.jpg 1200w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2021\/01\/jordi-renau-ceu-uch-hidrogeno-1-150x122.jpg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2021\/01\/jordi-renau-ceu-uch-hidrogeno-1-696x565.jpg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2021\/01\/jordi-renau-ceu-uch-hidrogeno-1-1068x866.jpg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2021\/01\/jordi-renau-ceu-uch-hidrogeno-1-1920x1558.jpg 1920w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2021\/01\/jordi-renau-ceu-uch-hidrogeno-1-518x420.jpg 518w\" sizes=\"auto, (max-width: 1060px) 100vw, 1060px\" \/><figcaption class=\"wp-element-caption\">Jordi Renau, profesor de la ESET e investigador del Grupo TecEner de la CEU UCH, participa en el programa de Ciencia en el Parlamento en la CV.<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"wp-block-paragraph\">El profesor <strong><strong><a href=\"https:\/\/www.uchceu.es\/directorio\/jordi-renau\" target=\"_blank\" rel=\"noreferrer noopener\">Jordi Renau Mart\u00ednez<\/a><\/strong><\/strong> es miembro del <a href=\"https:\/\/www.uchceu.es\/grupos-lineas-investigacion\/grupo-de-investigacion-y-desarrollo-de-tecnologias-en-aplicaciones-energeticas-tecener\" target=\"_blank\" rel=\"noreferrer noopener\">Grupo de Investigaci\u00f3n y Desarrollo de Tecnolog\u00edas en Aplicaciones Energ\u00e9ticas (TecEner)<\/a> de la CEU UCH. Con una amplia trayectoria investigadora en el \u00e1mbito de la producci\u00f3n y almacenamiento de <strong>hidr\u00f3geno verde<\/strong>, ha liderado y formado parte de varios proyectos de desarrollo de tecnolog\u00edas de aplicaci\u00f3n de hidr\u00f3geno en viviendas, en sistemas de potencia h\u00edbridos para veh\u00edculos no tripulados y en infraestructuras de producci\u00f3n en pymes de este tipo de hidr\u00f3geno, producido con energ\u00edas renovables. En estas pr\u00f3ximas semanas, el profesor Jordi Renau iniciar\u00e1 la colaboraci\u00f3n con la diputada por Castell\u00f3n en <a href=\"https:\/\/www.cortsvalencianes.es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les Corts<\/a> y concejal del <a href=\"https:\/\/www.calig.es\/es\" target=\"_blank\" rel=\"noreferrer noopener\">Ayuntamiento de C\u00e0lig<\/a>, Candela Angl\u00e9s, para <strong>trasladar su experiencia investigadora a los \u00e1mbitos local y auton\u00f3mico<\/strong>.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ciencia y Parlamento, en la CV<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>programa \u201cScience Meets Regions Comunitat Valenciana 2023\u201d<\/strong> para la colaboraci\u00f3n entre cient\u00edficos y pol\u00edticos impulsado por <strong><a href=\"https:\/\/cienciaenelparlamento.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">CeeP<\/a><\/strong>, se realiza en la Comunidad Valenciana en colaboraci\u00f3n con la Red de Universidades Valencianas para el fomento de la Investigaci\u00f3n, el Desarrollo y la Innovaci\u00f3n (<strong><a href=\"https:\/\/urldefense.com\/v3\/__https:\/ruvid.org\/__;!!D9dNQwwGXtA!WB6b-6w8LxwOqry82MgCWzZQEmColSZvDoDKLsa45nHBam2hw4iY8k1m-Eu_txo69pBuIIBAlzZ4N61_6kpf3Q-6jg$\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>RUVID<\/strong><\/a><\/strong>), con financiaci\u00f3n del <a href=\"https:\/\/commission.europa.eu\/about-european-commission\/departments-and-executive-agencies\/joint-research-centre_en\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Joint Research Center (JRC) de la Comisi\u00f3n Europea<\/strong><\/a>. En total, participan en esta iniciativa <strong>12 cient\u00edficos<\/strong> de siete universidades, una empresa y un centro de investigaci\u00f3n de la Comunidad, y <strong>14 cargos electos<\/strong>: alcaldes y concejales de siete ayuntamientos y diputados de las tres provincias en Les Corts Valencianes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los <strong>cient\u00edficos participantes <\/strong>son dos investigadores de la Universitat Jaume I de Castell\u00f3n, dos de la Universitat de Val\u00e8ncia, dos de la Universidad Miguel Hern\u00e1ndez de Elche, una de la Universidad de Alicante, uno de la Universidad CEU Cardenal Herrera, una de la Universidad Cat\u00f3lica de Valencia, uno de la Universidad Polit\u00e9cnica de Valencia, una del Instituto de investigaci\u00f3n INGENIO (CSIC-UPV) y otro de la empresa ProtoQSAR . Son 6 hombres y 6 mujeres expertos en agua, pl\u00e1sticos sostenibles, pilas y energ\u00edas verdes, transporte sostenible, arquitectura y reconstrucci\u00f3n urban\u00edstica verde, por citar algunas de las tem\u00e1ticas de sus investigaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de los <strong>pol\u00edticos<\/strong>, son los alcaldes y alcaldesas de los municipios de Almussafes, Alzira, Onda, Riba-Roja y Sagunto; cuatro concejales y concejalas de los municipios de Benidorm, C\u00e0lig y Sagunto; y siete diputados y diputada, tres por Valencia, tres por Alicante y una por Castell\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LISTADO COMPLETO de los 12 emparejamientos del SMR-Valencia 2023:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-ciencia-en-el-parlamento wp-block-embed-ciencia-en-el-parlamento\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"GTWUDnXCAY\"><a href=\"https:\/\/cienciaenelparlamento.org\/12-cientificos-y-14-politicos-las-caras-del-programa-de-emparejamiento-science-meets-regions-comunitat-valenciana-2023\/\">12 cient\u00edficos y 14 pol\u00edticos: las caras del programa de emparejamiento \u201cScience Meets Regions Comunitat Valenciana 2023\u201d<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#171;12 cient\u00edficos y 14 pol\u00edticos: las caras del programa de emparejamiento \u201cScience Meets Regions Comunitat Valenciana 2023\u201d&#187; &#8212; Ciencia en el parlamento\" src=\"https:\/\/cienciaenelparlamento.org\/12-cientificos-y-14-politicos-las-caras-del-programa-de-emparejamiento-science-meets-regions-comunitat-valenciana-2023\/embed\/#?secret=GTWUDnXCAY\" data-secret=\"GTWUDnXCAY\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">1.- Luis Cabedo, de la Universitat Jaume I de Castell\u00f3n (UJI), trabajar\u00e1 con tres personas del Ayuntamiento de Sagunto: su alcalde, Dar\u00edo Moreno, y el concejal de Universidad, Ciencia e Innovaci\u00f3n, Toni Iborra, ambos del PSPV-PSOE, as\u00ed como la concejala Maria Josep Pic\u00f3, de Comprom\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2.- Laureano E. Carpio, de la empresa ProtoQSAR, trabajar\u00e1 con Isaura Navarro, diputada del grupo parlamentario de Comprom\u00eds por Valencia en Les Corts Valencianes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.- Sergio Chiva, tambi\u00e9n de la Universitat Jaume I de Castell\u00f3n (UJI), trabajar\u00e1 con Carmina Ballester, alcaldesa del Ayuntamiento de Onda y miembro del PP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4.- Esther Moreno, de la Universidad Cat\u00f3lica de Valencia (UCV), trabajar\u00e1 con Paula Espinosa, diputada del grupo parlamentario de Comprom\u00eds por Valencia en Les Corts Valencianes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.- Herminia Puerto, de la Universidad Miguel Hern\u00e1ndez de Elche (UMH), trabajar\u00e1 con Jos\u00e9 For\u00e9s, diputado del grupo parlamentario del PP por Alicante en Les Corts Valencianes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">6.- Jordi Renau, de la Universidad CEU Cardenal Herrera (UCHCEU), trabajar\u00e1 con Candela Angl\u00e9s diputada del grupo parlamentario del PP por Castell\u00f3n en Les Corts Valencianes y concejal del Ayuntamiento de C\u00e0lig.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">7.- Josep Ribes, de la Universitat de Val\u00e8ncia (UV), trabajar\u00e1 con Alfons Dom\u00ednguez, alcalde de Alzira y miembro de Comprom\u00eds per Alzira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8.- Esther Roca, tambi\u00e9n de la Universitat de Val\u00e8ncia (UV), trabajar\u00e1 con Robert Raga, alcalde de Riba-roja y miembro del PSPV-PSOE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">9.- Carolina Senabre, de la Universidad Miguel Hern\u00e1ndez de Elche (UMH), trabajar\u00e1 con Ram\u00f3n Abad, diputado del grupo parlamentario PSPV-PSOE por Alicante en Les Corts Valencianes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">10.- Jos\u00e9 Ram\u00f3n Serrano, de la Universitat Polit\u00e8cnica de Val\u00e8ncia (UPV), trabajar\u00e1 con David Bernardo L\u00f3pez, diputado del grupo parlamentario PSPV-PSOE por Valencia en Les Corts Valencianes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11.- Silvia Spairani, de la Universidad de Alicante (UA), trabajar\u00e1 con Jos\u00e9 Ram\u00f3n Gonz\u00e1lez de Z\u00e1rate, diputado del grupo parlamentario del PP por Alicante en Les Corts Valencianes y concejal del Ayuntamiento de Benidorm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">12.- Oksana Udovyk, del instituto de investigaci\u00f3n INGENIO (CSIC-UPV), trabajar\u00e1 con Antonio Gonz\u00e1lez, alcalde de Almussafes y miembro del PSPV-PSOE.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-actualidad-ceu wp-block-embed-actualidad-ceu\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"FvFM3E5Wju\"><a href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/\">Jordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abJordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana\u00bb \u2014 Actualidad CEU\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/embed\/#?secret=k94pehrxwL#?secret=FvFM3E5Wju\" data-secret=\"FvFM3E5Wju\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-actualidad-ceu wp-block-embed-actualidad-ceu\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"hy25SHt7ZD\"><a href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-de-la-ceu-uch-desarrollan-un-sistema-alimentado-por-hidrogeno-verde-para-la-cogeneracion-de-electricidad-y-calor-en-hogares\/\">Investigadores de la CEU UCH desarrollan un sistema alimentado por hidr\u00f3geno \u201cverde\u201d para la cogeneraci\u00f3n de electricidad y calor en hogares<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abInvestigadores de la CEU UCH desarrollan un sistema alimentado por hidr\u00f3geno \u201cverde\u201d para la cogeneraci\u00f3n de electricidad y calor en hogares\u00bb \u2014 Actualidad CEU\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-de-la-ceu-uch-desarrollan-un-sistema-alimentado-por-hidrogeno-verde-para-la-cogeneracion-de-electricidad-y-calor-en-hogares\/embed\/#?secret=0d51IS8yz3#?secret=hy25SHt7ZD\" data-secret=\"hy25SHt7ZD\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El \u201cScience Meets Regions Comunitat Valenciana 2023\u201d, liderado por la Asociaci\u00f3n Ciencia en el Parlamento (CeeP), se dedica a la transici\u00f3n verde y la sosteniblidad, con la colaboraci\u00f3n de RUVID y la financiaci\u00f3n del Joint Research Center (JRC) de la Comisi\u00f3n Europea El programa \u201cScience Meets Regions Comunitat Valenciana 2023\u201d (SMR-Valencia), liderado por la Asociaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":157539,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[3,6,18,39,17,1089],"tags":[145,173,250,258,268,331],"class_list":["post-166567","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-cientifica","category-comunidad-investigadora","category-medio-ambiente-actualidad-cientifica","category-x-slider-investigacion","category-xmaquetacion","category-destacada_home1","tag-dpto-ciencias-fisicas-matematicas-y-de-la-computacion","tag-eset","tag-grupo-tec-ener","tag-idit","tag-investigacion","tag-medio-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El investigador Jordi Renau y la diputada por Castell\u00f3n Candela Angl\u00e9s inician su colaboraci\u00f3n en el programa de &quot;Ciencia en el Parlamento&quot; en la CV<\/title>\n<meta name=\"description\" content=\"El \u201cScience Meets Regions Comunitat Valenciana 2023\u201d, liderado por la Asociaci\u00f3n Ciencia en el Parlamento (CeeP), se dedica a la transici\u00f3n verde y la sosteniblidad, con la colaboraci\u00f3n de RUVID y la financiaci\u00f3n del Joint Research Center (JRC) de la Comisi\u00f3n Europea\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El investigador Jordi Renau y la diputada por Castell\u00f3n Candela Angl\u00e9s inician su colaboraci\u00f3n en el programa de &quot;Ciencia en el Parlamento&quot; en la CV\" \/>\n<meta property=\"og:description\" content=\"El \u201cScience Meets Regions Comunitat Valenciana 2023\u201d, liderado por la Asociaci\u00f3n Ciencia en el Parlamento (CeeP), se dedica a la transici\u00f3n verde y la sosteniblidad, con la colaboraci\u00f3n de RUVID y la financiaci\u00f3n del Joint Research Center (JRC) de la Comisi\u00f3n Europea\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-14T09:28:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-19T19:05:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elisa Marco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa Marco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\\\/\"},\"author\":{\"name\":\"Elisa Marco\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\"},\"headline\":\"El investigador Jordi Renau y la diputada por Castell\u00f3n Candela Angl\u00e9s inician su colaboraci\u00f3n en el programa de \u00abCiencia en el Parlamento\u00bb en la CV\",\"datePublished\":\"2023-11-14T09:28:25+00:00\",\"dateModified\":\"2023-12-19T19:05:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\\\/\"},\"wordCount\":1047,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/jordi-renau-martinez-ceu-uch-2-scaled.jpeg\",\"keywords\":[\"Dpto. Ciencias F\u00edsicas Matem\u00e1ticas y de la Computaci\u00f3n\",\"ESET\",\"Grupo TEC-ENER\",\"IDIT\",\"Investigaci\u00f3n\",\"medio ambiente\"],\"articleSection\":[\"Actualidad Cient\u00edfica\",\"Comunidad Investigadora\",\"Medio Ambiente\",\"x slider investigacion\",\"xMaquetaci\u00f3n\",\"xPrimera noticia en home\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\\\/\",\"name\":\"El investigador Jordi Renau y la diputada por Castell\u00f3n Candela Angl\u00e9s inician su colaboraci\u00f3n en el programa de \\\"Ciencia en el Parlamento\\\" en la CV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/jordi-renau-martinez-ceu-uch-2-scaled.jpeg\",\"datePublished\":\"2023-11-14T09:28:25+00:00\",\"dateModified\":\"2023-12-19T19:05:42+00:00\",\"description\":\"El \u201cScience Meets Regions Comunitat Valenciana 2023\u201d, liderado por la Asociaci\u00f3n Ciencia en el Parlamento (CeeP), se dedica a la transici\u00f3n verde y la sosteniblidad, con la colaboraci\u00f3n de RUVID y la financiaci\u00f3n del Joint Research Center (JRC) de la Comisi\u00f3n Europea\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/jordi-renau-martinez-ceu-uch-2-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/jordi-renau-martinez-ceu-uch-2-scaled.jpeg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El investigador Jordi Renau y la diputada por Castell\u00f3n Candela Angl\u00e9s inician su colaboraci\u00f3n en el programa de \u00abCiencia en el Parlamento\u00bb en la CV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\",\"name\":\"Elisa Marco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"caption\":\"Elisa Marco\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El investigador Jordi Renau y la diputada por Castell\u00f3n Candela Angl\u00e9s inician su colaboraci\u00f3n en el programa de \"Ciencia en el Parlamento\" en la CV","description":"El \u201cScience Meets Regions Comunitat Valenciana 2023\u201d, liderado por la Asociaci\u00f3n Ciencia en el Parlamento (CeeP), se dedica a la transici\u00f3n verde y la sosteniblidad, con la colaboraci\u00f3n de RUVID y la financiaci\u00f3n del Joint Research Center (JRC) de la Comisi\u00f3n Europea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/","og_locale":"es_ES","og_type":"article","og_title":"El investigador Jordi Renau y la diputada por Castell\u00f3n Candela Angl\u00e9s inician su colaboraci\u00f3n en el programa de \"Ciencia en el Parlamento\" en la CV","og_description":"El \u201cScience Meets Regions Comunitat Valenciana 2023\u201d, liderado por la Asociaci\u00f3n Ciencia en el Parlamento (CeeP), se dedica a la transici\u00f3n verde y la sosteniblidad, con la colaboraci\u00f3n de RUVID y la financiaci\u00f3n del Joint Research Center (JRC) de la Comisi\u00f3n Europea","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2023-11-14T09:28:25+00:00","article_modified_time":"2023-12-19T19:05:42+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-scaled.jpeg","type":"image\/jpeg"}],"author":"Elisa Marco","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Elisa Marco","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/"},"author":{"name":"Elisa Marco","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334"},"headline":"El investigador Jordi Renau y la diputada por Castell\u00f3n Candela Angl\u00e9s inician su colaboraci\u00f3n en el programa de \u00abCiencia en el Parlamento\u00bb en la CV","datePublished":"2023-11-14T09:28:25+00:00","dateModified":"2023-12-19T19:05:42+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/"},"wordCount":1047,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-scaled.jpeg","keywords":["Dpto. Ciencias F\u00edsicas Matem\u00e1ticas y de la Computaci\u00f3n","ESET","Grupo TEC-ENER","IDIT","Investigaci\u00f3n","medio ambiente"],"articleSection":["Actualidad Cient\u00edfica","Comunidad Investigadora","Medio Ambiente","x slider investigacion","xMaquetaci\u00f3n","xPrimera noticia en home"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/","name":"El investigador Jordi Renau y la diputada por Castell\u00f3n Candela Angl\u00e9s inician su colaboraci\u00f3n en el programa de \"Ciencia en el Parlamento\" en la CV","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/#primaryimage"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-scaled.jpeg","datePublished":"2023-11-14T09:28:25+00:00","dateModified":"2023-12-19T19:05:42+00:00","description":"El \u201cScience Meets Regions Comunitat Valenciana 2023\u201d, liderado por la Asociaci\u00f3n Ciencia en el Parlamento (CeeP), se dedica a la transici\u00f3n verde y la sosteniblidad, con la colaboraci\u00f3n de RUVID y la financiaci\u00f3n del Joint Research Center (JRC) de la Comisi\u00f3n Europea","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/#primaryimage","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-scaled.jpeg","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-scaled.jpeg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/el-investigador-jordi-renau-y-la-diputada-por-castellon-candela-angles-inician-su-colaboracion-en-el-programa-de-ciencia-en-el-parlamento-en-la-cv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"El investigador Jordi Renau y la diputada por Castell\u00f3n Candela Angl\u00e9s inician su colaboraci\u00f3n en el programa de \u00abCiencia en el Parlamento\u00bb en la CV"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334","name":"Elisa Marco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","caption":"Elisa Marco"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-scaled.jpeg",2560,1920,false],"thumbnail":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-150x150.jpeg",150,150,true],"medium":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-300x225.jpeg",300,225,true],"medium_large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-768x576.jpeg",696,522,true],"large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-1060x795.jpeg",696,522,true],"listado":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-310x174.jpeg",310,174,true],"nuevaweb":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-280x280.jpeg",280,280,true],"destacadablogs":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-580x280.jpeg",580,280,true],"1536x1536":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-1536x1152.jpeg",1536,1152,true],"2048x2048":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-2048x1536.jpeg",2048,1536,true],"td_150x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-150x113.jpeg",150,113,true],"td_218x150":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-218x150.jpeg",218,150,true],"td_300x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-300x225.jpeg",300,225,true],"td_324x400":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-324x400.jpeg",324,400,true],"td_485x360":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-485x360.jpeg",485,360,true],"td_696x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-696x522.jpeg",696,522,true],"td_1068x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-1068x801.jpeg",1068,801,true],"td_1920x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-1920x1440.jpeg",1920,1440,true],"td_0x420":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-560x420.jpeg",560,420,true],"td_80x60":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-80x60.jpeg",80,60,true],"td_100x70":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-100x70.jpeg",100,70,true],"td_265x198":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-265x198.jpeg",265,198,true],"td_324x160":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-324x160.jpeg",324,160,true],"td_324x235":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-324x235.jpeg",324,235,true],"td_356x220":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-356x220.jpeg",356,220,true],"td_356x364":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-356x364.jpeg",356,364,true],"td_533x261":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-533x261.jpeg",533,261,true],"td_534x462":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-534x462.jpeg",534,462,true],"td_696x385":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-696x385.jpeg",696,385,true],"td_741x486":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-741x486.jpeg",741,486,true],"td_1068x580":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-1068x580.jpeg",1068,580,true]},"uagb_author_info":{"display_name":"Elisa Marco","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"},"uagb_comment_info":0,"uagb_excerpt":"El \u201cScience Meets Regions Comunitat Valenciana 2023\u201d, liderado por la Asociaci\u00f3n Ciencia en el Parlamento (CeeP), se dedica a la transici\u00f3n verde y la sosteniblidad, con la colaboraci\u00f3n de RUVID y la financiaci\u00f3n del Joint Research Center (JRC) de la Comisi\u00f3n Europea El programa \u201cScience Meets Regions Comunitat Valenciana 2023\u201d (SMR-Valencia), liderado por la Asociaci\u00f3n&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/166567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=166567"}],"version-history":[{"count":5,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/166567\/revisions"}],"predecessor-version":[{"id":166573,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/166567\/revisions\/166573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media\/157539"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=166567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=166567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=166567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}