{"id":157538,"date":"2023-03-21T11:49:23","date_gmt":"2023-03-21T10:49:23","guid":{"rendered":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?p=157538"},"modified":"2023-03-27T10:08:51","modified_gmt":"2023-03-27T08:08:51","slug":"jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana","status":"publish","type":"post","link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/","title":{"rendered":"Jordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Con una amplia trayectoria investigadora sobre producci\u00f3n y almacenamiento de hidr\u00f3geno verde, el profesor <a href=\"https:\/\/www.uchceu.es\/directorio\/jordi-renau\" target=\"_blank\" rel=\"noreferrer noopener\">Jordi Renau<\/a> forma parte de los doce candidatos seleccionados para este emparejamiento ciencia-pol\u00edtica en la CV, que forma parte del programa Science Meets Regions del Joint Research Center (JRC) de la Comisi\u00f3n Europea<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1060\" height=\"795\" src=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-1060x795.jpeg\" alt=\"\" class=\"wp-image-157539\" srcset=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-1060x795.jpeg 1060w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-300x225.jpeg 300w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-768x576.jpeg 768w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-1536x1152.jpeg 1536w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-2048x1536.jpeg 2048w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-1200x900.jpeg 1200w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-150x113.jpeg 150w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-696x522.jpeg 696w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-1068x801.jpeg 1068w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-1920x1440.jpeg 1920w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-560x420.jpeg 560w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-80x60.jpeg 80w, https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2-265x198.jpeg 265w\" sizes=\"auto, (max-width: 1060px) 100vw, 1060px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La asociaci\u00f3n de \u00e1mbito estatal <a href=\"https:\/\/urldefense.com\/v3\/__https:\/cienciaenelparlamento.org\/__;!!D9dNQwwGXtA!WB6b-6w8LxwOqry82MgCWzZQEmColSZvDoDKLsa45nHBam2hw4iY8k1m-Eu_txo69pBuIIBAlzZ4N61_6kpAGV43Hw$\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Ciencia en el Parlamento<\/strong><\/a> (CeeP), en colaboraci\u00f3n con <a href=\"https:\/\/urldefense.com\/v3\/__https:\/ruvid.org\/__;!!D9dNQwwGXtA!WB6b-6w8LxwOqry82MgCWzZQEmColSZvDoDKLsa45nHBam2hw4iY8k1m-Eu_txo69pBuIIBAlzZ4N61_6kpf3Q-6jg$\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>RUVID<\/strong><\/a> (Red de Universidades Valencianas para el fomento de la Investigaci\u00f3n, el Desarrollo y la Innovaci\u00f3n) en la Comunidad Valenciana, han presentado los doce perfiles de investigaci\u00f3n que participar\u00e1n en el <strong>programa de emparejamiento <em>Science Meets Regions Comunitat Valenciana 2023: Transici\u00f3n verde y sostenibilidad<\/em><\/strong>. Y uno de ellos es <strong>Jordi Renau Mart\u00ednez<\/strong>, profesor adjunto del Departamento de Matem\u00e1ticas, F\u00edsica y Ciencias Tecnol\u00f3gicas de la Universidad CEU Cardenal Herrera (CEU UCH) y miembro del <a href=\"https:\/\/www.uchceu.es\/grupos-lineas-investigacion\/grupo-de-investigacion-y-desarrollo-de-tecnologias-en-aplicaciones-energeticas-tecener\" target=\"_blank\" rel=\"noreferrer noopener\">Grupo de Investigaci\u00f3n y Desarrollo de Tecnolog\u00edas en Aplicaciones Energ\u00e9ticas (TecEner)<\/a>. Su <strong>trayectoria investigadora sobre producci\u00f3n y almacenamiento de hidr\u00f3geno verde<\/strong> ha sido clave para convertirse en <strong>uno de los doce candidatos seleccionados<\/strong> para este programa, dedicado a la transici\u00f3n verde y la sostenibilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auspiciado por el Joint Research Center, la <strong>iniciativa europea Science Meets Regions<\/strong> tiene como objetivo <strong>acercar las comunidades cient\u00edfica y pol\u00edtica<\/strong> para fomentar colaboraciones tangibles, efectivas y sostenibles a lo largo del tiempo y as\u00ed avanzar en los retos que plantea la transici\u00f3n verde en la regi\u00f3n. La Comunidad Valenciana es la primera Comunidad Aut\u00f3noma espa\u00f1ola en la que se desarrollar\u00e1 este programa que, en 2022, se llev\u00f3 a cabo a nivel nacional con unos resultados muy satisfactorios. Explicar a los dirigentes pol\u00edticos c\u00f3mo se desarrolla la ciencia en su territorio y cu\u00e1les son los interlocutores ideales para la tem\u00e1tica de especializaci\u00f3n (en este caso, Transici\u00f3n verde y Sostenibilidad) que les pueden <strong>ayudar a la toma de decisiones para resolver problemas de \u00edndole t\u00e9cnico-cient\u00edfica <\/strong>ser\u00e1 una de las claves del cometido para el que se han presentado m\u00e1s de medio centenar de candidatos tras el llamamiento a la participaci\u00f3n en el <strong>primer Programa de Emparejamiento <em>Science Meets Regions<\/em> en la Comunitat Valenciana<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un experto en hidr\u00f3geno verde, candidato de la CEU UCH<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los seleccionados para este programa de emparejamiento entre cient\u00edficos y pol\u00edticos est\u00e1 el doctor ingeniero industrial por la Universidad CEU Cardenal Herrera, (CEU UCH) <strong><a href=\"https:\/\/www.uchceu.es\/directorio\/jordi-renau\" target=\"_blank\" rel=\"noreferrer noopener\">Jordi Renau Mart\u00ednez<\/a><\/strong>, profesor adjunto del Departamento de Matem\u00e1ticas, F\u00edsica y Ciencias Tecnol\u00f3gicas de la CEU UCH y miembro del <a href=\"https:\/\/www.uchceu.es\/grupos-lineas-investigacion\/grupo-de-investigacion-y-desarrollo-de-tecnologias-en-aplicaciones-energeticas-tecener\" target=\"_blank\" rel=\"noreferrer noopener\">Grupo de Investigaci\u00f3n y Desarrollo de Tecnolog\u00edas en Aplicaciones Energ\u00e9ticas (TecEner)<\/a>. Ya en su <a href=\"https:\/\/repositorioinstitucional.ceu.es\/handle\/10637\/8587\" target=\"_blank\" rel=\"noreferrer noopener\">tesis doctoral<\/a>, el profesor Renau desarroll\u00f3 una <a href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/aviones-no-tripulados-investigadores-de-la-ceu-uch-colaboran-en-el-desarrollo-una-pila-de-combustible-de-hidrogeno-ultraligera-para-mejorar-su-eficiencia\/\" target=\"_blank\" rel=\"noreferrer noopener\">planta de potencia de hidr\u00f3geno para aviones no tripulados<\/a>, como parte del proyecto competitivo liderado por el LIFTEC-CSIC de Zaragoza, con tecnolog\u00eda de la empresa aeron\u00e1utica alicantina Medavia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El resultado de esta colaboraci\u00f3n condujo a la creaci\u00f3n del <a href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/investigadores-de-la-ceu-uch-desarrollan-un-sistema-alimentado-por-hidrogeno-verde-para-la-cogeneracion-de-electricidad-y-calor-en-hogares\/\" target=\"_blank\" rel=\"noreferrer noopener\">consorcio investigador formado por la CEU UCH, el LIFTEC-CSIC y el IRI-CSIC (Barcelona)<\/a>, para el desarrollo de tecnolog\u00edas de aplicaci\u00f3n del hidr\u00f3geno en viviendas y sistemas de potencia h\u00edbridos para veh\u00edculos no tripulados. Desde 2015, en su laboratorio en la CEU UCH trabaja en <strong>tecnolog\u00edas de producci\u00f3n de hidr\u00f3geno verde<\/strong>. En 2021, obtuvo financiaci\u00f3n del programa de I+D+i de la Generalitat Valenciana para el desarrollo de un <a href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/la-ceu-uch-y-global-clean-energy-crearan-una-planta-piloto-de-produccion-de-hidrogeno-verde-a-escala-pyme\/\" target=\"_blank\" rel=\"noreferrer noopener\">proyecto de transferencia Universidad-Empresa<\/a> sobre infraestructuras de producci\u00f3n de hidr\u00f3geno para pymes.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u00bfQu\u00e9 es el hidr\u00f3geno verde? | ENERG\u00cdAS RENOVABLES | SOSTENIBILIDAD\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/JX72W1QiFic?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Hidr\u00f3geno verde, \u00bfla energ\u00eda del futuro?\u00a0 | ENERG\u00cdAS RENOVABLES | SOSTENIBILIDAD\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/0OqJvF2WArQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"El hidr\u00f3geno verde, \u00bfgenera residuos?\u00a0 | ENERG\u00cdAS RENOVABLES | SOSTENIBILIDAD\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/lu4EcN8Dsxc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Evidencia cient\u00edfica para un mejor servicio p\u00fablico<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Junto a Jordi Renau, de la CEU UCH, seis mujeres y cinco hombres del \u00e1mbito cient\u00edfico han sido <strong>elegidos para el programa<\/strong>: Esther Roca Campos y Josep Ribes Bertomeu, ambos de la Universitat de Val\u00e8ncia; Jos\u00e9 Ram\u00f3n Serrano Cruz, de la Universitat Polit\u00e8cnica de Val\u00e8ncia; Silvia Spairani Berrio, de la Universidad de Alicante; Sergio Chiva Vicente y Luis Cabedo Mas, ambos de la Universitat Jaume I de Castell\u00f3; Herminia Puerto Molina y Carolina Senabre Blanes, de la Universidad Miguel Hern\u00e1ndez de Elche; Esther Moreno Latorre, de la Universidad Cat\u00f3lica de Valencia; Oksana Udovyk, de INGENIO, centro mixto de la UPV y el CSIC; y Laureano Emilio Carpio Mulas, de la empresa ProtoQSAR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las <strong>disciplinas cient\u00edficas<\/strong> en las que estas doce personas trabajan cubren un amplio abanico que abarca las tem\u00e1ticas de Ingenier\u00eda nuclear y recursos h\u00eddricos y contaminaci\u00f3n ambiental; Hidr\u00f3geno verde; Bioinform\u00e1tica para la b\u00fasqueda de compuestos de menor da\u00f1o al medio ambiente; Educaci\u00f3n ambiental; Reconstrucci\u00f3n verde posguerra; Did\u00e1ctica en temas de sostenibilidad; Eficiencia del uso del agua y la energ\u00eda en cultivos; Modelado ambiental enfocado a la gesti\u00f3n hidr\u00e1ulica; Arquitectura y calificaci\u00f3n energ\u00e9tica; Reciclaje y reutilizaci\u00f3n de recursos del agua residual urbana y residuos org\u00e1nicos municipales; Pl\u00e1sticos sostenibles; Energ\u00eda fotovoltaica; y Gobernanza y participaci\u00f3n ciudadana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras las elecciones municipales de mayo, comenzar\u00e1 la b\u00fasqueda de la pareja pol\u00edtica que se asignar\u00e1 a cada una de estas doce personas investigadoras. Para ello, se tendr\u00e1n en cuenta perfiles pol\u00edticos que puedan poner en valor la evidencia cient\u00edfica para un mejor servicio p\u00fablico a la ciudadan\u00eda, y as\u00ed contribuir, desde su \u00e1mbito local, regional o auton\u00f3mico, a favorecer el <strong>intercambio de conocimiento entre el poder legislativo y la comunidad cient\u00edfica<\/strong>, as\u00ed como a mejorar el entendimiento mutuo entre ambos mundos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SOBRE CEEP, RUVID Y SMR<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/urldefense.com\/v3\/__https:\/cienciaenelparlamento.org\/__;!!D9dNQwwGXtA!WB6b-6w8LxwOqry82MgCWzZQEmColSZvDoDKLsa45nHBam2hw4iY8k1m-Eu_txo69pBuIIBAlzZ4N61_6kpAGV43Hw$\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Ciencia en el Parlamento<\/strong><\/a> es una asociaci\u00f3n sin \u00e1nimo de lucro que tiene como objetivo que la ciencia y el conocimiento cient\u00edfico sean una de las fuentes de informaci\u00f3n en la formulaci\u00f3n de propuestas pol\u00edticas. Ciencia en el Parlamento surgi\u00f3 en 2018 como una iniciativa popular con integrantes del mundo de la ciencia voluntarios que dedican parte de su tiempo libre a esta labor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La <a href=\"https:\/\/urldefense.com\/v3\/__https:\/ruvid.org\/__;!!D9dNQwwGXtA!WB6b-6w8LxwOqry82MgCWzZQEmColSZvDoDKLsa45nHBam2hw4iY8k1m-Eu_txo69pBuIIBAlzZ4N61_6kpf3Q-6jg$\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Red de Universidades Valencianas para el fomento de la Investigaci\u00f3n, el Desarrollo y la Innovaci\u00f3n (RUVID)<\/strong><\/a> nace en diciembre de 2001 a trav\u00e9s de un convenio de colaboraci\u00f3n entre las cinco universidades p\u00fablicas valencianas. Actualmente, est\u00e1 compuesta por los siguientes socios: Universitat de Val\u00e8ncia, Universitat Polit\u00e8cnica de Val\u00e8ncia, Universidad de Alicante, Universitat Jaume I de Castell\u00f3, Universidad Miguel Hern\u00e1ndez de Elche, Universidad CEU Cardenal Herrera, Universidad Cat\u00f3lica de Valencia y el Consejo Superior de Investigaciones Cient\u00edficas &#8211; Delegaci\u00f3n en la Comunitat Valenciana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa <em>Science meets Regions<\/em> del Joint Research Center tiene como objetivos adoptar un enfoque claro y estrat\u00e9gico sobre temas de relevancia para regiones y ciudades, en l\u00ednea con las prioridades de la Comisi\u00f3n Europea, y llenar el vac\u00edo existente a nivel local y regional en los instrumentos de la UE que abordan la formulaci\u00f3n de pol\u00edticas informadas en la evidencia. Los <a href=\"https:\/\/urldefense.com\/v3\/__https:\/joint-research-centre.ec.europa.eu\/science-meets-regions\/pairing-schemes_en__;!!D9dNQwwGXtA!WB6b-6w8LxwOqry82MgCWzZQEmColSZvDoDKLsa45nHBam2hw4iY8k1m-Eu_txo69pBuIIBAlzZ4N61_6kpuQAfPkw$\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>programas de emparejamiento seleccionados se pueden ver en este enlace<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una amplia trayectoria investigadora sobre producci\u00f3n y almacenamiento de hidr\u00f3geno verde, el profesor Jordi Renau forma parte de los doce candidatos seleccionados para este emparejamiento ciencia-pol\u00edtica en la CV, que forma parte del programa Science Meets Regions del Joint Research Center (JRC) de la Comisi\u00f3n Europea La asociaci\u00f3n de \u00e1mbito estatal Ciencia en el [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":157616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[3,12,14,18,31,20,32,39,17,28,1090],"tags":[145,173,250,258,331],"class_list":["post-157538","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad-cientifica","category-gente-ceu","category-ingenieria-y-arquitectura-actualidad-cientifica","category-medio-ambiente-actualidad-cientifica","category-nota-de-prensa-valencia","category-profesores-gente-ceu","category-x-profesores-home","category-x-slider-investigacion","category-xmaquetacion","category-xnota-de-prensa","category-destacada_home2","tag-dpto-ciencias-fisicas-matematicas-y-de-la-computacion","tag-eset","tag-grupo-tec-ener","tag-idit","tag-medio-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana<\/title>\n<meta name=\"description\" content=\"Con una amplia trayectoria investigadora sobre producci\u00f3n y almacenamiento de hidr\u00f3geno verde, el profesor Jordi Renau forma parte de los doce candidatos seleccionados para este emparejamiento ciencia-pol\u00edtica en la CV, que forma parte del programa Science Meets Regions del Joint Research Center (JRC) de la Comisi\u00f3n Europea\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana\" \/>\n<meta property=\"og:description\" content=\"Con una amplia trayectoria investigadora sobre producci\u00f3n y almacenamiento de hidr\u00f3geno verde, el profesor Jordi Renau forma parte de los doce candidatos seleccionados para este emparejamiento ciencia-pol\u00edtica en la CV, que forma parte del programa Science Meets Regions del Joint Research Center (JRC) de la Comisi\u00f3n Europea\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualidad CEU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UCHCEU\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-21T10:49:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-27T08:08:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1770\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elisa Marco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uchceu\" \/>\n<meta name=\"twitter:site\" content=\"@uchceu\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elisa Marco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\\\/\"},\"author\":{\"name\":\"Elisa Marco\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\"},\"headline\":\"Jordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana\",\"datePublished\":\"2023-03-21T10:49:23+00:00\",\"dateModified\":\"2023-03-27T08:08:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\\\/\"},\"wordCount\":1204,\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/jordi-renau-martinez-ceu-uch-scaled.jpg\",\"keywords\":[\"Dpto. Ciencias F\u00edsicas Matem\u00e1ticas y de la Computaci\u00f3n\",\"ESET\",\"Grupo TEC-ENER\",\"IDIT\",\"medio ambiente\"],\"articleSection\":[\"Actualidad Cient\u00edfica\",\"Gente CEU\",\"Ingenier\u00eda y Arquitectura\",\"Medio Ambiente\",\"nota de prensa valencia\",\"Profesores\",\"x profesores home\",\"x slider investigacion\",\"xMaquetaci\u00f3n\",\"xNota de Prensa\",\"xSegunda noticia en home\"],\"inLanguage\":\"es\"},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\\\/\",\"name\":\"Jordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/jordi-renau-martinez-ceu-uch-scaled.jpg\",\"datePublished\":\"2023-03-21T10:49:23+00:00\",\"dateModified\":\"2023-03-27T08:08:51+00:00\",\"description\":\"Con una amplia trayectoria investigadora sobre producci\u00f3n y almacenamiento de hidr\u00f3geno verde, el profesor Jordi Renau forma parte de los doce candidatos seleccionados para este emparejamiento ciencia-pol\u00edtica en la CV, que forma parte del programa Science Meets Regions del Joint Research Center (JRC) de la Comisi\u00f3n Europea\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/jordi-renau-martinez-ceu-uch-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/jordi-renau-martinez-ceu-uch-scaled.jpg\",\"width\":2560,\"height\":1770},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#website\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"name\":\"Actualidad CEU\",\"description\":\"El peri\u00f3dico de la Universidad CEU Cardenal Herrera\",\"publisher\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\"},\"alternateName\":\"AC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#organization\",\"name\":\"Universidad CEU Cardenal Herrera\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"contentUrl\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/logotipo-ceu-uch-gris.png\",\"width\":540,\"height\":140,\"caption\":\"Universidad CEU Cardenal Herrera\"},\"image\":{\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UCHCEU\",\"https:\\\/\\\/x.com\\\/uchceu\",\"https:\\\/\\\/www.instagram.com\\\/uchceu_universidad\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/497316\",\"https:\\\/\\\/www.youtube.com\\\/ceuvalencia\",\"https:\\\/\\\/www.tiktok.com\\\/@uchceu_universidad\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/#\\\/schema\\\/person\\\/31ddba919ce9f30ec285d011f857b334\",\"name\":\"Elisa Marco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g\",\"caption\":\"Elisa Marco\"},\"url\":\"https:\\\/\\\/medios.uchceu.es\\\/actualidad-ceu\\\/author\\\/elisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana","description":"Con una amplia trayectoria investigadora sobre producci\u00f3n y almacenamiento de hidr\u00f3geno verde, el profesor Jordi Renau forma parte de los doce candidatos seleccionados para este emparejamiento ciencia-pol\u00edtica en la CV, que forma parte del programa Science Meets Regions del Joint Research Center (JRC) de la Comisi\u00f3n Europea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/","og_locale":"es_ES","og_type":"article","og_title":"Jordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana","og_description":"Con una amplia trayectoria investigadora sobre producci\u00f3n y almacenamiento de hidr\u00f3geno verde, el profesor Jordi Renau forma parte de los doce candidatos seleccionados para este emparejamiento ciencia-pol\u00edtica en la CV, que forma parte del programa Science Meets Regions del Joint Research Center (JRC) de la Comisi\u00f3n Europea","og_url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/","og_site_name":"Actualidad CEU","article_publisher":"https:\/\/www.facebook.com\/UCHCEU","article_published_time":"2023-03-21T10:49:23+00:00","article_modified_time":"2023-03-27T08:08:51+00:00","og_image":[{"width":2560,"height":1770,"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-scaled.jpg","type":"image\/jpeg"}],"author":"Elisa Marco","twitter_card":"summary_large_image","twitter_creator":"@uchceu","twitter_site":"@uchceu","twitter_misc":{"Escrito por":"Elisa Marco","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/#article","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/"},"author":{"name":"Elisa Marco","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334"},"headline":"Jordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana","datePublished":"2023-03-21T10:49:23+00:00","dateModified":"2023-03-27T08:08:51+00:00","mainEntityOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/"},"wordCount":1204,"publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-scaled.jpg","keywords":["Dpto. Ciencias F\u00edsicas Matem\u00e1ticas y de la Computaci\u00f3n","ESET","Grupo TEC-ENER","IDIT","medio ambiente"],"articleSection":["Actualidad Cient\u00edfica","Gente CEU","Ingenier\u00eda y Arquitectura","Medio Ambiente","nota de prensa valencia","Profesores","x profesores home","x slider investigacion","xMaquetaci\u00f3n","xNota de Prensa","xSegunda noticia en home"],"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/","name":"Jordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana","isPartOf":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/#primaryimage"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/#primaryimage"},"thumbnailUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-scaled.jpg","datePublished":"2023-03-21T10:49:23+00:00","dateModified":"2023-03-27T08:08:51+00:00","description":"Con una amplia trayectoria investigadora sobre producci\u00f3n y almacenamiento de hidr\u00f3geno verde, el profesor Jordi Renau forma parte de los doce candidatos seleccionados para este emparejamiento ciencia-pol\u00edtica en la CV, que forma parte del programa Science Meets Regions del Joint Research Center (JRC) de la Comisi\u00f3n Europea","breadcrumb":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/#primaryimage","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-scaled.jpg","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-scaled.jpg","width":2560,"height":1770},{"@type":"BreadcrumbList","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/jordi-renau-elegido-para-el-programa-ciencia-en-el-parlamento-en-la-comunidad-valenciana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/medios.uchceu.es\/actualidad-ceu\/"},{"@type":"ListItem","position":2,"name":"Jordi Renau, elegido para el programa \u201cCiencia en el Parlamento\u201d en la Comunidad Valenciana"}]},{"@type":"WebSite","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#website","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","name":"Actualidad CEU","description":"El peri\u00f3dico de la Universidad CEU Cardenal Herrera","publisher":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization"},"alternateName":"AC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medios.uchceu.es\/actualidad-ceu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#organization","name":"Universidad CEU Cardenal Herrera","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/","url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","contentUrl":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2018\/11\/logotipo-ceu-uch-gris.png","width":540,"height":140,"caption":"Universidad CEU Cardenal Herrera"},"image":{"@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UCHCEU","https:\/\/x.com\/uchceu","https:\/\/www.instagram.com\/uchceu_universidad","https:\/\/www.linkedin.com\/school\/497316","https:\/\/www.youtube.com\/ceuvalencia","https:\/\/www.tiktok.com\/@uchceu_universidad"]},{"@type":"Person","@id":"https:\/\/medios.uchceu.es\/actualidad-ceu\/#\/schema\/person\/31ddba919ce9f30ec285d011f857b334","name":"Elisa Marco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed64f0e17f4cceecb56f2f81d2a17bcf0f0e787a2c7abf00b5aeea711849fd16?s=96&d=mm&r=g","caption":"Elisa Marco"},"url":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-scaled.jpg",2560,1770,false],"thumbnail":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-150x150.jpg",150,150,true],"medium":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-300x207.jpg",300,207,true],"medium_large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-768x531.jpg",696,481,true],"large":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-1060x733.jpg",696,481,true],"listado":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-310x174.jpg",310,174,true],"nuevaweb":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-280x280.jpg",280,280,true],"destacadablogs":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-580x280.jpg",580,280,true],"1536x1536":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-1536x1062.jpg",1536,1062,true],"2048x2048":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-2048x1416.jpg",2048,1416,true],"td_150x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-150x104.jpg",150,104,true],"td_218x150":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-218x150.jpg",218,150,true],"td_300x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-300x207.jpg",300,207,true],"td_324x400":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-324x400.jpg",324,400,true],"td_485x360":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-485x360.jpg",485,360,true],"td_696x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-696x481.jpg",696,481,true],"td_1068x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-1068x738.jpg",1068,738,true],"td_1920x0":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-1920x1327.jpg",1920,1327,true],"td_0x420":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-608x420.jpg",608,420,true],"td_80x60":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-80x60.jpg",80,60,true],"td_100x70":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-100x70.jpg",100,70,true],"td_265x198":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-265x198.jpg",265,198,true],"td_324x160":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-324x160.jpg",324,160,true],"td_324x235":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-324x235.jpg",324,235,true],"td_356x220":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-356x220.jpg",356,220,true],"td_356x364":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-356x364.jpg",356,364,true],"td_533x261":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-533x261.jpg",533,261,true],"td_534x462":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-534x462.jpg",534,462,true],"td_696x385":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-696x385.jpg",696,385,true],"td_741x486":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-741x486.jpg",741,486,true],"td_1068x580":["https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-content\/uploads\/sites\/2\/2023\/03\/jordi-renau-martinez-ceu-uch-1068x580.jpg",1068,580,true]},"uagb_author_info":{"display_name":"Elisa Marco","author_link":"https:\/\/medios.uchceu.es\/actualidad-ceu\/author\/elisa\/"},"uagb_comment_info":0,"uagb_excerpt":"Con una amplia trayectoria investigadora sobre producci\u00f3n y almacenamiento de hidr\u00f3geno verde, el profesor Jordi Renau forma parte de los doce candidatos seleccionados para este emparejamiento ciencia-pol\u00edtica en la CV, que forma parte del programa Science Meets Regions del Joint Research Center (JRC) de la Comisi\u00f3n Europea La asociaci\u00f3n de \u00e1mbito estatal Ciencia en el&hellip;","_links":{"self":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/157538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/comments?post=157538"}],"version-history":[{"count":1,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/157538\/revisions"}],"predecessor-version":[{"id":157542,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/posts\/157538\/revisions\/157542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media\/157616"}],"wp:attachment":[{"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/media?parent=157538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/categories?post=157538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medios.uchceu.es\/actualidad-ceu\/wp-json\/wp\/v2\/tags?post=157538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}